{"id":34541,"date":"2020-07-27T10:26:04","date_gmt":"2020-07-27T08:26:04","guid":{"rendered":"https:\/\/explore-agadirsoussmassa.com\/oasis-daguinane-2\/"},"modified":"2020-10-19T14:30:41","modified_gmt":"2020-10-19T12:30:41","slug":"%d9%88%d8%a7%d8%ad%d8%a9-%d8%a7%d8%ac%d9%88%d9%8a%d9%86%d8%a7%d9%86%d8%a7","status":"publish","type":"post","link":"https:\/\/explore-agadirsoussmassa.com\/ar\/%d9%88%d8%a7%d8%ad%d8%a9-%d8%a7%d8%ac%d9%88%d9%8a%d9%86%d8%a7%d9%86%d8%a7\/","title":{"rendered":"\u0648\u0627\u062d\u0629 \u0623\u0643\u064a\u0646\u0627\u0646"},"content":{"rendered":"<div id=\"pl-gb34541-6a574ac85279f\"  class=\"panel-layout panel-is-rtl\" ><div id=\"pg-gb34541-6a574ac85279f-0\"  class=\"panel-grid panel-no-style\" ><div id=\"pgc-gb34541-6a574ac85279f-0-0\"  class=\"panel-grid-cell\" ><div id=\"panel-gb34541-6a574ac85279f-0-0-0\" class=\"so-panel widget widget_text panel-first-child panel-last-child\" data-index=\"0\" ><div id=\"sdrstyle\" class=\"panel-widget-style panel-widget-style-for-gb34541-6a574ac85279f-0-0-0\" >\t\t\t<div class=\"textwidget\"><h3 id=\"%d8%a3%d9%83%d9%8a%d9%86%d8%a7%d9%86%d8%8c-%d8%a7%d9%84%d9%88%d8%a7%d8%ad%d8%a9-%d8%a7%d9%84%d8%ae%d9%81%d9%8a%d8%a9\" style=\";text-align: right; direction: rtl;\">\u0623\u0643\u064a\u0646\u0627\u0646\u060c \u0627\u0644\u0648\u0627\u062d\u0629 \u0627\u0644\u062e\u0641\u064a\u0629<\/h3>\n<p><em>\u0627\u0644\u0631\u062d\u0644\u0629 \u0645\u0646 \u0623\u0643\u0627\u062f\u064a\u0631: 5:30<\/em><\/p>\n<\/div>\n\t\t<\/div><\/div><\/div><\/div><div id=\"pg-gb34541-6a574ac85279f-1\"  class=\"panel-grid panel-no-style\" ><div id=\"pgc-gb34541-6a574ac85279f-1-0\"  class=\"panel-grid-cell\" ><div id=\"panel-gb34541-6a574ac85279f-1-0-0\" class=\"so-panel widget widget_text panel-first-child panel-last-child\" data-index=\"1\" ><div id=\"sdrstyle\" class=\"panel-widget-style panel-widget-style-for-gb34541-6a574ac85279f-1-0-0\" >\t\t\t<div class=\"textwidget\"><p><strong>\u0648\u0627\u062d\u0629 \u0623\u0643\u064a\u0646\u0627\u0646\u060c \u0630\u0643\u0631\u064a\u0627\u062a \u0644\u0627 \u062a\u0646\u0633\u0649<\/strong><\/p>\n<p>\u0633\u064a\u0643\u0648\u0646 \u0627\u0644\u062a\u0648\u0642\u0641 \u0641\u064a \u0648\u0627\u062d\u0629 \u0623\u0643\u064a\u0646\u0627\u0646 \u0645\u0631\u062d\u0644\u0629 \u0645\u0647\u0645\u0629 \u0641\u064a \u0631\u062d\u0644\u062a\u0643\u0645 \u0635\u0648\u0628 \u0627\u0644\u0635\u062d\u0631\u0627\u0621 (<u>\u0627\u0644\u0645\u0646\u062a\u0632\u0647 \u0627\u0644\u0648\u0637\u0646\u064a \u0625\u064a\u0631\u064a\u0643\u064a<\/u> \u0639\u0644\u0649 \u0633\u0628\u064a\u0644 \u0627\u0644\u0645\u062b\u0627\u0644). \u0641\u064a \u0623\u0643\u064a\u0646\u0627\u0646\u060c \u0646\u0648\u0635\u064a \u0628\u0627\u0644\u062a\u062c\u0648\u0644 \u0633\u064a\u0631\u064b\u0627 \u0639\u0644\u0649 \u0627\u0644\u0623\u0642\u062f\u0627\u0645 \u0641\u064a \u0627\u0644\u0648\u0627\u062d\u0629 \u0645\u0646 \u062e\u0644\u0627\u0644 \u0627\u062a\u0628\u0627\u0639 \u0627\u0644\u0633\u0627\u0642\u064a\u0627\u062a \u0648\u0627\u0644\u0639\u0648\u062f\u0629 \u0628\u062c\u0627\u0646\u0628 \u0627\u0644\u0648\u0627\u062f\u064a.<\/p>\n<p>\u0644\u0627 \u062a\u062a\u0631\u062f\u062f\u0648\u0627 \u0641\u064a \u0627\u0644\u0633\u0624\u0627\u0644 \u0639\u0646 \u0627\u0644\u0633\u062f\u0648\u062f \u0627\u0644\u0645\u0627\u0626\u064a\u0629 \u0648\u0627\u0644\u0633\u0627\u0639\u0629 \u0648\u0646\u0638\u0627\u0645 \u062a\u0648\u0632\u064a\u0639 \u0627\u0644\u0645\u064a\u0627\u0647. \u0648\u062a\u0639\u062a\u0628\u0631 \u0648\u0627\u062d\u0629 \u0623\u0643\u064a\u0646\u0627\u0646 \u0645\u062d\u0637\u0629 \u062a\u0648\u0642\u0641 \u0631\u0627\u0626\u0639\u0629 \u0644\u0623\u0646 \u0627\u0644\u0642\u0631\u064a\u0629 \u0647\u064a \u0645\u0644\u0627\u0630 \u0644\u0644\u0647\u062f\u0648\u0621 \u0648\u0641\u064a\u0647\u0627 \u0645\u0646\u0627\u0638\u0631 \u0637\u0628\u064a\u0639\u064a\u0629 \u062e\u0644\u0627\u0628\u0629. \u0647\u0630\u0627 \u0648\u062a\u0648\u062c\u062f \u0645\u0633\u0627\u0631\u0627\u062a \u0639\u0644\u0649 \u062c\u0627\u0646\u0628\u064a \u0627\u0644\u0645\u0636\u0627\u064a\u0642 \u0625\u0630\u0627 \u0643\u0646\u062a\u0645 \u0645\u0646 \u0639\u0634\u0627\u0642 \u0627\u0644\u062a\u0646\u0632\u0647 \u0641\u064a \u0627\u0644\u0645\u0631\u062a\u0641\u0639\u0627\u062a (\u0635\u0648\u0631 \u0644\u0627 \u062a\u064f\u0646\u0633\u0649).<\/p>\n<\/div>\n\t\t<\/div><\/div><\/div><\/div><\/div>\n\n<div class=\"cnvs-block-justified-gallery cnvs-block-justified-gallery-1595842003172\" >\n<div\n\tclass='gallery cnvs-gallery-type-justified'\n\tdata-jg-margins=\"10\"\n\tdata-jg-border=\"-10\"\n\tdata-jg-row-height=\"258\"\n\tdata-jg-max-row-height=\"220%\"\n\tdata-jg-last-row=\"justify\"\n\tdata-jg-captions=\"true\"\n\tdata-jg-randomize=\"false\"\n>\n\t\t\t<figure class=\"gallery-item\">\n\t\t\t\t\t\t\t<a href=\"https:\/\/explore-agadirsoussmassa.com\/wp-content\/uploads\/2020\/05\/aguinane-1.png\">\n\t\t\t\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1160\" height=\"742\" src=\"https:\/\/explore-agadirsoussmassa.com\/wp-content\/uploads\/2020\/05\/aguinane-1-1160x742.png\" class=\"attachment-csco-1160 size-csco-1160\" alt=\"Oasis d&#039;Aguinane\" srcset=\"https:\/\/explore-agadirsoussmassa.com\/wp-content\/uploads\/2020\/05\/aguinane-1-1160x742.png 1160w, https:\/\/explore-agadirsoussmassa.com\/wp-content\/uploads\/2020\/05\/aguinane-1-800x512.png 800w, https:\/\/explore-agadirsoussmassa.com\/wp-content\/uploads\/2020\/05\/aguinane-1-320x205.png 320w, https:\/\/explore-agadirsoussmassa.com\/wp-content\/uploads\/2020\/05\/aguinane-1-560x358.png 560w, https:\/\/explore-agadirsoussmassa.com\/wp-content\/uploads\/2020\/05\/aguinane-1.png 1360w\" sizes=\"auto, (max-width: 1160px) 100vw, 1160px\" \/>\n\t\t\t\t\t\t\t<\/a>\n\t\t\t\n\t\t\t<div class=\"caption wp-caption-text gallery-caption\">\u0648\u0627\u062d\u0629 \u0623\u0643\u064a\u0646\u0627\u0646<\/div>\t\t<\/figure>\n\t\t\t\t<figure class=\"gallery-item\">\n\t\t\t\t\t\t\t<a href=\"https:\/\/explore-agadirsoussmassa.com\/wp-content\/uploads\/2020\/05\/aguinane-2.png\">\n\t\t\t\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1160\" height=\"870\" src=\"https:\/\/explore-agadirsoussmassa.com\/wp-content\/uploads\/2020\/05\/aguinane-2-1160x870.png\" class=\"attachment-csco-1160 size-csco-1160\" alt=\"Oasis d&#039;Aguinane\" srcset=\"https:\/\/explore-agadirsoussmassa.com\/wp-content\/uploads\/2020\/05\/aguinane-2-1160x870.png 1160w, https:\/\/explore-agadirsoussmassa.com\/wp-content\/uploads\/2020\/05\/aguinane-2-800x600.png 800w, https:\/\/explore-agadirsoussmassa.com\/wp-content\/uploads\/2020\/05\/aguinane-2-320x240.png 320w, https:\/\/explore-agadirsoussmassa.com\/wp-content\/uploads\/2020\/05\/aguinane-2-300x225.png 300w, https:\/\/explore-agadirsoussmassa.com\/wp-content\/uploads\/2020\/05\/aguinane-2-560x420.png 560w, https:\/\/explore-agadirsoussmassa.com\/wp-content\/uploads\/2020\/05\/aguinane-2.png 1200w\" sizes=\"auto, (max-width: 1160px) 100vw, 1160px\" \/>\n\t\t\t\t\t\t\t<\/a>\n\t\t\t\n\t\t\t<div class=\"caption wp-caption-text gallery-caption\">\u0648\u0627\u062d\u0629 \u0623\u0643\u064a\u0646\u0627\u0646<\/div>\t\t<\/figure>\n\t\t\t\t<figure class=\"gallery-item\">\n\t\t\t\t\t\t\t<a href=\"https:\/\/explore-agadirsoussmassa.com\/wp-content\/uploads\/2020\/02\/Large_aguinane-4.jpg\">\n\t\t\t\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"698\" height=\"425\" src=\"https:\/\/explore-agadirsoussmassa.com\/wp-content\/uploads\/2020\/02\/Large_aguinane-4.jpg\" class=\"attachment-csco-1160 size-csco-1160\" alt=\"Oasis d&#039;Aguinane\" srcset=\"https:\/\/explore-agadirsoussmassa.com\/wp-content\/uploads\/2020\/02\/Large_aguinane-4.jpg 698w, https:\/\/explore-agadirsoussmassa.com\/wp-content\/uploads\/2020\/02\/Large_aguinane-4-320x195.jpg 320w, https:\/\/explore-agadirsoussmassa.com\/wp-content\/uploads\/2020\/02\/Large_aguinane-4-560x341.jpg 560w\" sizes=\"auto, (max-width: 698px) 100vw, 698px\" \/>\n\t\t\t\t\t\t\t<\/a>\n\t\t\t\n\t\t\t<div class=\"caption wp-caption-text gallery-caption\">\u0648\u0627\u062d\u0629 \u0623\u0643\u064a\u0646\u0627\u0646<\/div>\t\t<\/figure>\n\t\t\t\t<figure class=\"gallery-item\">\n\t\t\t\t\t\t\t<a href=\"https:\/\/explore-agadirsoussmassa.com\/wp-content\/uploads\/2020\/05\/aguinane-4.png\">\n\t\t\t\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1160\" height=\"870\" src=\"https:\/\/explore-agadirsoussmassa.com\/wp-content\/uploads\/2020\/05\/aguinane-4-1160x870.png\" class=\"attachment-csco-1160 size-csco-1160\" alt=\"Oasis d&#039;Aguinane\" srcset=\"https:\/\/explore-agadirsoussmassa.com\/wp-content\/uploads\/2020\/05\/aguinane-4-1160x870.png 1160w, https:\/\/explore-agadirsoussmassa.com\/wp-content\/uploads\/2020\/05\/aguinane-4-800x600.png 800w, https:\/\/explore-agadirsoussmassa.com\/wp-content\/uploads\/2020\/05\/aguinane-4-320x240.png 320w, https:\/\/explore-agadirsoussmassa.com\/wp-content\/uploads\/2020\/05\/aguinane-4-300x225.png 300w, https:\/\/explore-agadirsoussmassa.com\/wp-content\/uploads\/2020\/05\/aguinane-4-560x420.png 560w, https:\/\/explore-agadirsoussmassa.com\/wp-content\/uploads\/2020\/05\/aguinane-4.png 1360w\" sizes=\"auto, (max-width: 1160px) 100vw, 1160px\" \/>\n\t\t\t\t\t\t\t<\/a>\n\t\t\t\n\t\t\t<div class=\"caption wp-caption-text gallery-caption\">\u0648\u0627\u062d\u0629 \u0623\u0643\u064a\u0646\u0627\u0646<\/div>\t\t<\/figure>\n\t\t<\/div>\n\n<\/div>\n\n<div id=\"pl-gb34541-6a574ac8551d8\"  class=\"panel-layout panel-is-rtl\" ><div id=\"pg-gb34541-6a574ac8551d8-0\"  class=\"panel-grid panel-no-style\" ><div id=\"pgc-gb34541-6a574ac8551d8-0-0\"  class=\"panel-grid-cell\" ><div id=\"panel-gb34541-6a574ac8551d8-0-0-0\" class=\"so-panel widget widget_text panel-first-child panel-last-child\" data-index=\"0\" >\t\t\t<div class=\"textwidget\"><p><em>\u0643\u064a\u0641\u064a\u0629 \u0627\u0644\u0648\u0635\u0648\u0644:<\/em><\/p>\n<p>\u0627\u0644\u062e\u064a\u0627\u0631 1 &#8211; \u00a0\u0627\u0646\u0637\u0644\u0627\u0642\u0627 \u0645\u0646 \u0623\u0643\u0627\u062f\u064a\u0631\u060c \u062a\u0648\u062c\u0647\u0648\u0627 \u0635\u0648\u0628 \u062a\u0627\u0631\u0648\u062f\u0627\u0646\u062a &#8211; \u062a\u0627\u0644\u0648\u064a\u0646 (\u0639\u0627\u0635\u0645\u0629 \u0627\u0644\u0632\u0639\u0641\u0631\u0627\u0646) \u0639\u0628\u0631 \u0627\u0644\u0637\u0631\u064a\u0642 \u0627\u0644\u0648\u0637\u0646\u064a\u0629 \u0631\u0642\u0645 10. \u0639\u0646\u062f\u0645\u0627 \u062a\u062a\u062c\u0627\u0648\u0632\u0648\u0646 \u062a\u0627\u0644\u0648\u064a\u0646\u060c \u0627\u0646\u0639\u0637\u0641\u0648\u0627 \u064a\u0645\u064a\u0646\u064b\u0627 \u0639\u0646\u062f \u0627\u0644\u0646\u0642\u0637\u0629: 30.471271\u060c 7.842794-\u060c \u0648\u0627\u0633\u062a\u0645\u0631\u0648\u0627 \u0639\u0628\u0631 \u0627\u0644\u0637\u0631\u064a\u0642 \u0627\u0644\u0625\u0642\u0644\u064a\u0645\u064a\u0629 1743 \u0625\u0644\u0649 \u0648\u0627\u062d\u0629 \u0623\u0642\u0627 \u0625\u064a\u063a\u0627\u0646 (29.994823\u060c 7.529454-). \u0641\u064a \u0623\u0642\u0627 \u0625\u064a\u063a\u0627\u0646\u060c \u0627\u062a\u062c\u0647\u0648\u0627 \u0634\u0645\u0627\u0644\u064b\u0627 \u0625\u0644\u0649 \u0648\u0627\u062d\u0629 \u0623\u0643\u064a\u0646\u0627\u0646 \u062d\u064a\u062b \u064a\u0645\u0643\u0646\u0643\u0645 \u0642\u0636\u0627\u0621 \u0627\u0644\u0644\u064a\u0644 (30.206741\u060c 7.561984-). \u0644\u0627 \u062a\u0641\u0648\u062a\u0648\u0627 \u0641\u0631\u0635\u0629 \u0632\u064a\u0627\u0631\u0629 \u0642\u0631\u064a\u0629 <a href=\"\/grenier-collectif-adkhs\/\">\u0623\u062f\u062e\u0633<\/a> \u0627\u0644\u0645\u062d\u0635\u0646\u0629 (30.124472\u060c 7.464598-). \u064a\u0645\u0631 \u0637\u0631\u064a\u0642 \u0627\u0644\u0648\u0635\u0648\u0644 \u0625\u0644\u0649 \u0648\u0627\u062d\u0629 \u0623\u0643\u064a\u0646\u0627\u0646 \u0639\u0628\u0631 \u0645\u0636\u0627\u064a\u0642 \u0631\u0627\u0626\u0639\u0629.<\/p>\n<p>\u0627\u0644\u062e\u064a\u0627\u0631 2 (4&#215;4) &#8211; \u0648\u0627\u0644\u0630\u064a \u0633\u064a\u0633\u0645\u062d \u0644\u0643\u0645 \u0628\u0627\u0644\u0648\u0635\u0648\u0644 \u0625\u0644\u0649 \u0623\u0643\u064a\u0646\u0627\u0646 \u0645\u0646 \u0623\u0639\u0644\u0649 \u0627\u0644\u0648\u0627\u062f\u064a \u0645\u0639 \u0625\u0637\u0644\u0627\u0644\u0629 \u0627\u0633\u062a\u062b\u0646\u0627\u0626\u064a\u0629 \u0639\u0644\u0649 \u0627\u0644\u0648\u0627\u062d\u0629.<\/p>\n<p>\u0639\u0646\u062f \u0627\u0644\u0627\u0646\u0637\u0644\u0627\u0642 \u0645\u0646 \u0623\u0643\u0627\u062f\u064a\u0631\u060c \u062a\u0648\u062c\u0647\u0648\u0627 \u0635\u0648\u0628 \u062a\u0627\u0631\u0648\u062f\u0627\u0646\u062a &#8211; \u062a\u0627\u0644\u0648\u064a\u0646 (\u0639\u0627\u0635\u0645\u0629 \u0627\u0644\u0632\u0639\u0641\u0631\u0627\u0646) \u0639\u0628\u0631 \u0627\u0644\u0637\u0631\u064a\u0642 \u0627\u0644\u0648\u0637\u0646\u064a\u0629 \u0631\u0642\u0645 10. \u0639\u0646\u062f\u0645\u0627 \u062a\u062a\u062c\u0627\u0648\u0632\u0648\u0646 \u062a\u0627\u0644\u0648\u064a\u0646\u060c \u0627\u0646\u0639\u0637\u0641\u0648\u0627 \u064a\u0645\u064a\u0646\u064b\u0627 \u0639\u0646\u062f \u0627\u0644\u0646\u0642\u0637\u0629: 30.471271\u060c 7.842794- \u0648\u062a\u0627\u0628\u0639\u0648\u0627 \u0639\u0628\u0631 \u0627\u0644\u0637\u0631\u064a\u0642 \u0627\u0644\u0625\u0642\u0644\u064a\u0645\u064a\u0629 1743 \u0644\u0645\u0633\u0627\u0641\u0629 16 \u0643\u0644\u0645. \u0628\u0639\u062f \u0630\u0644\u0643\u060c \u0627\u0633\u0644\u0643\u0648\u0627 \u0627\u0644\u0645\u0633\u0627\u0631 \u0627\u0644\u0648\u0627\u0642\u0639 \u0639\u0644\u0649 \u0627\u0644\u064a\u0633\u0627\u0631 \u0639\u0646\u062f \u0627\u0644\u0646\u0642\u0637\u0629 (30.366284\u060c 7.760416-)\u060c \u0633\u062a\u0639\u0628\u0631\u0648\u0646 \u0628\u062f\u0627\u064a\u0629 \u0647\u0636\u0628\u0629 \u0644\u062d\u0648\u0627\u0644\u064a \u0639\u0634\u0631\u064a\u0646 \u0643\u064a\u0644\u0648\u0645\u062a\u0631\u064b\u0627 (\u0633\u0627\u0639\u0629 \u0648\u0627\u062d\u062f\u0629 \u062a\u0642\u0631\u064a\u0628\u0627). \u0639\u0644\u0649 \u0628\u0639\u062f 5 \u0643\u0644\u0645 \u0645\u0646 \u062a\u064a\u0645\u062f\u063a\u0627\u0631\u062a (30.272226\u060c 7.602485-)\u060c \u0633\u062a\u0645\u0631\u0648\u0646 \u0645\u0646 \u0627\u0644\u0642\u0645\u0629 \u0648\u062a\u0646\u0632\u0644\u0648\u0646 \u0646\u062d\u0648 \u0627\u0644\u0642\u0631\u064a\u0629. \u064a\u062a\u0628\u0642\u0649 \u0623\u0645\u0627\u0645\u0643\u0645 10 \u0643\u064a\u0644\u0648\u0645\u062a\u0631\u0627\u062a (30 \u062f\u0642\u064a\u0642\u0629) \u0639\u0644\u0649 \u0627\u0644\u0647\u0636\u0628\u0629 \u062d\u062a\u0649 \u0627\u0644\u0648\u0635\u0648\u0644 \u0625\u0644\u0649 \u0642\u0645\u0629 \u0642\u0631\u0628 \u0642\u0631\u064a\u0629 \u0623\u0633\u0631\u0627\u0631\u063a. \u0648\u064a\u0644\u0632\u0645\u0643\u0645 \u0628\u0639\u062f \u0630\u0644\u0643 \u0645\u0648\u0627\u0635\u0644\u0629 \u0627\u0644\u0631\u062d\u0644\u0629 \u0637\u0648\u0627\u0644 \u0643\u064a\u0644\u0648\u0645\u062a\u0631\u064a\u0646 \u062d\u062a\u0649 \u0623\u0643\u064a\u0646\u0627\u0646.<\/p>\n<p>\u0645\u0644\u0627\u062d\u0638\u0629 \u0645\u0647\u0645\u0629 &#8211; \u0645\u0633\u0627\u0631 \u0627\u0644\u0631\u062d\u0644\u0629: \u0633\u062a\u0645\u0631\u0648\u0646 \u0641\u064a \u0627\u0644\u062e\u064a\u0627\u0631\u064a\u0646 \u0645\u0639\u0627 \u0628\u0627\u0644\u0642\u0631\u0628 \u0645\u0646 <a href=\"\/grenier-collectif-ifri-imadidane\/\">\u0645\u062e\u0627\u0632\u0646 \u0625\u064a\u0641\u0631\u064a<\/a> (30.444483\u060c 7.839283-)\u060c \u0648\u062a\u0639\u062f \u0632\u064a\u0627\u0631\u062a\u0647\u0627 \u0623\u0645\u0631\u0627 \u0636\u0631\u0648\u0631\u064a\u0627!<\/p>\n<p><em>\u0623\u0646\u0634\u0637\u0629<\/em><em>:<\/em><\/p>\n<ul>\n<li>\u0627\u0644\u062a\u062c\u0648\u0644 \u0645\u0634\u064a\u0627 \u0639\u0644\u0649 \u0627\u0644\u0623\u0642\u062f\u0627\u0645<\/li>\n<li>\u0632\u064a\u0627\u0631\u0629 \u0627\u0644\u0648\u0627\u062d\u0629<\/li>\n<li>\u0627\u0644\u0633\u0627\u0639\u0629 \u0627\u0644\u0645\u0627\u0626\u064a\u0629<\/li>\n<li>\u0632\u064a\u0627\u0631\u0629 \u0645\u062e\u0627\u0632\u0646 \u0623\u062f\u062e\u0633<\/li>\n<\/ul>\n<\/div>\n\t\t<\/div><\/div><\/div><\/div>","protected":false},"excerpt":{"rendered":"<div class=\"post-excerpt\">\u0633\u062a\u0643\u0648\u0646 \u0632\u064a\u0627\u0631\u0629 \u0648\u0627\u062d\u0629 \u0623\u0643\u064a\u0646\u0627\u0646 \u0648\u0645\u062e\u0627\u0632\u0646 \u0623\u062f\u062e\u0633 \u0623\u0628\u0631\u0632 \u0645\u062d\u0637\u0627\u062a \u0631\u062d\u0644\u062a\u0643\u0645 \u0642\u0628\u0644 \u0627\u0644\u062a\u0648\u062c\u0647 \u0635\u0648\u0628 \u0627\u0644\u0635\u062d\u0631\u0627\u0621 (\u0627\u0644\u0645\u0646\u062a\u0632\u0647 \u0627\u0644\u0648\u0637\u0646\u064a \u0625\u064a\u0631\u064a\u0643\u064a)<\/div>\n<div class=\"post-more\"><a href=\"https:\/\/explore-agadirsoussmassa.com\/ar\/%d9%88%d8%a7%d8%ad%d8%a9-%d8%a7%d8%ac%d9%88%d9%8a%d9%86%d8%a7%d9%86%d8%a7\/\" class=\"button button-primary button-effect\"><span>\u0627\u0646\u0638\u0631 \u0627\u0644\u062a\u0641\u0627\u0635\u064a\u0644<\/span><span><i class=\"cs-icon cs-icon-arrow-right\"><\/i><\/span><\/a><\/div>\n","protected":false},"author":1,"featured_media":6903,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[124,402],"tags":[],"powerkit_post_featured":[],"class_list":{"0":"post-34541","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-124","8":"category-402"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.0 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>\u0648\u0627\u062d\u0629 \u0623\u0643\u064a\u0646\u0627\u0646 - Explore Agadir Souss Massa<\/title>\n<meta name=\"description\" content=\"\u0633\u062a\u0643\u0648\u0646 \u0632\u064a\u0627\u0631\u0629 \u0648\u0627\u062d\u0629 \u0623\u0643\u064a\u0646\u0627\u0646 \u0648\u0645\u062e\u0627\u0632\u0646 \u0623\u062f\u062e\u0633 \u0623\u0628\u0631\u0632 \u0645\u062d\u0637\u0627\u062a \u0631\u062d\u0644\u062a\u0643\u0645 \u0642\u0628\u0644 \u0627\u0644\u062a\u0648\u062c\u0647 \u0635\u0648\u0628 \u0627\u0644\u0635\u062d\u0631\u0627\u0621 (\u0627\u0644\u0645\u0646\u062a\u0632\u0647 \u0627\u0644\u0648\u0637\u0646\u064a \u0625\u064a\u0631\u064a\u0643\u064a)\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/explore-agadirsoussmassa.com\/ar\/%d9%88%d8%a7%d8%ad%d8%a9-%d8%a7%d8%ac%d9%88%d9%8a%d9%86%d8%a7%d9%86%d8%a7\/\" \/>\n<meta property=\"og:locale\" content=\"ar_AR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u0648\u0627\u062d\u0629 \u0623\u0643\u064a\u0646\u0627\u0646 - Explore Agadir Souss Massa\" \/>\n<meta property=\"og:description\" content=\"\u0633\u062a\u0643\u0648\u0646 \u0632\u064a\u0627\u0631\u0629 \u0648\u0627\u062d\u0629 \u0623\u0643\u064a\u0646\u0627\u0646 \u0648\u0645\u062e\u0627\u0632\u0646 \u0623\u062f\u062e\u0633 \u0623\u0628\u0631\u0632 \u0645\u062d\u0637\u0627\u062a \u0631\u062d\u0644\u062a\u0643\u0645 \u0642\u0628\u0644 \u0627\u0644\u062a\u0648\u062c\u0647 \u0635\u0648\u0628 \u0627\u0644\u0635\u062d\u0631\u0627\u0621 (\u0627\u0644\u0645\u0646\u062a\u0632\u0647 \u0627\u0644\u0648\u0637\u0646\u064a \u0625\u064a\u0631\u064a\u0643\u064a)\" \/>\n<meta property=\"og:url\" content=\"https:\/\/explore-agadirsoussmassa.com\/ar\/%d9%88%d8%a7%d8%ad%d8%a9-%d8%a7%d8%ac%d9%88%d9%8a%d9%86%d8%a7%d9%86%d8%a7\/\" \/>\n<meta property=\"og:site_name\" content=\"Explore Agadir Souss Massa\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Explore-Souss-Massa-111659480353930\" \/>\n<meta property=\"article:published_time\" content=\"2020-07-27T08:26:04+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-10-19T12:30:41+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/explore-agadirsoussmassa.com\/wp-content\/uploads\/2020\/02\/Cover_P1010246.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1903\" \/>\n\t<meta property=\"og:image:height\" content=\"600\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"soussmassa\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u0643\u064f\u062a\u0628 \u0628\u0648\u0627\u0633\u0637\u0629\" \/>\n\t<meta name=\"twitter:data1\" content=\"soussmassa\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/explore-agadirsoussmassa.com\/ar\/%d9%88%d8%a7%d8%ad%d8%a9-%d8%a7%d8%ac%d9%88%d9%8a%d9%86%d8%a7%d9%86%d8%a7\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/explore-agadirsoussmassa.com\/ar\/%d9%88%d8%a7%d8%ad%d8%a9-%d8%a7%d8%ac%d9%88%d9%8a%d9%86%d8%a7%d9%86%d8%a7\/\"},\"author\":{\"name\":\"soussmassa\",\"@id\":\"https:\/\/explore-agadirsoussmassa.com\/ar\/#\/schema\/person\/c019e4bcfef76d1c57d426107449d03e\"},\"headline\":\"\u0648\u0627\u062d\u0629 \u0623\u0643\u064a\u0646\u0627\u0646\",\"datePublished\":\"2020-07-27T08:26:04+00:00\",\"dateModified\":\"2020-10-19T12:30:41+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/explore-agadirsoussmassa.com\/ar\/%d9%88%d8%a7%d8%ad%d8%a9-%d8%a7%d8%ac%d9%88%d9%8a%d9%86%d8%a7%d9%86%d8%a7\/\"},\"wordCount\":0,\"publisher\":{\"@id\":\"https:\/\/explore-agadirsoussmassa.com\/ar\/#organization\"},\"image\":{\"@id\":\"https:\/\/explore-agadirsoussmassa.com\/ar\/%d9%88%d8%a7%d8%ad%d8%a9-%d8%a7%d8%ac%d9%88%d9%8a%d9%86%d8%a7%d9%86%d8%a7\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/explore-agadirsoussmassa.com\/wp-content\/uploads\/2020\/02\/Cover_P1010246.jpg\",\"articleSection\":[\"\u0627\u0644\u0648\u0627\u062d\u0627\u062a \u0648\u0627\u0644\u0635\u062d\u0631\u0627\u0621\",\"\u0627\u0644\u0648\u0627\u062d\u0627\u062a \u0648\u0627\u0644\u0646\u062e\u064a\u0644\"],\"inLanguage\":\"ar\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/explore-agadirsoussmassa.com\/ar\/%d9%88%d8%a7%d8%ad%d8%a9-%d8%a7%d8%ac%d9%88%d9%8a%d9%86%d8%a7%d9%86%d8%a7\/\",\"url\":\"https:\/\/explore-agadirsoussmassa.com\/ar\/%d9%88%d8%a7%d8%ad%d8%a9-%d8%a7%d8%ac%d9%88%d9%8a%d9%86%d8%a7%d9%86%d8%a7\/\",\"name\":\"\u0648\u0627\u062d\u0629 \u0623\u0643\u064a\u0646\u0627\u0646 - Explore Agadir Souss Massa\",\"isPartOf\":{\"@id\":\"https:\/\/explore-agadirsoussmassa.com\/ar\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/explore-agadirsoussmassa.com\/ar\/%d9%88%d8%a7%d8%ad%d8%a9-%d8%a7%d8%ac%d9%88%d9%8a%d9%86%d8%a7%d9%86%d8%a7\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/explore-agadirsoussmassa.com\/ar\/%d9%88%d8%a7%d8%ad%d8%a9-%d8%a7%d8%ac%d9%88%d9%8a%d9%86%d8%a7%d9%86%d8%a7\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/explore-agadirsoussmassa.com\/wp-content\/uploads\/2020\/02\/Cover_P1010246.jpg\",\"datePublished\":\"2020-07-27T08:26:04+00:00\",\"dateModified\":\"2020-10-19T12:30:41+00:00\",\"description\":\"\u0633\u062a\u0643\u0648\u0646 \u0632\u064a\u0627\u0631\u0629 \u0648\u0627\u062d\u0629 \u0623\u0643\u064a\u0646\u0627\u0646 \u0648\u0645\u062e\u0627\u0632\u0646 \u0623\u062f\u062e\u0633 \u0623\u0628\u0631\u0632 \u0645\u062d\u0637\u0627\u062a \u0631\u062d\u0644\u062a\u0643\u0645 \u0642\u0628\u0644 \u0627\u0644\u062a\u0648\u062c\u0647 \u0635\u0648\u0628 \u0627\u0644\u0635\u062d\u0631\u0627\u0621 (\u0627\u0644\u0645\u0646\u062a\u0632\u0647 \u0627\u0644\u0648\u0637\u0646\u064a \u0625\u064a\u0631\u064a\u0643\u064a)\",\"breadcrumb\":{\"@id\":\"https:\/\/explore-agadirsoussmassa.com\/ar\/%d9%88%d8%a7%d8%ad%d8%a9-%d8%a7%d8%ac%d9%88%d9%8a%d9%86%d8%a7%d9%86%d8%a7\/#breadcrumb\"},\"inLanguage\":\"ar\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/explore-agadirsoussmassa.com\/ar\/%d9%88%d8%a7%d8%ad%d8%a9-%d8%a7%d8%ac%d9%88%d9%8a%d9%86%d8%a7%d9%86%d8%a7\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"ar\",\"@id\":\"https:\/\/explore-agadirsoussmassa.com\/ar\/%d9%88%d8%a7%d8%ad%d8%a9-%d8%a7%d8%ac%d9%88%d9%8a%d9%86%d8%a7%d9%86%d8%a7\/#primaryimage\",\"url\":\"https:\/\/explore-agadirsoussmassa.com\/wp-content\/uploads\/2020\/02\/Cover_P1010246.jpg\",\"contentUrl\":\"https:\/\/explore-agadirsoussmassa.com\/wp-content\/uploads\/2020\/02\/Cover_P1010246.jpg\",\"width\":1903,\"height\":600,\"caption\":\"Oasis d'Aguinane\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/explore-agadirsoussmassa.com\/ar\/%d9%88%d8%a7%d8%ad%d8%a9-%d8%a7%d8%ac%d9%88%d9%8a%d9%86%d8%a7%d9%86%d8%a7\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/explore-agadirsoussmassa.com\/ar\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u0648\u0627\u062d\u0629 \u0623\u0643\u064a\u0646\u0627\u0646\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/explore-agadirsoussmassa.com\/ar\/#website\",\"url\":\"https:\/\/explore-agadirsoussmassa.com\/ar\/\",\"name\":\"Explore Agadir Souss Massa\",\"description\":\"R\u00e9gion Souss Massa\",\"publisher\":{\"@id\":\"https:\/\/explore-agadirsoussmassa.com\/ar\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/explore-agadirsoussmassa.com\/ar\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ar\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/explore-agadirsoussmassa.com\/ar\/#organization\",\"name\":\"SDR Tourisme Souss Massa\",\"url\":\"https:\/\/explore-agadirsoussmassa.com\/ar\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ar\",\"@id\":\"https:\/\/explore-agadirsoussmassa.com\/ar\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/zt88dgbrixj.preview.infomaniak.website\/wp-content\/uploads\/2020\/08\/logo-sdr.png\",\"contentUrl\":\"https:\/\/zt88dgbrixj.preview.infomaniak.website\/wp-content\/uploads\/2020\/08\/logo-sdr.png\",\"width\":404,\"height\":286,\"caption\":\"SDR Tourisme Souss Massa\"},\"image\":{\"@id\":\"https:\/\/explore-agadirsoussmassa.com\/ar\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/Explore-Souss-Massa-111659480353930\",\"https:\/\/www.instagram.com\/exploresoussmassamorocco\/\",\"https:\/\/www.youtube.com\/channel\/UCpSGZAsRRpG40CeT3UcIcOA\/videos\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/explore-agadirsoussmassa.com\/ar\/#\/schema\/person\/c019e4bcfef76d1c57d426107449d03e\",\"name\":\"soussmassa\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ar\",\"@id\":\"https:\/\/explore-agadirsoussmassa.com\/ar\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/71a3f2c422286f264199c19844c327bfdf2a272a6aab356511f8970061b8dc04?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/71a3f2c422286f264199c19844c327bfdf2a272a6aab356511f8970061b8dc04?s=96&d=mm&r=g\",\"caption\":\"soussmassa\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u0648\u0627\u062d\u0629 \u0623\u0643\u064a\u0646\u0627\u0646 - Explore Agadir Souss Massa","description":"\u0633\u062a\u0643\u0648\u0646 \u0632\u064a\u0627\u0631\u0629 \u0648\u0627\u062d\u0629 \u0623\u0643\u064a\u0646\u0627\u0646 \u0648\u0645\u062e\u0627\u0632\u0646 \u0623\u062f\u062e\u0633 \u0623\u0628\u0631\u0632 \u0645\u062d\u0637\u0627\u062a \u0631\u062d\u0644\u062a\u0643\u0645 \u0642\u0628\u0644 \u0627\u0644\u062a\u0648\u062c\u0647 \u0635\u0648\u0628 \u0627\u0644\u0635\u062d\u0631\u0627\u0621 (\u0627\u0644\u0645\u0646\u062a\u0632\u0647 \u0627\u0644\u0648\u0637\u0646\u064a \u0625\u064a\u0631\u064a\u0643\u064a)","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/explore-agadirsoussmassa.com\/ar\/%d9%88%d8%a7%d8%ad%d8%a9-%d8%a7%d8%ac%d9%88%d9%8a%d9%86%d8%a7%d9%86%d8%a7\/","og_locale":"ar_AR","og_type":"article","og_title":"\u0648\u0627\u062d\u0629 \u0623\u0643\u064a\u0646\u0627\u0646 - Explore Agadir Souss Massa","og_description":"\u0633\u062a\u0643\u0648\u0646 \u0632\u064a\u0627\u0631\u0629 \u0648\u0627\u062d\u0629 \u0623\u0643\u064a\u0646\u0627\u0646 \u0648\u0645\u062e\u0627\u0632\u0646 \u0623\u062f\u062e\u0633 \u0623\u0628\u0631\u0632 \u0645\u062d\u0637\u0627\u062a \u0631\u062d\u0644\u062a\u0643\u0645 \u0642\u0628\u0644 \u0627\u0644\u062a\u0648\u062c\u0647 \u0635\u0648\u0628 \u0627\u0644\u0635\u062d\u0631\u0627\u0621 (\u0627\u0644\u0645\u0646\u062a\u0632\u0647 \u0627\u0644\u0648\u0637\u0646\u064a \u0625\u064a\u0631\u064a\u0643\u064a)","og_url":"https:\/\/explore-agadirsoussmassa.com\/ar\/%d9%88%d8%a7%d8%ad%d8%a9-%d8%a7%d8%ac%d9%88%d9%8a%d9%86%d8%a7%d9%86%d8%a7\/","og_site_name":"Explore Agadir Souss Massa","article_publisher":"https:\/\/www.facebook.com\/Explore-Souss-Massa-111659480353930","article_published_time":"2020-07-27T08:26:04+00:00","article_modified_time":"2020-10-19T12:30:41+00:00","og_image":[{"width":1903,"height":600,"url":"https:\/\/explore-agadirsoussmassa.com\/wp-content\/uploads\/2020\/02\/Cover_P1010246.jpg","type":"image\/jpeg"}],"author":"soussmassa","twitter_card":"summary_large_image","twitter_misc":{"\u0643\u064f\u062a\u0628 \u0628\u0648\u0627\u0633\u0637\u0629":"soussmassa"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/explore-agadirsoussmassa.com\/ar\/%d9%88%d8%a7%d8%ad%d8%a9-%d8%a7%d8%ac%d9%88%d9%8a%d9%86%d8%a7%d9%86%d8%a7\/#article","isPartOf":{"@id":"https:\/\/explore-agadirsoussmassa.com\/ar\/%d9%88%d8%a7%d8%ad%d8%a9-%d8%a7%d8%ac%d9%88%d9%8a%d9%86%d8%a7%d9%86%d8%a7\/"},"author":{"name":"soussmassa","@id":"https:\/\/explore-agadirsoussmassa.com\/ar\/#\/schema\/person\/c019e4bcfef76d1c57d426107449d03e"},"headline":"\u0648\u0627\u062d\u0629 \u0623\u0643\u064a\u0646\u0627\u0646","datePublished":"2020-07-27T08:26:04+00:00","dateModified":"2020-10-19T12:30:41+00:00","mainEntityOfPage":{"@id":"https:\/\/explore-agadirsoussmassa.com\/ar\/%d9%88%d8%a7%d8%ad%d8%a9-%d8%a7%d8%ac%d9%88%d9%8a%d9%86%d8%a7%d9%86%d8%a7\/"},"wordCount":0,"publisher":{"@id":"https:\/\/explore-agadirsoussmassa.com\/ar\/#organization"},"image":{"@id":"https:\/\/explore-agadirsoussmassa.com\/ar\/%d9%88%d8%a7%d8%ad%d8%a9-%d8%a7%d8%ac%d9%88%d9%8a%d9%86%d8%a7%d9%86%d8%a7\/#primaryimage"},"thumbnailUrl":"https:\/\/explore-agadirsoussmassa.com\/wp-content\/uploads\/2020\/02\/Cover_P1010246.jpg","articleSection":["\u0627\u0644\u0648\u0627\u062d\u0627\u062a \u0648\u0627\u0644\u0635\u062d\u0631\u0627\u0621","\u0627\u0644\u0648\u0627\u062d\u0627\u062a \u0648\u0627\u0644\u0646\u062e\u064a\u0644"],"inLanguage":"ar"},{"@type":"WebPage","@id":"https:\/\/explore-agadirsoussmassa.com\/ar\/%d9%88%d8%a7%d8%ad%d8%a9-%d8%a7%d8%ac%d9%88%d9%8a%d9%86%d8%a7%d9%86%d8%a7\/","url":"https:\/\/explore-agadirsoussmassa.com\/ar\/%d9%88%d8%a7%d8%ad%d8%a9-%d8%a7%d8%ac%d9%88%d9%8a%d9%86%d8%a7%d9%86%d8%a7\/","name":"\u0648\u0627\u062d\u0629 \u0623\u0643\u064a\u0646\u0627\u0646 - Explore Agadir Souss Massa","isPartOf":{"@id":"https:\/\/explore-agadirsoussmassa.com\/ar\/#website"},"primaryImageOfPage":{"@id":"https:\/\/explore-agadirsoussmassa.com\/ar\/%d9%88%d8%a7%d8%ad%d8%a9-%d8%a7%d8%ac%d9%88%d9%8a%d9%86%d8%a7%d9%86%d8%a7\/#primaryimage"},"image":{"@id":"https:\/\/explore-agadirsoussmassa.com\/ar\/%d9%88%d8%a7%d8%ad%d8%a9-%d8%a7%d8%ac%d9%88%d9%8a%d9%86%d8%a7%d9%86%d8%a7\/#primaryimage"},"thumbnailUrl":"https:\/\/explore-agadirsoussmassa.com\/wp-content\/uploads\/2020\/02\/Cover_P1010246.jpg","datePublished":"2020-07-27T08:26:04+00:00","dateModified":"2020-10-19T12:30:41+00:00","description":"\u0633\u062a\u0643\u0648\u0646 \u0632\u064a\u0627\u0631\u0629 \u0648\u0627\u062d\u0629 \u0623\u0643\u064a\u0646\u0627\u0646 \u0648\u0645\u062e\u0627\u0632\u0646 \u0623\u062f\u062e\u0633 \u0623\u0628\u0631\u0632 \u0645\u062d\u0637\u0627\u062a \u0631\u062d\u0644\u062a\u0643\u0645 \u0642\u0628\u0644 \u0627\u0644\u062a\u0648\u062c\u0647 \u0635\u0648\u0628 \u0627\u0644\u0635\u062d\u0631\u0627\u0621 (\u0627\u0644\u0645\u0646\u062a\u0632\u0647 \u0627\u0644\u0648\u0637\u0646\u064a \u0625\u064a\u0631\u064a\u0643\u064a)","breadcrumb":{"@id":"https:\/\/explore-agadirsoussmassa.com\/ar\/%d9%88%d8%a7%d8%ad%d8%a9-%d8%a7%d8%ac%d9%88%d9%8a%d9%86%d8%a7%d9%86%d8%a7\/#breadcrumb"},"inLanguage":"ar","potentialAction":[{"@type":"ReadAction","target":["https:\/\/explore-agadirsoussmassa.com\/ar\/%d9%88%d8%a7%d8%ad%d8%a9-%d8%a7%d8%ac%d9%88%d9%8a%d9%86%d8%a7%d9%86%d8%a7\/"]}]},{"@type":"ImageObject","inLanguage":"ar","@id":"https:\/\/explore-agadirsoussmassa.com\/ar\/%d9%88%d8%a7%d8%ad%d8%a9-%d8%a7%d8%ac%d9%88%d9%8a%d9%86%d8%a7%d9%86%d8%a7\/#primaryimage","url":"https:\/\/explore-agadirsoussmassa.com\/wp-content\/uploads\/2020\/02\/Cover_P1010246.jpg","contentUrl":"https:\/\/explore-agadirsoussmassa.com\/wp-content\/uploads\/2020\/02\/Cover_P1010246.jpg","width":1903,"height":600,"caption":"Oasis d'Aguinane"},{"@type":"BreadcrumbList","@id":"https:\/\/explore-agadirsoussmassa.com\/ar\/%d9%88%d8%a7%d8%ad%d8%a9-%d8%a7%d8%ac%d9%88%d9%8a%d9%86%d8%a7%d9%86%d8%a7\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/explore-agadirsoussmassa.com\/ar\/"},{"@type":"ListItem","position":2,"name":"\u0648\u0627\u062d\u0629 \u0623\u0643\u064a\u0646\u0627\u0646"}]},{"@type":"WebSite","@id":"https:\/\/explore-agadirsoussmassa.com\/ar\/#website","url":"https:\/\/explore-agadirsoussmassa.com\/ar\/","name":"Explore Agadir Souss Massa","description":"R\u00e9gion Souss Massa","publisher":{"@id":"https:\/\/explore-agadirsoussmassa.com\/ar\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/explore-agadirsoussmassa.com\/ar\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ar"},{"@type":"Organization","@id":"https:\/\/explore-agadirsoussmassa.com\/ar\/#organization","name":"SDR Tourisme Souss Massa","url":"https:\/\/explore-agadirsoussmassa.com\/ar\/","logo":{"@type":"ImageObject","inLanguage":"ar","@id":"https:\/\/explore-agadirsoussmassa.com\/ar\/#\/schema\/logo\/image\/","url":"https:\/\/zt88dgbrixj.preview.infomaniak.website\/wp-content\/uploads\/2020\/08\/logo-sdr.png","contentUrl":"https:\/\/zt88dgbrixj.preview.infomaniak.website\/wp-content\/uploads\/2020\/08\/logo-sdr.png","width":404,"height":286,"caption":"SDR Tourisme Souss Massa"},"image":{"@id":"https:\/\/explore-agadirsoussmassa.com\/ar\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Explore-Souss-Massa-111659480353930","https:\/\/www.instagram.com\/exploresoussmassamorocco\/","https:\/\/www.youtube.com\/channel\/UCpSGZAsRRpG40CeT3UcIcOA\/videos"]},{"@type":"Person","@id":"https:\/\/explore-agadirsoussmassa.com\/ar\/#\/schema\/person\/c019e4bcfef76d1c57d426107449d03e","name":"soussmassa","image":{"@type":"ImageObject","inLanguage":"ar","@id":"https:\/\/explore-agadirsoussmassa.com\/ar\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/71a3f2c422286f264199c19844c327bfdf2a272a6aab356511f8970061b8dc04?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/71a3f2c422286f264199c19844c327bfdf2a272a6aab356511f8970061b8dc04?s=96&d=mm&r=g","caption":"soussmassa"}}]}},"_links":{"self":[{"href":"https:\/\/explore-agadirsoussmassa.com\/ar\/wp-json\/wp\/v2\/posts\/34541","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/explore-agadirsoussmassa.com\/ar\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/explore-agadirsoussmassa.com\/ar\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/explore-agadirsoussmassa.com\/ar\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/explore-agadirsoussmassa.com\/ar\/wp-json\/wp\/v2\/comments?post=34541"}],"version-history":[{"count":5,"href":"https:\/\/explore-agadirsoussmassa.com\/ar\/wp-json\/wp\/v2\/posts\/34541\/revisions"}],"predecessor-version":[{"id":40535,"href":"https:\/\/explore-agadirsoussmassa.com\/ar\/wp-json\/wp\/v2\/posts\/34541\/revisions\/40535"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/explore-agadirsoussmassa.com\/ar\/wp-json\/wp\/v2\/media\/6903"}],"wp:attachment":[{"href":"https:\/\/explore-agadirsoussmassa.com\/ar\/wp-json\/wp\/v2\/media?parent=34541"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/explore-agadirsoussmassa.com\/ar\/wp-json\/wp\/v2\/categories?post=34541"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/explore-agadirsoussmassa.com\/ar\/wp-json\/wp\/v2\/tags?post=34541"},{"taxonomy":"powerkit_post_featured","embeddable":true,"href":"https:\/\/explore-agadirsoussmassa.com\/ar\/wp-json\/wp\/v2\/powerkit_post_featured?post=34541"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}