{"id":34795,"date":"2020-04-21T16:20:02","date_gmt":"2020-04-21T14:20:02","guid":{"rendered":"https:\/\/explore-agadirsoussmassa.com\/top-5-des-sorties-autour-de-tiznit\/"},"modified":"2021-02-19T11:03:04","modified_gmt":"2021-02-19T10:03:04","slug":"%d9%86%d8%b2%d9%87%d8%a7%d8%aa-%d8%b9%d8%a7%d8%a6%d9%84%d9%8a%d8%a9-%d8%ad%d9%88%d9%84-%d8%aa%d8%b2%d9%86%d9%8a%d8%aa","status":"publish","type":"post","link":"https:\/\/explore-agadirsoussmassa.com\/ar\/%d9%86%d8%b2%d9%87%d8%a7%d8%aa-%d8%b9%d8%a7%d8%a6%d9%84%d9%8a%d8%a9-%d8%ad%d9%88%d9%84-%d8%aa%d8%b2%d9%86%d9%8a%d8%aa\/","title":{"rendered":"\u0646\u0632\u0647\u0627\u062a \u0639\u0627\u0626\u0644\u064a\u0629 \u062d\u0648\u0644 \u062a\u0632\u0646\u064a\u062a"},"content":{"rendered":"<div id=\"pl-gb34795-6a580f42226d4\"  class=\"panel-layout panel-is-rtl\" ><div id=\"pg-gb34795-6a580f42226d4-0\"  class=\"panel-grid panel-no-style\" ><div id=\"pgc-gb34795-6a580f42226d4-0-0\"  class=\"panel-grid-cell\" ><div id=\"panel-gb34795-6a580f42226d4-0-0-0\" class=\"so-panel widget widget_text panel-first-child panel-last-child\" data-index=\"0\" ><div id=\"sdrstyle\" class=\"panel-widget-style panel-widget-style-for-gb34795-6a580f42226d4-0-0-0\" >\t\t\t<div class=\"textwidget\"><h3 id=\"%d9%85%d9%82%d8%aa%d8%b1%d8%ad%d8%a7%d8%aa-%d8%a3%d9%86%d8%b4%d8%b7%d8%a9-%d8%a8%d8%a7%d9%84%d9%82%d8%b1%d8%a8-%d9%85%d9%86-%d8%aa%d8%b2%d9%86%d9%8a%d8%aa%d8%9f\" style=\";text-align: right; direction: rtl;\">\u0645\u0642\u062a\u0631\u062d\u0627\u062a \u0623\u0646\u0634\u0637\u0629 \u0628\u0627\u0644\u0642\u0631\u0628 \u0645\u0646 \u062a\u0632\u0646\u064a\u062a\u061f<\/h3>\n<p>\u0627\u0644\u0631\u062d\u0644\u0629 \u0645\u0646 \u0623\u0643\u0627\u062f\u064a\u0631: \u0633\u0627\u0639\u0629 \u0648 40 \u062f\u0642\u064a\u0642\u0629 \/ 95 \u0643\u064a\u0644\u0648\u0645\u062a\u0631 (\u0633\u064a\u0627\u0631\u0629)<\/p>\n<p>\u0627\u0644\u0645\u0646\u062a\u0632\u0647 \u0627\u0644\u0648\u0637\u0646\u064a<span style=\"text-align: right;\"> &#8211; \u0627\u0644\u0633\u0627\u062d\u0644\/\u0627\u0644\u0623\u0646\u0634\u0637\u0629 \u0627\u0644\u0628\u062d\u0631\u064a\u0629 &#8211; \u0627\u0644\u0635\u062d\u0631\u0627\u0621 \u0627\u0644\u0635\u063a\u064a\u0631\u0629 &#8211; \u0627\u0644\u0628\u062d\u064a\u0631\u0629<\/span><\/p>\n<p>\u0634\u0627\u0637\u0626 \u0645\u0647\u062c\u0648\u0631 \u062c\u0646\u0648\u0628 \u0623\u0643\u0644\u0648 \u0623\u0648 \u0635\u062d\u0631\u0627\u0621 \u0635\u063a\u064a\u0631\u0629 \u062f\u0627\u062e\u0644\u064a\u0629\u061f \u0646\u0632\u0647\u0629 \u0641\u064a \u0627\u0644\u0628\u062d\u064a\u0631\u0629 \u0623\u0645 <a href=\"\/circuit-piste-cotiere-4x4-sud-agadir\/\" target=\"_blank\" rel=\"noopener\">\u0645\u0633\u0627\u0631\u0628\u0627\u0644\u0633\u064a\u0627\u0631\u0627\u062a \u0627\u0644\u0631\u0628\u0627\u0639\u064a\u0629 \u0627\u0644\u062f\u0641\u0639 \u0639\u0644\u0649 \u0637\u0648\u0644 \u0627\u0644\u0633\u0627\u062d\u0644<\/a> \u061f \u0645\u0631\u0627\u0642\u0628\u0629 \u0627\u0644\u0637\u064a\u0648\u0631 \u0627\u0644\u0645\u0647\u0627\u062c\u0631\u0629 \u0639\u0646\u062f <a href=\"\/observation-des-oiseaux-oued-massa\/\" target=\"_blank\" rel=\"noopener\">\u0645\u0635\u0628 \u0648\u0627\u062f\u064a \u0645\u0627\u0633\u0629<\/a> \u0623\u0645 \u0627\u0644\u0623\u0646\u0634\u0637\u0629 \u0627\u0644\u0628\u062d\u0631\u064a\u0629\u061f \u0644\u0643\u0645 \u0648\u0627\u0633\u0639 \u0627\u0644\u0627\u062e\u062a\u064a\u0627\u0631! <em><br \/>\n<\/em><\/p>\n<\/div>\n\t\t<\/div><\/div><\/div><\/div><\/div>\n\n<div class=\"cnvs-block-justified-gallery cnvs-block-justified-gallery-1595379598031\" >\n<div\n\tclass='gallery cnvs-gallery-type-justified'\n\tdata-jg-margins=\"10\"\n\tdata-jg-border=\"-10\"\n\tdata-jg-row-height=\"258\"\n\tdata-jg-max-row-height=\"250%\"\n\tdata-jg-last-row=\"justify\"\n\tdata-jg-captions=\"true\"\n\tdata-jg-randomize=\"false\"\n>\n\t\t\t<figure class=\"gallery-item\">\n\t\t\t\t\t\t\t<a href=\"https:\/\/explore-agadirsoussmassa.com\/wp-content\/uploads\/2019\/12\/2020-02-014648848455.jpg\">\n\t\t\t\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"833\" height=\"625\" src=\"https:\/\/explore-agadirsoussmassa.com\/wp-content\/uploads\/2019\/12\/2020-02-014648848455.jpg\" class=\"attachment-csco-1160 size-csco-1160\" alt=\"Parapente - Aglou\" srcset=\"https:\/\/explore-agadirsoussmassa.com\/wp-content\/uploads\/2019\/12\/2020-02-014648848455.jpg 833w, https:\/\/explore-agadirsoussmassa.com\/wp-content\/uploads\/2019\/12\/2020-02-014648848455-800x600.jpg 800w, https:\/\/explore-agadirsoussmassa.com\/wp-content\/uploads\/2019\/12\/2020-02-014648848455-320x240.jpg 320w, https:\/\/explore-agadirsoussmassa.com\/wp-content\/uploads\/2019\/12\/2020-02-014648848455-300x225.jpg 300w, https:\/\/explore-agadirsoussmassa.com\/wp-content\/uploads\/2019\/12\/2020-02-014648848455-560x420.jpg 560w\" sizes=\"auto, (max-width: 833px) 100vw, 833px\" \/>\n\t\t\t\t\t\t\t<\/a>\n\t\t\t\n\t\t\t<div class=\"caption wp-caption-text gallery-caption\">\u0627\u0644\u0637\u064a\u0631\u0627\u0646 \u0627\u0644\u0634\u0631\u0627\u0639\u064a &#8211; \u0623\u0643\u0644\u0648<\/div>\t\t<\/figure>\n\t\t\t\t<figure class=\"gallery-item\">\n\t\t\t\t\t\t\t<a href=\"https:\/\/explore-agadirsoussmassa.com\/wp-content\/uploads\/2020\/01\/005111541.jpg\">\n\t\t\t\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"833\" height=\"625\" src=\"https:\/\/explore-agadirsoussmassa.com\/wp-content\/uploads\/2020\/01\/005111541.jpg\" class=\"attachment-csco-1160 size-csco-1160\" alt=\"C\u00f4te Nord - Aglou\" srcset=\"https:\/\/explore-agadirsoussmassa.com\/wp-content\/uploads\/2020\/01\/005111541.jpg 833w, https:\/\/explore-agadirsoussmassa.com\/wp-content\/uploads\/2020\/01\/005111541-800x600.jpg 800w, https:\/\/explore-agadirsoussmassa.com\/wp-content\/uploads\/2020\/01\/005111541-320x240.jpg 320w, https:\/\/explore-agadirsoussmassa.com\/wp-content\/uploads\/2020\/01\/005111541-300x225.jpg 300w, https:\/\/explore-agadirsoussmassa.com\/wp-content\/uploads\/2020\/01\/005111541-560x420.jpg 560w\" sizes=\"auto, (max-width: 833px) 100vw, 833px\" \/>\n\t\t\t\t\t\t\t<\/a>\n\t\t\t\n\t\t\t<div class=\"caption wp-caption-text gallery-caption\">\u0627\u0644\u0633\u0627\u062d\u0644 \u0627\u0644\u0634\u0645\u0627\u0644\u0649 &#8211; \u0623\u0643\u0644\u0648<\/div>\t\t<\/figure>\n\t\t\t\t<figure class=\"gallery-item\">\n\t\t\t\t\t\t\t<a href=\"https:\/\/explore-agadirsoussmassa.com\/wp-content\/uploads\/2020\/04\/Capture-d\u2019e\u0301cran-2020-05-22-a\u0300-18.59.16-min.png\">\n\t\t\t\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1160\" height=\"870\" src=\"https:\/\/explore-agadirsoussmassa.com\/wp-content\/uploads\/2020\/04\/Capture-d\u2019e\u0301cran-2020-05-22-a\u0300-18.59.16-min.png\" class=\"attachment-csco-1160 size-csco-1160\" alt=\"Corniche - Aglou\" srcset=\"https:\/\/explore-agadirsoussmassa.com\/wp-content\/uploads\/2020\/04\/Capture-d\u2019e\u0301cran-2020-05-22-a\u0300-18.59.16-min.png 1680w, https:\/\/explore-agadirsoussmassa.com\/wp-content\/uploads\/2020\/04\/Capture-d\u2019e\u0301cran-2020-05-22-a\u0300-18.59.16-min-800x600.png 800w, https:\/\/explore-agadirsoussmassa.com\/wp-content\/uploads\/2020\/04\/Capture-d\u2019e\u0301cran-2020-05-22-a\u0300-18.59.16-min-1160x870.png 1160w, https:\/\/explore-agadirsoussmassa.com\/wp-content\/uploads\/2020\/04\/Capture-d\u2019e\u0301cran-2020-05-22-a\u0300-18.59.16-min-320x240.png 320w, https:\/\/explore-agadirsoussmassa.com\/wp-content\/uploads\/2020\/04\/Capture-d\u2019e\u0301cran-2020-05-22-a\u0300-18.59.16-min-1536x1152.png 1536w, https:\/\/explore-agadirsoussmassa.com\/wp-content\/uploads\/2020\/04\/Capture-d\u2019e\u0301cran-2020-05-22-a\u0300-18.59.16-min-300x225.png 300w, https:\/\/explore-agadirsoussmassa.com\/wp-content\/uploads\/2020\/04\/Capture-d\u2019e\u0301cran-2020-05-22-a\u0300-18.59.16-min-560x420.png 560w\" sizes=\"auto, (max-width: 1160px) 100vw, 1160px\" \/>\n\t\t\t\t\t\t\t<\/a>\n\t\t\t\n\t\t\t<div class=\"caption wp-caption-text gallery-caption\">\u0627\u0644\u0643\u0648\u0631\u0646\u064a\u0634 &#8211; \u0623\u0643\u0644\u0648<\/div>\t\t<\/figure>\n\t\t<\/div>\n\n<\/div>\n\n<div id=\"pl-gb34795-6a580f4225212\"  class=\"panel-layout panel-is-rtl\" ><div id=\"pg-gb34795-6a580f4225212-0\"  class=\"panel-grid panel-no-style\" ><div id=\"pgc-gb34795-6a580f4225212-0-0\"  class=\"panel-grid-cell\" ><div id=\"panel-gb34795-6a580f4225212-0-0-0\" class=\"so-panel widget widget_text panel-first-child panel-last-child\" data-index=\"0\" >\t\t\t<div class=\"textwidget\"><p>\u0634\u0627\u0637\u0626 \u0623\u0643\u0644\u0648<\/p>\n<p>\u0644\u0627 \u062a\u062a\u0631\u062f\u062f\u0648\u0627 \u0641\u064a \u0627\u0643\u062a\u0634\u0627\u0641 \u0642\u0631\u064a\u0629 \u0627\u0644\u0635\u064a\u0627\u062f\u064a\u0646\u060c \u0623\u0643\u0644\u0648\u060c \u0627\u0644\u0648\u0627\u0642\u0639\u0629 \u0639\u0644\u0649 \u0628\u0639\u062f 17 \u0643\u0644\u0645 \u0634\u0645\u0627\u0644 \u063a\u0631\u0628 \u062a\u064a\u0632\u0646\u064a\u062a. \u062d\u064a\u062b \u064a\u0644\u062a\u0642\u064a \u0627\u0644\u0645\u062d\u064a\u0637 \u0627\u0644\u0623\u0637\u0644\u0633\u064a \u0628\u0627\u0644\u0635\u062d\u0631\u0627\u0621 \u0641\u064a \u0647\u0630\u0627 \u0627\u0644\u0645\u0648\u0642\u0639 (\u0634\u0648\u0627\u0637\u0626 \u0631\u0645\u0644\u064a\u0629 \u0641\u0633\u064a\u062d\u0629\u060c \u0647\u0636\u0627\u0628 \u0645\u0637\u0644\u0629 \u0639\u0644\u0649 \u0627\u0644\u0645\u062d\u064a\u0637\u060c \u0643\u062b\u0628\u0627\u0646 \u0631\u0645\u0644\u064a\u0629).<\/p>\n<p>\u0643\u0645\u0627 \u0633\u062a\u0639\u062b\u0631\u0648\u0646 \u0641\u064a \u0647\u0630\u0647 \u0627\u0644\u0645\u0646\u0637\u0642\u0629 \u0639\u0644\u0649 \u0643\u0647\u0648\u0641 \u0635\u062e\u0631\u064a\u0629 \u0643\u0627\u0646 \u064a\u0633\u0643\u0646\u0647\u0627 \u0627\u0644\u0635\u064a\u0627\u062f\u064a\u0648\u0646\u060c \u0648\u064a\u0645\u0643\u0646 \u062d\u062a\u0649 \u0642\u0636\u0627\u0621 \u0627\u0644\u0644\u064a\u0644 \u0641\u064a \u0628\u0639\u0636\u0647\u0627. \u0634\u0645\u0627\u0644 \u0643\u0648\u0631\u0646\u064a\u0634 \u0623\u0643\u0644\u0648\u060c \u062a\u0648\u062c\u0647\u0648\u0627 \u062c\u0646\u0648\u0628\u0627 \u0635\u0648\u0628 \u0645\u064a\u0631\u0644\u0641\u062a\u060c \u0648\u0633\u062a\u0635\u0644\u0648\u0646 \u0625\u0644\u0649 \u0634\u0648\u0627\u0637\u0626 \u0641\u0633\u064a\u062d\u0629 \u062e\u0627\u0644\u064a\u0629\u060c \u0646\u0627\u0647\u064a\u0643 \u0639\u0646 \u0645\u062c\u0645\u0648\u0639\u0629 \u0645\u0646 \u0627\u0644\u0642\u0631\u0649\u060c \u0645\u0646 \u0628\u064a\u0646\u0647\u0627 \u0642\u0631\u064a\u0629 \u0627\u0644\u0635\u064a\u0627\u062f\u064a\u0646 \u0633\u064a\u062f\u064a \u0628\u0648\u0644\u0641\u0636\u0627\u064a\u0644 (29.668387\u060c 9.983036-).<\/p>\n<p>\u0643\u064a\u0641\u064a\u0629 \u0627\u0644\u0648\u0635\u0648\u0644:<\/p>\n<p>\u0627\u0646\u0637\u0644\u0627\u0642\u0627 \u0645\u0646 \u062a\u064a\u0632\u0646\u064a\u062a\u060c \u0627\u0633\u0644\u0643\u0648\u0627 \u0627\u0644\u0637\u0631\u064a\u0642 \u0627\u0644\u0625\u0642\u0644\u064a\u0645\u064a\u0629 1909 \u0641\u064a \u0627\u062a\u062c\u0627\u0647 \u0627\u0644\u0634\u0645\u0627\u0644 \u0627\u0644\u063a\u0631\u0628\u064a.<\/p>\n<\/div>\n\t\t<\/div><\/div><\/div><\/div>\n\n<div class=\"cnvs-block-justified-gallery cnvs-block-justified-gallery-1595379791210\" >\n<div\n\tclass='gallery cnvs-gallery-type-justified'\n\tdata-jg-margins=\"10\"\n\tdata-jg-border=\"-10\"\n\tdata-jg-row-height=\"258\"\n\tdata-jg-max-row-height=\"250%\"\n\tdata-jg-last-row=\"justify\"\n\tdata-jg-captions=\"true\"\n\tdata-jg-randomize=\"false\"\n>\n\t\t\t<figure class=\"gallery-item\">\n\t\t\t\t\t\t\t<a href=\"https:\/\/explore-agadirsoussmassa.com\/wp-content\/uploads\/2020\/02\/Capture-d\u2019e\u0301cran-2020-03-09-a\u0300-09.07.42.png\">\n\t\t\t\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"756\" height=\"568\" src=\"https:\/\/explore-agadirsoussmassa.com\/wp-content\/uploads\/2020\/02\/Capture-d\u2019e\u0301cran-2020-03-09-a\u0300-09.07.42.png\" class=\"attachment-csco-1160 size-csco-1160\" alt=\"Sidi Boulfdail\" srcset=\"https:\/\/explore-agadirsoussmassa.com\/wp-content\/uploads\/2020\/02\/Capture-d\u2019e\u0301cran-2020-03-09-a\u0300-09.07.42.png 756w, https:\/\/explore-agadirsoussmassa.com\/wp-content\/uploads\/2020\/02\/Capture-d\u2019e\u0301cran-2020-03-09-a\u0300-09.07.42-320x240.png 320w, https:\/\/explore-agadirsoussmassa.com\/wp-content\/uploads\/2020\/02\/Capture-d\u2019e\u0301cran-2020-03-09-a\u0300-09.07.42-300x225.png 300w, https:\/\/explore-agadirsoussmassa.com\/wp-content\/uploads\/2020\/02\/Capture-d\u2019e\u0301cran-2020-03-09-a\u0300-09.07.42-560x420.png 560w\" sizes=\"auto, (max-width: 756px) 100vw, 756px\" \/>\n\t\t\t\t\t\t\t<\/a>\n\t\t\t\n\t\t\t<div class=\"caption wp-caption-text gallery-caption\">\u0633\u064a\u062f\u064a \u0628\u0648\u0644\u0641\u0636\u0627\u064a\u0644<\/div>\t\t<\/figure>\n\t\t\t\t<figure class=\"gallery-item\">\n\t\t\t\t\t\t\t<a href=\"https:\/\/explore-agadirsoussmassa.com\/wp-content\/uploads\/2020\/04\/Capture-d\u2019e\u0301cran-2020-06-18-a\u0300-12.32.42-min-1.png\">\n\t\t\t\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1160\" height=\"870\" src=\"https:\/\/explore-agadirsoussmassa.com\/wp-content\/uploads\/2020\/04\/Capture-d\u2019e\u0301cran-2020-06-18-a\u0300-12.32.42-min-1.png\" class=\"attachment-csco-1160 size-csco-1160\" alt=\"Parapente - Littoral\" srcset=\"https:\/\/explore-agadirsoussmassa.com\/wp-content\/uploads\/2020\/04\/Capture-d\u2019e\u0301cran-2020-06-18-a\u0300-12.32.42-min-1.png 1600w, https:\/\/explore-agadirsoussmassa.com\/wp-content\/uploads\/2020\/04\/Capture-d\u2019e\u0301cran-2020-06-18-a\u0300-12.32.42-min-1-800x600.png 800w, https:\/\/explore-agadirsoussmassa.com\/wp-content\/uploads\/2020\/04\/Capture-d\u2019e\u0301cran-2020-06-18-a\u0300-12.32.42-min-1-1160x870.png 1160w, https:\/\/explore-agadirsoussmassa.com\/wp-content\/uploads\/2020\/04\/Capture-d\u2019e\u0301cran-2020-06-18-a\u0300-12.32.42-min-1-320x240.png 320w, https:\/\/explore-agadirsoussmassa.com\/wp-content\/uploads\/2020\/04\/Capture-d\u2019e\u0301cran-2020-06-18-a\u0300-12.32.42-min-1-1536x1152.png 1536w, https:\/\/explore-agadirsoussmassa.com\/wp-content\/uploads\/2020\/04\/Capture-d\u2019e\u0301cran-2020-06-18-a\u0300-12.32.42-min-1-300x225.png 300w, https:\/\/explore-agadirsoussmassa.com\/wp-content\/uploads\/2020\/04\/Capture-d\u2019e\u0301cran-2020-06-18-a\u0300-12.32.42-min-1-560x420.png 560w\" sizes=\"auto, (max-width: 1160px) 100vw, 1160px\" \/>\n\t\t\t\t\t\t\t<\/a>\n\t\t\t\n\t\t\t<div class=\"caption wp-caption-text gallery-caption\">\u0627\u0644\u0637\u064a\u0631\u0627\u0646 \u0627\u0644\u0634\u0631\u0627\u0639\u064a &#8211; \u0627\u0644\u062e\u0637 \u0627\u0644\u0633\u0627\u062d\u0644\u064a<\/div>\t\t<\/figure>\n\t\t<\/div>\n\n<\/div>\n\n<div id=\"pl-gb34795-6a580f4226bf4\"  class=\"panel-layout panel-is-rtl\" ><div id=\"pg-gb34795-6a580f4226bf4-0\"  class=\"panel-grid panel-no-style\" ><div id=\"pgc-gb34795-6a580f4226bf4-0-0\"  class=\"panel-grid-cell\" ><div id=\"panel-gb34795-6a580f4226bf4-0-0-0\" class=\"so-panel widget widget_text panel-first-child panel-last-child\" data-index=\"0\" ><div id=\"sdrstyle\" class=\"panel-widget-style panel-widget-style-for-gb34795-6a580f4226bf4-0-0-0\" >\t\t\t<div class=\"textwidget\"><p><strong>\u062c\u0648\u0644\u0627\u062a \u0628\u0627\u0644\u0633\u064a\u0627\u0631\u0627\u062a \u0627\u0644\u0631\u0628\u0627\u0639\u064a\u0629 \u0627\u0644\u062f\u0641\u0639 \u0644\u0644\u0623\u0633\u0631\u0629 \u0643\u0644\u0647\u0627<\/strong><\/p>\n<p>\u0645\u0646 \u0623\u0643\u0644\u0648 (\u0627\u062a\u062c\u0627\u0647 \u0627\u0644\u0634\u0645\u0627\u0644 \u0627\u0644\u063a\u0631\u0628\u064a)\u060c \u0633\u062a\u062c\u062f\u0648\u0646 \u0631\u062d\u0644\u0627\u062a \u0627\u0633\u062a\u0643\u0634\u0627\u0641\u064a\u0629 \u0631\u0627\u0626\u0639\u0629 \u0639\u0644\u0649 \u0645\u062a\u0646 \u0627\u0644\u0633\u064a\u0627\u0631\u0627\u062a \u0627\u0644\u0631\u0628\u0627\u0639\u064a\u0629 \u0627\u0644\u062f\u0641\u0639. (\u0646\u0642\u0637\u0629 \u0627\u0644\u0628\u062f\u0627\u064a\u0629: 29.803602\u060c 9.825272-)\u060c \u0625\u0644\u0649 \u0648\u0627\u062f \u0645\u0627\u0633\u0629 \u0623\u0648 \u062a\u064a\u0641\u0646\u064a\u062a. \u0633\u062a\u062c\u062f\u0648\u0646 \u0628\u0633\u0631\u0639\u0629 \u0641\u064a \u0647\u0630\u0627 \u0627\u0644\u0627\u062a\u062c\u0627\u0647 \u0643\u0647\u0648\u0641 \u0627\u0644\u0635\u064a\u0627\u062f\u064a\u0646 (29.811917\u060c 9.828957-) \u062b\u0645 \u0645\u062d\u0645\u064a\u0629 \u0627\u0644\u0637\u064a\u0648\u0631 \u0641\u064a \u0648\u0627\u062f\u064a \u0645\u0627\u0633\u0629 (\u0627\u0644\u0645\u0646\u062a\u0632\u0647 \u0627\u0644\u0648\u0637\u0646\u064a \u0633\u0648\u0633 \u0645\u0627\u0633\u0629 = 30.057156\u060c 9.655337-) \u0648\u0647\u0648 \u0645\u0648\u0642\u0639 \u0631\u0627\u0626\u0639 <a href=\"\/observation-des-oiseaux-oued-massa\/\">\u0644\u0645\u0634\u0627\u0647\u062f\u0629 \u0627\u0644\u0637\u064a\u0648\u0631<\/a> .<\/p>\n<p>\u0633\u0648\u0641 \u062a\u062c\u062f\u0648\u0646 \u0623\u064a\u0636\u064b\u0627 \u0641\u064a <a href=\"\/sidi-rbat\/\">\u0633\u064a\u062f\u064a \u0627\u0644\u0631\u0628\u0627\u0637<\/a> (30.091839\u060c -9.665463) \u0634\u0627\u0637\u0626\u064b\u0627 \u0631\u0627\u0626\u0639\u064b\u0627 \u0628\u0647 \u0645\u0633\u0627\u0643\u0646 \u0643\u0647\u0641\u064a\u0629. \u0633\u064a\u062f\u064a \u0627\u0644\u0631\u0628\u0627\u0637 \u0647\u0648 \u0634\u0627\u0637\u0626 \u0645\u0647\u062c\u0648\u0631 \u0631\u0627\u0626\u0639 \u0644\u0644\u0627\u0633\u062a\u0631\u062e\u0627\u0621 \u0648\u0627\u0644\u0639\u064a\u0634 \u0641\u064a \u0642\u0644\u0628 \u0627\u0644\u0645\u0646\u062a\u0632\u0647 \u0627\u0644\u0637\u0628\u064a\u0639\u064a \u0628\u0645\u0646\u0637\u0642\u0629 \u0633\u0648\u0633 \u0645\u0627\u0633\u0629. \u0633\u064a\u062f\u064a \u0631\u0628\u0627\u0637 \u0645\u0643\u0627\u0646 \u0645\u062b\u0627\u0644\u064a \u0644\u0644\u0628\u0642\u0627\u0621 \u0628\u062c\u0627\u0646\u0628 \u0627\u0644\u0628\u062d\u0631.<\/p>\n<\/div>\n\t\t<\/div><\/div><\/div><\/div><\/div>\n\n<div class=\"cnvs-block-justified-gallery cnvs-block-justified-gallery-1595379960254\" >\n<div\n\tclass='gallery cnvs-gallery-type-justified'\n\tdata-jg-margins=\"10\"\n\tdata-jg-border=\"-10\"\n\tdata-jg-row-height=\"258\"\n\tdata-jg-max-row-height=\"250%\"\n\tdata-jg-last-row=\"justify\"\n\tdata-jg-captions=\"true\"\n\tdata-jg-randomize=\"false\"\n>\n\t\t\t<figure class=\"gallery-item\">\n\t\t\t\t\t\t\t<a href=\"https:\/\/explore-agadirsoussmassa.com\/wp-content\/uploads\/2020\/03\/faune-pnsm4.png\">\n\t\t\t\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1160\" height=\"870\" src=\"https:\/\/explore-agadirsoussmassa.com\/wp-content\/uploads\/2020\/03\/faune-pnsm4-1160x870.png\" class=\"attachment-csco-1160 size-csco-1160\" alt=\"Promenade- Oued Massa\" srcset=\"https:\/\/explore-agadirsoussmassa.com\/wp-content\/uploads\/2020\/03\/faune-pnsm4-1160x870.png 1160w, https:\/\/explore-agadirsoussmassa.com\/wp-content\/uploads\/2020\/03\/faune-pnsm4-800x600.png 800w, https:\/\/explore-agadirsoussmassa.com\/wp-content\/uploads\/2020\/03\/faune-pnsm4-320x240.png 320w, https:\/\/explore-agadirsoussmassa.com\/wp-content\/uploads\/2020\/03\/faune-pnsm4-1536x1152.png 1536w, https:\/\/explore-agadirsoussmassa.com\/wp-content\/uploads\/2020\/03\/faune-pnsm4-300x225.png 300w, https:\/\/explore-agadirsoussmassa.com\/wp-content\/uploads\/2020\/03\/faune-pnsm4-560x420.png 560w, https:\/\/explore-agadirsoussmassa.com\/wp-content\/uploads\/2020\/03\/faune-pnsm4.png 1720w\" sizes=\"auto, (max-width: 1160px) 100vw, 1160px\" \/>\n\t\t\t\t\t\t\t<\/a>\n\t\t\t\n\t\t\t<div class=\"caption wp-caption-text gallery-caption\">\u0627\u0644\u0645\u0634\u064a &#8211; \u0648\u0627\u062f\u064a \u0645\u0627\u0633\u0629<\/div>\t\t<\/figure>\n\t\t\t\t<figure class=\"gallery-item\">\n\t\t\t\t\t\t\t<a href=\"https:\/\/explore-agadirsoussmassa.com\/wp-content\/uploads\/2020\/03\/faune-pnsm2.png\">\n\t\t\t\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1160\" height=\"869\" src=\"https:\/\/explore-agadirsoussmassa.com\/wp-content\/uploads\/2020\/03\/faune-pnsm2.png\" class=\"attachment-csco-1160 size-csco-1160\" alt=\"Promenade- Oued Massa\" srcset=\"https:\/\/explore-agadirsoussmassa.com\/wp-content\/uploads\/2020\/03\/faune-pnsm2.png 1720w, https:\/\/explore-agadirsoussmassa.com\/wp-content\/uploads\/2020\/03\/faune-pnsm2-800x599.png 800w, https:\/\/explore-agadirsoussmassa.com\/wp-content\/uploads\/2020\/03\/faune-pnsm2-1160x869.png 1160w, https:\/\/explore-agadirsoussmassa.com\/wp-content\/uploads\/2020\/03\/faune-pnsm2-320x240.png 320w, https:\/\/explore-agadirsoussmassa.com\/wp-content\/uploads\/2020\/03\/faune-pnsm2-1536x1150.png 1536w, https:\/\/explore-agadirsoussmassa.com\/wp-content\/uploads\/2020\/03\/faune-pnsm2-300x225.png 300w, https:\/\/explore-agadirsoussmassa.com\/wp-content\/uploads\/2020\/03\/faune-pnsm2-560x420.png 560w\" sizes=\"auto, (max-width: 1160px) 100vw, 1160px\" \/>\n\t\t\t\t\t\t\t<\/a>\n\t\t\t\n\t\t\t<div class=\"caption wp-caption-text gallery-caption\">\u0627\u0644\u0645\u0634\u064a &#8211; \u0648\u0627\u062f\u064a \u0645\u0627\u0633\u0629<\/div>\t\t<\/figure>\n\t\t\t\t<figure class=\"gallery-item\">\n\t\t\t\t\t\t\t<a href=\"https:\/\/explore-agadirsoussmassa.com\/wp-content\/uploads\/2020\/05\/aglou-11.png\">\n\t\t\t\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1160\" height=\"870\" src=\"https:\/\/explore-agadirsoussmassa.com\/wp-content\/uploads\/2020\/05\/aglou-11-1160x870.png\" class=\"attachment-csco-1160 size-csco-1160\" alt=\"Piste Coti\u00e8re\" srcset=\"https:\/\/explore-agadirsoussmassa.com\/wp-content\/uploads\/2020\/05\/aglou-11-1160x870.png 1160w, https:\/\/explore-agadirsoussmassa.com\/wp-content\/uploads\/2020\/05\/aglou-11-800x600.png 800w, https:\/\/explore-agadirsoussmassa.com\/wp-content\/uploads\/2020\/05\/aglou-11-320x240.png 320w, https:\/\/explore-agadirsoussmassa.com\/wp-content\/uploads\/2020\/05\/aglou-11-300x225.png 300w, https:\/\/explore-agadirsoussmassa.com\/wp-content\/uploads\/2020\/05\/aglou-11-560x420.png 560w, https:\/\/explore-agadirsoussmassa.com\/wp-content\/uploads\/2020\/05\/aglou-11.png 1360w\" sizes=\"auto, (max-width: 1160px) 100vw, 1160px\" \/>\n\t\t\t\t\t\t\t<\/a>\n\t\t\t\n\t\t\t<div class=\"caption wp-caption-text gallery-caption\">\u0627\u0644\u0645\u0646\u062d\u062f\u0631 \u0627\u0644\u0633\u0627\u062d\u0644\u064a<\/div>\t\t<\/figure>\n\t\t<\/div>\n\n<\/div>\n\n<div id=\"pl-gb34795-6a580f42289bb\"  class=\"panel-layout panel-is-rtl\" ><div id=\"pg-gb34795-6a580f42289bb-0\"  class=\"panel-grid panel-no-style\" ><div id=\"pgc-gb34795-6a580f42289bb-0-0\"  class=\"panel-grid-cell\" ><div id=\"panel-gb34795-6a580f42289bb-0-0-0\" class=\"so-panel widget widget_text panel-first-child panel-last-child\" data-index=\"0\" ><div id=\"sdrstyle\" class=\"panel-widget-style panel-widget-style-for-gb34795-6a580f42289bb-0-0-0\" >\t\t\t<div class=\"textwidget\"><p><strong>\u0635\u062d\u0631\u0627\u0621 \u0635\u063a\u064a\u0631\u0629 \u0648\u0646\u0632\u0647\u0629 \u0639\u0644\u0649 \u0636\u0641\u0627\u0641 \u0627\u0644\u0628\u062d\u064a\u0631\u0629<\/strong><\/p>\n<p>\u0643\u062b\u0628\u0627\u0646 \u0623\u0631\u0628\u0639\u0627\u0621 <a href=\"\/les-dunes-de-rasmouka-mini-sahara\/\">\u0631\u0633\u0645\u0648\u0643\u0629<\/a> (29.802597\u060c -9.551616). \u0633\u0648\u0641 \u062a\u062c\u062f\u0648\u0646 \u0628\u0636\u0639\u0629 \u0643\u064a\u0644\u0648\u0645\u062a\u0631\u0627\u062a \u0645\u0631\u0628\u0639\u0629 \u0645\u0646 \u0627\u0644\u0631\u0645\u0627\u0644 \u0627\u0644\u0646\u0627\u0639\u0645\u0629 \u0647\u0646\u0627\u0643\u060c \u0648\u062a\u0634\u0639\u0631\u0648\u0646 \u0628\u0623\u0646\u0643\u0645 \u0648\u0633\u0637 \u0635\u062d\u0631\u0627\u0621 \u0635\u063a\u064a\u0631\u0629. \u0625\u0646\u0647 \u0645\u0643\u0627\u0646 \u0645\u062b\u0627\u0644\u064a \u0644\u0644\u0623\u0637\u0641\u0627\u0644\u060c \u062d\u064a\u062b \u064a\u0633\u062a\u0637\u064a\u0639\u0648\u0646 \u0627\u0644\u062c\u0631\u064a \u0648\u0627\u0644\u0631\u0643\u0636 \u0639\u0644\u0649 \u0627\u0644\u0643\u062b\u0628\u0627\u0646 \u0627\u0644\u0631\u0645\u0644\u064a\u0629 \u0627\u0644\u0643\u0628\u064a\u0631\u0629. \u0633\u062f \u064a\u0648\u0633\u0641 \u0628\u0646 \u062a\u0627\u0634\u0641\u064a\u0646 (29.846477 \u060c -9.494424) \u0628\u062d\u064a\u0631\u0629 \u062a\u0642\u0639 \u0639\u0644\u0649 \u0628\u0639\u062f \u0639\u0634\u0631\u064a\u0646 \u062f\u0642\u064a\u0642\u0629 \u0645\u0646 \u0645\u062f\u064a\u0646\u0629 \u062a\u0632\u0646\u064a\u062a. \u0625\u0646\u0647 \u0627\u0644\u0645\u0643\u0627\u0646 \u0627\u0644\u0645\u062b\u0627\u0644\u064a \u0644\u0642\u0636\u0627\u0621 \u064a\u0648\u0645 \u0646\u0632\u0647\u0629 \u0644\u0637\u064a\u0641 \u0645\u0639 \u0627\u0644\u0639\u0627\u0626\u0644\u0629. \u0647\u0646\u0627\u0643 \u0625\u0645\u0643\u0627\u0646\u064a\u0629 <a href=\"\/peche-sportive-dans-le-souss-massa\/\">\u0644\u0644\u0635\u064a\u062f \u0647\u0646\u0627\u0643<\/a> .<\/p>\n<\/div>\n\t\t<\/div><\/div><\/div><\/div><\/div>\n\n<div class=\"cnvs-block-justified-gallery cnvs-block-justified-gallery-1595380198218\" >\n<div\n\tclass='gallery cnvs-gallery-type-justified'\n\tdata-jg-margins=\"10\"\n\tdata-jg-border=\"-10\"\n\tdata-jg-row-height=\"258\"\n\tdata-jg-max-row-height=\"250%\"\n\tdata-jg-last-row=\"justify\"\n\tdata-jg-captions=\"true\"\n\tdata-jg-randomize=\"false\"\n>\n\t\t\t<figure class=\"gallery-item\">\n\t\t\t\t\t\t\t<a href=\"https:\/\/explore-agadirsoussmassa.com\/wp-content\/uploads\/2020\/04\/barrage-ybt-3.png\">\n\t\t\t\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1160\" height=\"870\" src=\"https:\/\/explore-agadirsoussmassa.com\/wp-content\/uploads\/2020\/04\/barrage-ybt-3.png\" class=\"attachment-csco-1160 size-csco-1160\" alt=\"Lac de barrage Youssef Ben Tachfine\" srcset=\"https:\/\/explore-agadirsoussmassa.com\/wp-content\/uploads\/2020\/04\/barrage-ybt-3.png 1680w, https:\/\/explore-agadirsoussmassa.com\/wp-content\/uploads\/2020\/04\/barrage-ybt-3-800x600.png 800w, https:\/\/explore-agadirsoussmassa.com\/wp-content\/uploads\/2020\/04\/barrage-ybt-3-1160x870.png 1160w, https:\/\/explore-agadirsoussmassa.com\/wp-content\/uploads\/2020\/04\/barrage-ybt-3-320x240.png 320w, https:\/\/explore-agadirsoussmassa.com\/wp-content\/uploads\/2020\/04\/barrage-ybt-3-1536x1152.png 1536w, https:\/\/explore-agadirsoussmassa.com\/wp-content\/uploads\/2020\/04\/barrage-ybt-3-300x225.png 300w, https:\/\/explore-agadirsoussmassa.com\/wp-content\/uploads\/2020\/04\/barrage-ybt-3-560x420.png 560w\" sizes=\"auto, (max-width: 1160px) 100vw, 1160px\" \/>\n\t\t\t\t\t\t\t<\/a>\n\t\t\t\n\t\t\t<div class=\"caption wp-caption-text gallery-caption\">\u0628\u062d\u064a\u0631\u0629 \u0633\u062f \u064a\u0648\u0633\u0641 \u0628\u0646 \u062a\u0627\u0634\u0641\u064a\u0646<\/div>\t\t<\/figure>\n\t\t\t\t<figure class=\"gallery-item\">\n\t\t\t\t\t\t\t<a href=\"https:\/\/explore-agadirsoussmassa.com\/wp-content\/uploads\/2020\/02\/arbaa-rasmouka2.png\">\n\t\t\t\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1160\" height=\"870\" src=\"https:\/\/explore-agadirsoussmassa.com\/wp-content\/uploads\/2020\/02\/arbaa-rasmouka2.png\" class=\"attachment-csco-1160 size-csco-1160\" alt=\"Dunes d&#039;Arbaa Rasmouka\" \/>\n\t\t\t\t\t\t\t<\/a>\n\t\t\t\n\t\t\t<div class=\"caption wp-caption-text gallery-caption\">\u0643\u062b\u0628\u0627\u0646 \u0623\u0631\u0628\u0639\u0627\u0621 \u0631\u0633\u0645\u0648\u0643\u0629<\/div>\t\t<\/figure>\n\t\t<\/div>\n\n<\/div>\n\n<div id=\"pl-gb34795-6a580f422a0f1\"  class=\"panel-layout panel-is-rtl\" ><div id=\"pg-gb34795-6a580f422a0f1-0\"  class=\"panel-grid panel-no-style\" ><div id=\"pgc-gb34795-6a580f422a0f1-0-0\"  class=\"panel-grid-cell\" ><div id=\"panel-gb34795-6a580f422a0f1-0-0-0\" class=\"so-panel widget widget_text panel-first-child panel-last-child\" data-index=\"0\" >\t\t\t<div class=\"textwidget\"><p>\u00a0<\/p>\n<p>\u00a0<\/p>\n<\/div>\n\t\t<\/div><\/div><\/div><\/div>","protected":false},"excerpt":{"rendered":"<div class=\"post-excerpt\">\u0645\u0642\u062a\u0631\u062d\u0627\u062a \u0646\u0632\u0647\u0627\u062a\/\u0623\u0646\u0634\u0637\u0629 \u062d\u0648\u0644 \u062a\u0632\u0646\u064a\u062a\u061f \u0634\u0627\u0637\u0626 \u0645\u0647\u062c\u0648\u0631 \u0623\u0645 \u0635\u062d\u0631\u0627\u0621 \u0635\u063a\u064a\u0629\u061f \u0627\u0644\u0645\u0646\u062a\u0632\u0647 \u0627\u0644\u0648\u0637\u0646\u064a\u061f \u0646\u0632\u0647\u0629 \u0641\u064a \u0627\u0644\u0628\u062d\u064a\u0631\u0629 \u0623\u0648 \u0627\u0644\u0645\u0633\u0627\u0631 \u0627\u0644\u0633\u0627\u062d\u0644\u064a \u0639\u0644\u0649 \u0645\u062a\u0646 \u0627\u0644\u0633\u064a\u0627\u0631\u0627\u062a \u0627\u0644\u0631\u0628\u0627\u0639\u064a\u0629 \u0627\u0644\u062f\u0641\u0639\u061f<\/div>\n<div class=\"post-more\"><a href=\"https:\/\/explore-agadirsoussmassa.com\/ar\/%d9%86%d8%b2%d9%87%d8%a7%d8%aa-%d8%b9%d8%a7%d8%a6%d9%84%d9%8a%d8%a9-%d8%ad%d9%88%d9%84-%d8%aa%d8%b2%d9%86%d9%8a%d8%aa\/\" class=\"button button-primary button-effect\"><span>\u0627\u0646\u0638\u0631 \u0627\u0644\u062a\u0641\u0627\u0635\u064a\u0644<\/span><span><i class=\"cs-icon cs-icon-arrow-right\"><\/i><\/span><\/a><\/div>\n","protected":false},"author":1,"featured_media":29511,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[477,449,478],"tags":[325],"powerkit_post_featured":[],"class_list":{"0":"post-34795","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-477","8":"category-449","9":"category-478","10":"tag-tiznit-ar"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.0 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>\u0646\u0632\u0647\u0627\u062a \u0639\u0627\u0626\u0644\u064a\u0629 \u062d\u0648\u0644 \u062a\u0632\u0646\u064a\u062a - Explore Agadir Souss Massa<\/title>\n<meta name=\"description\" content=\"\u0645\u0642\u062a\u0631\u062d\u0627\u062a \u0646\u0632\u0647\u0627\u062a\/\u0623\u0646\u0634\u0637\u0629 \u062d\u0648\u0644 \u062a\u0632\u0646\u064a\u062a\u061f \u0634\u0627\u0637\u0626 \u0645\u0647\u062c\u0648\u0631 \u0623\u0645 \u0635\u062d\u0631\u0627\u0621 \u0635\u063a\u064a\u0629\u061f \u0627\u0644\u0645\u0646\u062a\u0632\u0647 \u0627\u0644\u0648\u0637\u0646\u064a\u061f \u0646\u0632\u0647\u0629 \u0641\u064a \u0627\u0644\u0628\u062d\u064a\u0631\u0629 \u0623\u0648 \u0627\u0644\u0645\u0633\u0627\u0631 \u0627\u0644\u0633\u0627\u062d\u0644\u064a \u0639\u0644\u0649 \u0645\u062a\u0646 \u0627\u0644\u0633\u064a\u0627\u0631\u0627\u062a \u0627\u0644\u0631\u0628\u0627\u0639\u064a\u0629 \u0627\u0644\u062f\u0641\u0639\u061f\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/explore-agadirsoussmassa.com\/ar\/%d9%86%d8%b2%d9%87%d8%a7%d8%aa-%d8%b9%d8%a7%d8%a6%d9%84%d9%8a%d8%a9-%d8%ad%d9%88%d9%84-%d8%aa%d8%b2%d9%86%d9%8a%d8%aa\/\" \/>\n<meta property=\"og:locale\" content=\"ar_AR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u0646\u0632\u0647\u0627\u062a \u0639\u0627\u0626\u0644\u064a\u0629 \u062d\u0648\u0644 \u062a\u0632\u0646\u064a\u062a - Explore Agadir Souss Massa\" \/>\n<meta property=\"og:description\" content=\"\u0645\u0642\u062a\u0631\u062d\u0627\u062a \u0646\u0632\u0647\u0627\u062a\/\u0623\u0646\u0634\u0637\u0629 \u062d\u0648\u0644 \u062a\u0632\u0646\u064a\u062a\u061f \u0634\u0627\u0637\u0626 \u0645\u0647\u062c\u0648\u0631 \u0623\u0645 \u0635\u062d\u0631\u0627\u0621 \u0635\u063a\u064a\u0629\u061f \u0627\u0644\u0645\u0646\u062a\u0632\u0647 \u0627\u0644\u0648\u0637\u0646\u064a\u061f \u0646\u0632\u0647\u0629 \u0641\u064a \u0627\u0644\u0628\u062d\u064a\u0631\u0629 \u0623\u0648 \u0627\u0644\u0645\u0633\u0627\u0631 \u0627\u0644\u0633\u0627\u062d\u0644\u064a \u0639\u0644\u0649 \u0645\u062a\u0646 \u0627\u0644\u0633\u064a\u0627\u0631\u0627\u062a \u0627\u0644\u0631\u0628\u0627\u0639\u064a\u0629 \u0627\u0644\u062f\u0641\u0639\u061f\" \/>\n<meta property=\"og:url\" content=\"https:\/\/explore-agadirsoussmassa.com\/ar\/%d9%86%d8%b2%d9%87%d8%a7%d8%aa-%d8%b9%d8%a7%d8%a6%d9%84%d9%8a%d8%a9-%d8%ad%d9%88%d9%84-%d8%aa%d8%b2%d9%86%d9%8a%d8%aa\/\" \/>\n<meta property=\"og:site_name\" content=\"Explore Agadir Souss Massa\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Explore-Souss-Massa-111659480353930\" \/>\n<meta property=\"article:published_time\" content=\"2020-04-21T14:20:02+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-02-19T10:03:04+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/explore-agadirsoussmassa.com\/wp-content\/uploads\/2020\/04\/Capture-d\u2019e\u0301cran-2020-06-18-a\u0300-12.23.27-min.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1204\" \/>\n\t<meta property=\"og:image:height\" content=\"660\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"soussmassa\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u0643\u064f\u062a\u0628 \u0628\u0648\u0627\u0633\u0637\u0629\" \/>\n\t<meta name=\"twitter:data1\" content=\"soussmassa\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/explore-agadirsoussmassa.com\/ar\/%d9%86%d8%b2%d9%87%d8%a7%d8%aa-%d8%b9%d8%a7%d8%a6%d9%84%d9%8a%d8%a9-%d8%ad%d9%88%d9%84-%d8%aa%d8%b2%d9%86%d9%8a%d8%aa\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/explore-agadirsoussmassa.com\/ar\/%d9%86%d8%b2%d9%87%d8%a7%d8%aa-%d8%b9%d8%a7%d8%a6%d9%84%d9%8a%d8%a9-%d8%ad%d9%88%d9%84-%d8%aa%d8%b2%d9%86%d9%8a%d8%aa\/\"},\"author\":{\"name\":\"soussmassa\",\"@id\":\"https:\/\/explore-agadirsoussmassa.com\/ar\/#\/schema\/person\/c019e4bcfef76d1c57d426107449d03e\"},\"headline\":\"\u0646\u0632\u0647\u0627\u062a \u0639\u0627\u0626\u0644\u064a\u0629 \u062d\u0648\u0644 \u062a\u0632\u0646\u064a\u062a\",\"datePublished\":\"2020-04-21T14:20:02+00:00\",\"dateModified\":\"2021-02-19T10:03:04+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/explore-agadirsoussmassa.com\/ar\/%d9%86%d8%b2%d9%87%d8%a7%d8%aa-%d8%b9%d8%a7%d8%a6%d9%84%d9%8a%d8%a9-%d8%ad%d9%88%d9%84-%d8%aa%d8%b2%d9%86%d9%8a%d8%aa\/\"},\"wordCount\":0,\"publisher\":{\"@id\":\"https:\/\/explore-agadirsoussmassa.com\/ar\/#organization\"},\"image\":{\"@id\":\"https:\/\/explore-agadirsoussmassa.com\/ar\/%d9%86%d8%b2%d9%87%d8%a7%d8%aa-%d8%b9%d8%a7%d8%a6%d9%84%d9%8a%d8%a9-%d8%ad%d9%88%d9%84-%d8%aa%d8%b2%d9%86%d9%8a%d8%aa\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/explore-agadirsoussmassa.com\/wp-content\/uploads\/2020\/04\/Capture-d\u2019e\u0301cran-2020-06-18-a\u0300-12.23.27-min.png\",\"keywords\":[\"tiznit\"],\"articleSection\":[\"\u062a\u0632\u0646\u064a\u062a\",\"\u0645\u0627 \u064a\u062c\u0628 \u0645\u0634\u0627\u0647\u062f\u062a\u0647\",\"\u0645\u062f\u0646\"],\"inLanguage\":\"ar\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/explore-agadirsoussmassa.com\/ar\/%d9%86%d8%b2%d9%87%d8%a7%d8%aa-%d8%b9%d8%a7%d8%a6%d9%84%d9%8a%d8%a9-%d8%ad%d9%88%d9%84-%d8%aa%d8%b2%d9%86%d9%8a%d8%aa\/\",\"url\":\"https:\/\/explore-agadirsoussmassa.com\/ar\/%d9%86%d8%b2%d9%87%d8%a7%d8%aa-%d8%b9%d8%a7%d8%a6%d9%84%d9%8a%d8%a9-%d8%ad%d9%88%d9%84-%d8%aa%d8%b2%d9%86%d9%8a%d8%aa\/\",\"name\":\"\u0646\u0632\u0647\u0627\u062a \u0639\u0627\u0626\u0644\u064a\u0629 \u062d\u0648\u0644 \u062a\u0632\u0646\u064a\u062a - Explore Agadir Souss Massa\",\"isPartOf\":{\"@id\":\"https:\/\/explore-agadirsoussmassa.com\/ar\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/explore-agadirsoussmassa.com\/ar\/%d9%86%d8%b2%d9%87%d8%a7%d8%aa-%d8%b9%d8%a7%d8%a6%d9%84%d9%8a%d8%a9-%d8%ad%d9%88%d9%84-%d8%aa%d8%b2%d9%86%d9%8a%d8%aa\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/explore-agadirsoussmassa.com\/ar\/%d9%86%d8%b2%d9%87%d8%a7%d8%aa-%d8%b9%d8%a7%d8%a6%d9%84%d9%8a%d8%a9-%d8%ad%d9%88%d9%84-%d8%aa%d8%b2%d9%86%d9%8a%d8%aa\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/explore-agadirsoussmassa.com\/wp-content\/uploads\/2020\/04\/Capture-d\u2019e\u0301cran-2020-06-18-a\u0300-12.23.27-min.png\",\"datePublished\":\"2020-04-21T14:20:02+00:00\",\"dateModified\":\"2021-02-19T10:03:04+00:00\",\"description\":\"\u0645\u0642\u062a\u0631\u062d\u0627\u062a \u0646\u0632\u0647\u0627\u062a\/\u0623\u0646\u0634\u0637\u0629 \u062d\u0648\u0644 \u062a\u0632\u0646\u064a\u062a\u061f \u0634\u0627\u0637\u0626 \u0645\u0647\u062c\u0648\u0631 \u0623\u0645 \u0635\u062d\u0631\u0627\u0621 \u0635\u063a\u064a\u0629\u061f \u0627\u0644\u0645\u0646\u062a\u0632\u0647 \u0627\u0644\u0648\u0637\u0646\u064a\u061f \u0646\u0632\u0647\u0629 \u0641\u064a \u0627\u0644\u0628\u062d\u064a\u0631\u0629 \u0623\u0648 \u0627\u0644\u0645\u0633\u0627\u0631 \u0627\u0644\u0633\u0627\u062d\u0644\u064a \u0639\u0644\u0649 \u0645\u062a\u0646 \u0627\u0644\u0633\u064a\u0627\u0631\u0627\u062a \u0627\u0644\u0631\u0628\u0627\u0639\u064a\u0629 \u0627\u0644\u062f\u0641\u0639\u061f\",\"breadcrumb\":{\"@id\":\"https:\/\/explore-agadirsoussmassa.com\/ar\/%d9%86%d8%b2%d9%87%d8%a7%d8%aa-%d8%b9%d8%a7%d8%a6%d9%84%d9%8a%d8%a9-%d8%ad%d9%88%d9%84-%d8%aa%d8%b2%d9%86%d9%8a%d8%aa\/#breadcrumb\"},\"inLanguage\":\"ar\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/explore-agadirsoussmassa.com\/ar\/%d9%86%d8%b2%d9%87%d8%a7%d8%aa-%d8%b9%d8%a7%d8%a6%d9%84%d9%8a%d8%a9-%d8%ad%d9%88%d9%84-%d8%aa%d8%b2%d9%86%d9%8a%d8%aa\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"ar\",\"@id\":\"https:\/\/explore-agadirsoussmassa.com\/ar\/%d9%86%d8%b2%d9%87%d8%a7%d8%aa-%d8%b9%d8%a7%d8%a6%d9%84%d9%8a%d8%a9-%d8%ad%d9%88%d9%84-%d8%aa%d8%b2%d9%86%d9%8a%d8%aa\/#primaryimage\",\"url\":\"https:\/\/explore-agadirsoussmassa.com\/wp-content\/uploads\/2020\/04\/Capture-d\u2019e\u0301cran-2020-06-18-a\u0300-12.23.27-min.png\",\"contentUrl\":\"https:\/\/explore-agadirsoussmassa.com\/wp-content\/uploads\/2020\/04\/Capture-d\u2019e\u0301cran-2020-06-18-a\u0300-12.23.27-min.png\",\"width\":1204,\"height\":660},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/explore-agadirsoussmassa.com\/ar\/%d9%86%d8%b2%d9%87%d8%a7%d8%aa-%d8%b9%d8%a7%d8%a6%d9%84%d9%8a%d8%a9-%d8%ad%d9%88%d9%84-%d8%aa%d8%b2%d9%86%d9%8a%d8%aa\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/explore-agadirsoussmassa.com\/ar\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u0646\u0632\u0647\u0627\u062a \u0639\u0627\u0626\u0644\u064a\u0629 \u062d\u0648\u0644 \u062a\u0632\u0646\u064a\u062a\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/explore-agadirsoussmassa.com\/ar\/#website\",\"url\":\"https:\/\/explore-agadirsoussmassa.com\/ar\/\",\"name\":\"Explore Agadir Souss Massa\",\"description\":\"R\u00e9gion Souss Massa\",\"publisher\":{\"@id\":\"https:\/\/explore-agadirsoussmassa.com\/ar\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/explore-agadirsoussmassa.com\/ar\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ar\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/explore-agadirsoussmassa.com\/ar\/#organization\",\"name\":\"SDR Tourisme Souss Massa\",\"url\":\"https:\/\/explore-agadirsoussmassa.com\/ar\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ar\",\"@id\":\"https:\/\/explore-agadirsoussmassa.com\/ar\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/zt88dgbrixj.preview.infomaniak.website\/wp-content\/uploads\/2020\/08\/logo-sdr.png\",\"contentUrl\":\"https:\/\/zt88dgbrixj.preview.infomaniak.website\/wp-content\/uploads\/2020\/08\/logo-sdr.png\",\"width\":404,\"height\":286,\"caption\":\"SDR Tourisme Souss Massa\"},\"image\":{\"@id\":\"https:\/\/explore-agadirsoussmassa.com\/ar\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/Explore-Souss-Massa-111659480353930\",\"https:\/\/www.instagram.com\/exploresoussmassamorocco\/\",\"https:\/\/www.youtube.com\/channel\/UCpSGZAsRRpG40CeT3UcIcOA\/videos\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/explore-agadirsoussmassa.com\/ar\/#\/schema\/person\/c019e4bcfef76d1c57d426107449d03e\",\"name\":\"soussmassa\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ar\",\"@id\":\"https:\/\/explore-agadirsoussmassa.com\/ar\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/71a3f2c422286f264199c19844c327bfdf2a272a6aab356511f8970061b8dc04?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/71a3f2c422286f264199c19844c327bfdf2a272a6aab356511f8970061b8dc04?s=96&d=mm&r=g\",\"caption\":\"soussmassa\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u0646\u0632\u0647\u0627\u062a \u0639\u0627\u0626\u0644\u064a\u0629 \u062d\u0648\u0644 \u062a\u0632\u0646\u064a\u062a - Explore Agadir Souss Massa","description":"\u0645\u0642\u062a\u0631\u062d\u0627\u062a \u0646\u0632\u0647\u0627\u062a\/\u0623\u0646\u0634\u0637\u0629 \u062d\u0648\u0644 \u062a\u0632\u0646\u064a\u062a\u061f \u0634\u0627\u0637\u0626 \u0645\u0647\u062c\u0648\u0631 \u0623\u0645 \u0635\u062d\u0631\u0627\u0621 \u0635\u063a\u064a\u0629\u061f \u0627\u0644\u0645\u0646\u062a\u0632\u0647 \u0627\u0644\u0648\u0637\u0646\u064a\u061f \u0646\u0632\u0647\u0629 \u0641\u064a \u0627\u0644\u0628\u062d\u064a\u0631\u0629 \u0623\u0648 \u0627\u0644\u0645\u0633\u0627\u0631 \u0627\u0644\u0633\u0627\u062d\u0644\u064a \u0639\u0644\u0649 \u0645\u062a\u0646 \u0627\u0644\u0633\u064a\u0627\u0631\u0627\u062a \u0627\u0644\u0631\u0628\u0627\u0639\u064a\u0629 \u0627\u0644\u062f\u0641\u0639\u061f","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/explore-agadirsoussmassa.com\/ar\/%d9%86%d8%b2%d9%87%d8%a7%d8%aa-%d8%b9%d8%a7%d8%a6%d9%84%d9%8a%d8%a9-%d8%ad%d9%88%d9%84-%d8%aa%d8%b2%d9%86%d9%8a%d8%aa\/","og_locale":"ar_AR","og_type":"article","og_title":"\u0646\u0632\u0647\u0627\u062a \u0639\u0627\u0626\u0644\u064a\u0629 \u062d\u0648\u0644 \u062a\u0632\u0646\u064a\u062a - Explore Agadir Souss Massa","og_description":"\u0645\u0642\u062a\u0631\u062d\u0627\u062a \u0646\u0632\u0647\u0627\u062a\/\u0623\u0646\u0634\u0637\u0629 \u062d\u0648\u0644 \u062a\u0632\u0646\u064a\u062a\u061f \u0634\u0627\u0637\u0626 \u0645\u0647\u062c\u0648\u0631 \u0623\u0645 \u0635\u062d\u0631\u0627\u0621 \u0635\u063a\u064a\u0629\u061f \u0627\u0644\u0645\u0646\u062a\u0632\u0647 \u0627\u0644\u0648\u0637\u0646\u064a\u061f \u0646\u0632\u0647\u0629 \u0641\u064a \u0627\u0644\u0628\u062d\u064a\u0631\u0629 \u0623\u0648 \u0627\u0644\u0645\u0633\u0627\u0631 \u0627\u0644\u0633\u0627\u062d\u0644\u064a \u0639\u0644\u0649 \u0645\u062a\u0646 \u0627\u0644\u0633\u064a\u0627\u0631\u0627\u062a \u0627\u0644\u0631\u0628\u0627\u0639\u064a\u0629 \u0627\u0644\u062f\u0641\u0639\u061f","og_url":"https:\/\/explore-agadirsoussmassa.com\/ar\/%d9%86%d8%b2%d9%87%d8%a7%d8%aa-%d8%b9%d8%a7%d8%a6%d9%84%d9%8a%d8%a9-%d8%ad%d9%88%d9%84-%d8%aa%d8%b2%d9%86%d9%8a%d8%aa\/","og_site_name":"Explore Agadir Souss Massa","article_publisher":"https:\/\/www.facebook.com\/Explore-Souss-Massa-111659480353930","article_published_time":"2020-04-21T14:20:02+00:00","article_modified_time":"2021-02-19T10:03:04+00:00","og_image":[{"width":1204,"height":660,"url":"https:\/\/explore-agadirsoussmassa.com\/wp-content\/uploads\/2020\/04\/Capture-d\u2019e\u0301cran-2020-06-18-a\u0300-12.23.27-min.png","type":"image\/png"}],"author":"soussmassa","twitter_card":"summary_large_image","twitter_misc":{"\u0643\u064f\u062a\u0628 \u0628\u0648\u0627\u0633\u0637\u0629":"soussmassa"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/explore-agadirsoussmassa.com\/ar\/%d9%86%d8%b2%d9%87%d8%a7%d8%aa-%d8%b9%d8%a7%d8%a6%d9%84%d9%8a%d8%a9-%d8%ad%d9%88%d9%84-%d8%aa%d8%b2%d9%86%d9%8a%d8%aa\/#article","isPartOf":{"@id":"https:\/\/explore-agadirsoussmassa.com\/ar\/%d9%86%d8%b2%d9%87%d8%a7%d8%aa-%d8%b9%d8%a7%d8%a6%d9%84%d9%8a%d8%a9-%d8%ad%d9%88%d9%84-%d8%aa%d8%b2%d9%86%d9%8a%d8%aa\/"},"author":{"name":"soussmassa","@id":"https:\/\/explore-agadirsoussmassa.com\/ar\/#\/schema\/person\/c019e4bcfef76d1c57d426107449d03e"},"headline":"\u0646\u0632\u0647\u0627\u062a \u0639\u0627\u0626\u0644\u064a\u0629 \u062d\u0648\u0644 \u062a\u0632\u0646\u064a\u062a","datePublished":"2020-04-21T14:20:02+00:00","dateModified":"2021-02-19T10:03:04+00:00","mainEntityOfPage":{"@id":"https:\/\/explore-agadirsoussmassa.com\/ar\/%d9%86%d8%b2%d9%87%d8%a7%d8%aa-%d8%b9%d8%a7%d8%a6%d9%84%d9%8a%d8%a9-%d8%ad%d9%88%d9%84-%d8%aa%d8%b2%d9%86%d9%8a%d8%aa\/"},"wordCount":0,"publisher":{"@id":"https:\/\/explore-agadirsoussmassa.com\/ar\/#organization"},"image":{"@id":"https:\/\/explore-agadirsoussmassa.com\/ar\/%d9%86%d8%b2%d9%87%d8%a7%d8%aa-%d8%b9%d8%a7%d8%a6%d9%84%d9%8a%d8%a9-%d8%ad%d9%88%d9%84-%d8%aa%d8%b2%d9%86%d9%8a%d8%aa\/#primaryimage"},"thumbnailUrl":"https:\/\/explore-agadirsoussmassa.com\/wp-content\/uploads\/2020\/04\/Capture-d\u2019e\u0301cran-2020-06-18-a\u0300-12.23.27-min.png","keywords":["tiznit"],"articleSection":["\u062a\u0632\u0646\u064a\u062a","\u0645\u0627 \u064a\u062c\u0628 \u0645\u0634\u0627\u0647\u062f\u062a\u0647","\u0645\u062f\u0646"],"inLanguage":"ar"},{"@type":"WebPage","@id":"https:\/\/explore-agadirsoussmassa.com\/ar\/%d9%86%d8%b2%d9%87%d8%a7%d8%aa-%d8%b9%d8%a7%d8%a6%d9%84%d9%8a%d8%a9-%d8%ad%d9%88%d9%84-%d8%aa%d8%b2%d9%86%d9%8a%d8%aa\/","url":"https:\/\/explore-agadirsoussmassa.com\/ar\/%d9%86%d8%b2%d9%87%d8%a7%d8%aa-%d8%b9%d8%a7%d8%a6%d9%84%d9%8a%d8%a9-%d8%ad%d9%88%d9%84-%d8%aa%d8%b2%d9%86%d9%8a%d8%aa\/","name":"\u0646\u0632\u0647\u0627\u062a \u0639\u0627\u0626\u0644\u064a\u0629 \u062d\u0648\u0644 \u062a\u0632\u0646\u064a\u062a - Explore Agadir Souss Massa","isPartOf":{"@id":"https:\/\/explore-agadirsoussmassa.com\/ar\/#website"},"primaryImageOfPage":{"@id":"https:\/\/explore-agadirsoussmassa.com\/ar\/%d9%86%d8%b2%d9%87%d8%a7%d8%aa-%d8%b9%d8%a7%d8%a6%d9%84%d9%8a%d8%a9-%d8%ad%d9%88%d9%84-%d8%aa%d8%b2%d9%86%d9%8a%d8%aa\/#primaryimage"},"image":{"@id":"https:\/\/explore-agadirsoussmassa.com\/ar\/%d9%86%d8%b2%d9%87%d8%a7%d8%aa-%d8%b9%d8%a7%d8%a6%d9%84%d9%8a%d8%a9-%d8%ad%d9%88%d9%84-%d8%aa%d8%b2%d9%86%d9%8a%d8%aa\/#primaryimage"},"thumbnailUrl":"https:\/\/explore-agadirsoussmassa.com\/wp-content\/uploads\/2020\/04\/Capture-d\u2019e\u0301cran-2020-06-18-a\u0300-12.23.27-min.png","datePublished":"2020-04-21T14:20:02+00:00","dateModified":"2021-02-19T10:03:04+00:00","description":"\u0645\u0642\u062a\u0631\u062d\u0627\u062a \u0646\u0632\u0647\u0627\u062a\/\u0623\u0646\u0634\u0637\u0629 \u062d\u0648\u0644 \u062a\u0632\u0646\u064a\u062a\u061f \u0634\u0627\u0637\u0626 \u0645\u0647\u062c\u0648\u0631 \u0623\u0645 \u0635\u062d\u0631\u0627\u0621 \u0635\u063a\u064a\u0629\u061f \u0627\u0644\u0645\u0646\u062a\u0632\u0647 \u0627\u0644\u0648\u0637\u0646\u064a\u061f \u0646\u0632\u0647\u0629 \u0641\u064a \u0627\u0644\u0628\u062d\u064a\u0631\u0629 \u0623\u0648 \u0627\u0644\u0645\u0633\u0627\u0631 \u0627\u0644\u0633\u0627\u062d\u0644\u064a \u0639\u0644\u0649 \u0645\u062a\u0646 \u0627\u0644\u0633\u064a\u0627\u0631\u0627\u062a \u0627\u0644\u0631\u0628\u0627\u0639\u064a\u0629 \u0627\u0644\u062f\u0641\u0639\u061f","breadcrumb":{"@id":"https:\/\/explore-agadirsoussmassa.com\/ar\/%d9%86%d8%b2%d9%87%d8%a7%d8%aa-%d8%b9%d8%a7%d8%a6%d9%84%d9%8a%d8%a9-%d8%ad%d9%88%d9%84-%d8%aa%d8%b2%d9%86%d9%8a%d8%aa\/#breadcrumb"},"inLanguage":"ar","potentialAction":[{"@type":"ReadAction","target":["https:\/\/explore-agadirsoussmassa.com\/ar\/%d9%86%d8%b2%d9%87%d8%a7%d8%aa-%d8%b9%d8%a7%d8%a6%d9%84%d9%8a%d8%a9-%d8%ad%d9%88%d9%84-%d8%aa%d8%b2%d9%86%d9%8a%d8%aa\/"]}]},{"@type":"ImageObject","inLanguage":"ar","@id":"https:\/\/explore-agadirsoussmassa.com\/ar\/%d9%86%d8%b2%d9%87%d8%a7%d8%aa-%d8%b9%d8%a7%d8%a6%d9%84%d9%8a%d8%a9-%d8%ad%d9%88%d9%84-%d8%aa%d8%b2%d9%86%d9%8a%d8%aa\/#primaryimage","url":"https:\/\/explore-agadirsoussmassa.com\/wp-content\/uploads\/2020\/04\/Capture-d\u2019e\u0301cran-2020-06-18-a\u0300-12.23.27-min.png","contentUrl":"https:\/\/explore-agadirsoussmassa.com\/wp-content\/uploads\/2020\/04\/Capture-d\u2019e\u0301cran-2020-06-18-a\u0300-12.23.27-min.png","width":1204,"height":660},{"@type":"BreadcrumbList","@id":"https:\/\/explore-agadirsoussmassa.com\/ar\/%d9%86%d8%b2%d9%87%d8%a7%d8%aa-%d8%b9%d8%a7%d8%a6%d9%84%d9%8a%d8%a9-%d8%ad%d9%88%d9%84-%d8%aa%d8%b2%d9%86%d9%8a%d8%aa\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/explore-agadirsoussmassa.com\/ar\/"},{"@type":"ListItem","position":2,"name":"\u0646\u0632\u0647\u0627\u062a \u0639\u0627\u0626\u0644\u064a\u0629 \u062d\u0648\u0644 \u062a\u0632\u0646\u064a\u062a"}]},{"@type":"WebSite","@id":"https:\/\/explore-agadirsoussmassa.com\/ar\/#website","url":"https:\/\/explore-agadirsoussmassa.com\/ar\/","name":"Explore Agadir Souss Massa","description":"R\u00e9gion Souss Massa","publisher":{"@id":"https:\/\/explore-agadirsoussmassa.com\/ar\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/explore-agadirsoussmassa.com\/ar\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ar"},{"@type":"Organization","@id":"https:\/\/explore-agadirsoussmassa.com\/ar\/#organization","name":"SDR Tourisme Souss Massa","url":"https:\/\/explore-agadirsoussmassa.com\/ar\/","logo":{"@type":"ImageObject","inLanguage":"ar","@id":"https:\/\/explore-agadirsoussmassa.com\/ar\/#\/schema\/logo\/image\/","url":"https:\/\/zt88dgbrixj.preview.infomaniak.website\/wp-content\/uploads\/2020\/08\/logo-sdr.png","contentUrl":"https:\/\/zt88dgbrixj.preview.infomaniak.website\/wp-content\/uploads\/2020\/08\/logo-sdr.png","width":404,"height":286,"caption":"SDR Tourisme Souss Massa"},"image":{"@id":"https:\/\/explore-agadirsoussmassa.com\/ar\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Explore-Souss-Massa-111659480353930","https:\/\/www.instagram.com\/exploresoussmassamorocco\/","https:\/\/www.youtube.com\/channel\/UCpSGZAsRRpG40CeT3UcIcOA\/videos"]},{"@type":"Person","@id":"https:\/\/explore-agadirsoussmassa.com\/ar\/#\/schema\/person\/c019e4bcfef76d1c57d426107449d03e","name":"soussmassa","image":{"@type":"ImageObject","inLanguage":"ar","@id":"https:\/\/explore-agadirsoussmassa.com\/ar\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/71a3f2c422286f264199c19844c327bfdf2a272a6aab356511f8970061b8dc04?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/71a3f2c422286f264199c19844c327bfdf2a272a6aab356511f8970061b8dc04?s=96&d=mm&r=g","caption":"soussmassa"}}]}},"_links":{"self":[{"href":"https:\/\/explore-agadirsoussmassa.com\/ar\/wp-json\/wp\/v2\/posts\/34795","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/explore-agadirsoussmassa.com\/ar\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/explore-agadirsoussmassa.com\/ar\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/explore-agadirsoussmassa.com\/ar\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/explore-agadirsoussmassa.com\/ar\/wp-json\/wp\/v2\/comments?post=34795"}],"version-history":[{"count":10,"href":"https:\/\/explore-agadirsoussmassa.com\/ar\/wp-json\/wp\/v2\/posts\/34795\/revisions"}],"predecessor-version":[{"id":43821,"href":"https:\/\/explore-agadirsoussmassa.com\/ar\/wp-json\/wp\/v2\/posts\/34795\/revisions\/43821"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/explore-agadirsoussmassa.com\/ar\/wp-json\/wp\/v2\/media\/29511"}],"wp:attachment":[{"href":"https:\/\/explore-agadirsoussmassa.com\/ar\/wp-json\/wp\/v2\/media?parent=34795"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/explore-agadirsoussmassa.com\/ar\/wp-json\/wp\/v2\/categories?post=34795"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/explore-agadirsoussmassa.com\/ar\/wp-json\/wp\/v2\/tags?post=34795"},{"taxonomy":"powerkit_post_featured","embeddable":true,"href":"https:\/\/explore-agadirsoussmassa.com\/ar\/wp-json\/wp\/v2\/powerkit_post_featured?post=34795"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}