{"id":34927,"date":"2020-04-10T18:13:16","date_gmt":"2020-04-10T16:13:16","guid":{"rendered":"https:\/\/explore-agadirsoussmassa.com\/tombeaux-saadiens-aguerd\/"},"modified":"2021-02-18T10:43:05","modified_gmt":"2021-02-18T09:43:05","slug":"%d9%85%d9%82%d8%a7%d8%a8%d8%b1-%d8%a7%d9%84%d8%b3%d8%b9%d8%af%d9%8a%d9%8a%d9%86-%d8%a3%d8%b1%d8%b6-%d9%85%d8%b3%d9%83%d9%8a%d9%86%d8%a9","status":"publish","type":"post","link":"https:\/\/explore-agadirsoussmassa.com\/ar\/%d9%85%d9%82%d8%a7%d8%a8%d8%b1-%d8%a7%d9%84%d8%b3%d8%b9%d8%af%d9%8a%d9%8a%d9%86-%d8%a3%d8%b1%d8%b6-%d9%85%d8%b3%d9%83%d9%8a%d9%86%d8%a9\/","title":{"rendered":"\u0645\u0642\u0627\u0628\u0631 \u0627\u0644\u0633\u0639\u062f\u064a\u064a\u0646 &#8211; \u0623\u0631\u0636 \u0645\u0633\u0643\u064a\u0646\u0629"},"content":{"rendered":"<div id=\"pl-gb34927-6a572cb8a2ab7\"  class=\"panel-layout panel-is-rtl\" ><div id=\"pg-gb34927-6a572cb8a2ab7-0\"  class=\"panel-grid panel-no-style\" ><div id=\"pgc-gb34927-6a572cb8a2ab7-0-0\"  class=\"panel-grid-cell\" ><div id=\"panel-gb34927-6a572cb8a2ab7-0-0-0\" class=\"so-panel widget widget_text panel-first-child panel-last-child\" data-index=\"0\" ><div id=\"sdrstyle\" class=\"panel-widget-style panel-widget-style-for-gb34927-6a572cb8a2ab7-0-0-0\" >\t\t\t<div class=\"textwidget\"><h3 id=\"%d9%85%d8%b9%d9%82%d9%84-%d8%a7%d9%84%d8%af%d9%88%d9%84%d8%a9-%d8%a7%d9%84%d8%b3%d8%b9%d8%af%d9%8a%d8%a9-%d8%a8%d8%a7%d9%84%d9%82%d8%b1%d8%a8-%d9%85%d9%86-%d8%a3%d9%83%d8%a7%d8%af%d9%8a%d8%b1\" style=\";text-align: right; direction: rtl;\">\u0645\u0639\u0642\u0644 \u0627\u0644\u062f\u0648\u0644\u0629 \u0627\u0644\u0633\u0639\u062f\u064a\u0629 &#8211; \u0628\u0627\u0644\u0642\u0631\u0628 \u0645\u0646 \u0623\u0643\u0627\u062f\u064a\u0631<\/h3>\n<p>\u0627\u0644\u0631\u062d\u0644\u0629 \u0645\u0646 \u0623\u0643\u0627\u062f\u064a\u0631: \u0623\u0642\u0644 \u0645\u0646 \u0633\u0627\u0639\u0629<\/p>\n<div class=\"thirdtitle bigsize\" style=\"text-transform: uppercase; ;text-align: right; direction: rtl;\">\u0645\u0642\u0627\u0628\u0631 \u0627\u0644\u0634\u0631\u0641\u0627\u0621 \u0627\u0644\u0633\u0639\u062f\u064a\u064a\u0646<\/div>\n<div>\n<p><em>\u064a\u0642\u0639 \u0645\u0633\u062c\u062f<\/em> <em>\u062a\u0645\u0632\u0643\u064a\u062f\u0627 \u0623\u0648\u0643\u0631\u0636 \u0641\u064a \u0642\u0631\u064a\u0629<\/em> <em>\u0623\u0643\u0631\u0636 (<\/em><em>30.486199\u060c <\/em><em>9.469668-<\/em><em>)<\/em> <em>\u0639\u0644\u0649 \u0628\u0639\u062f 12 \u0643\u0644\u0645 \u0634\u0645\u0627\u0644 \u0634\u0631\u0642 \u0645\u062f\u064a\u0646\u0629 \u0623\u0643\u0627\u062f\u064a\u0631\u060c \u0648\u062a\u062d\u064a\u0637 \u0628\u0647 \u0645\u0642\u0628\u0631\u0629 \u062a\u0636\u0645 \u0642\u0628\u0648\u0631 \u0627\u0644\u0634\u0631\u0641\u0627\u0621 \u0627\u0644\u0633\u0639\u062f\u064a\u064a\u0646 \u0648\u0623\u0641\u0631\u0627\u062f \u0623\u0633\u0631\u0647\u0645\u060c \u0646\u0627\u0647\u064a\u0643 \u0639\u0646 \u0627\u0644\u062c\u0646\u0648\u062f \u0627\u0644\u0630\u064a\u0646 \u0644\u0642\u0648\u0627 \u062d\u062a\u0641\u0647\u0645 \u062e\u0644\u0627\u0644 \u0627\u0644\u0645\u0639\u0627\u0631\u0643. \u062d\u064a\u062b<\/em> <em>\u062a\u0645 \u062f\u0641\u0646 \u0627\u0644\u0631\u062c\u0627\u0644 \u0648\u0627\u0644\u0646\u0633\u0627\u0621 \u0641\u064a \u0636\u0631\u064a\u062d\u064a\u0646 \u0645\u0646\u0641\u0635\u0644\u064a\u0646\u060c \u0647\u0630\u0627 \u0648\u064a\u062f\u0644 \u0627\u0644\u0639\u062f\u062f \u0627\u0644\u0643\u0628\u064a\u0631 \u0644\u0644\u0642\u0628\u0648\u0631 \u0639\u0644\u0649 \u0637\u0648\u0644 \u0645\u062f\u0629 \u0627\u062d\u062a\u0644\u0627\u0644 \u0627\u0644\u0633\u0639\u062f\u064a\u064a\u0646 \u0644\u0623\u0631\u0636 \u0645\u0633\u0643\u064a\u0646\u0629 (\u0645\u0646 \u0628\u062f\u0627\u064a\u0629 \u0627\u0644\u0642\u0631\u0646 \u0627\u0644\u0633\u0627\u062f\u0633 \u0639\u0634\u0631 \u0648\u062d\u062a\u0649 \u0645\u0646\u062a\u0635\u0641\u0647)<\/em><em>.<\/em><\/p>\n<\/div>\n<\/div>\n\t\t<\/div><\/div><\/div><\/div><\/div>\n\n<div class=\"cnvs-block-justified-gallery cnvs-block-justified-gallery-1595534725170\" >\n<div\n\tclass='gallery cnvs-gallery-type-justified'\n\tdata-jg-margins=\"10\"\n\tdata-jg-border=\"-10\"\n\tdata-jg-row-height=\"275\"\n\tdata-jg-max-row-height=\"200%\"\n\tdata-jg-last-row=\"justify\"\n\tdata-jg-captions=\"true\"\n\tdata-jg-randomize=\"false\"\n>\n\t\t\t<figure class=\"gallery-item\">\n\t\t\t\t\t\t\t<a href=\"https:\/\/explore-agadirsoussmassa.com\/wp-content\/uploads\/2020\/04\/tombaux-2.jpg\">\n\t\t\t\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"960\" height=\"638\" src=\"https:\/\/explore-agadirsoussmassa.com\/wp-content\/uploads\/2020\/04\/tombaux-2.jpg\" class=\"attachment-csco-1160 size-csco-1160\" alt=\"\" srcset=\"https:\/\/explore-agadirsoussmassa.com\/wp-content\/uploads\/2020\/04\/tombaux-2.jpg 960w, https:\/\/explore-agadirsoussmassa.com\/wp-content\/uploads\/2020\/04\/tombaux-2-800x532.jpg 800w, https:\/\/explore-agadirsoussmassa.com\/wp-content\/uploads\/2020\/04\/tombaux-2-320x213.jpg 320w, https:\/\/explore-agadirsoussmassa.com\/wp-content\/uploads\/2020\/04\/tombaux-2-560x372.jpg 560w, https:\/\/explore-agadirsoussmassa.com\/wp-content\/uploads\/2020\/04\/tombaux-2-272x182.jpg 272w\" sizes=\"auto, (max-width: 960px) 100vw, 960px\" \/>\n\t\t\t\t\t\t\t<\/a>\n\t\t\t\n\t\t\t\t\t<\/figure>\n\t\t\t\t<figure class=\"gallery-item\">\n\t\t\t\t\t\t\t<a href=\"https:\/\/explore-agadirsoussmassa.com\/wp-content\/uploads\/2020\/04\/tombeaux-4.jpg\">\n\t\t\t\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"953\" height=\"636\" src=\"https:\/\/explore-agadirsoussmassa.com\/wp-content\/uploads\/2020\/04\/tombeaux-4.jpg\" class=\"attachment-csco-1160 size-csco-1160\" alt=\"\" srcset=\"https:\/\/explore-agadirsoussmassa.com\/wp-content\/uploads\/2020\/04\/tombeaux-4.jpg 953w, https:\/\/explore-agadirsoussmassa.com\/wp-content\/uploads\/2020\/04\/tombeaux-4-800x534.jpg 800w, https:\/\/explore-agadirsoussmassa.com\/wp-content\/uploads\/2020\/04\/tombeaux-4-320x214.jpg 320w, https:\/\/explore-agadirsoussmassa.com\/wp-content\/uploads\/2020\/04\/tombeaux-4-560x374.jpg 560w, https:\/\/explore-agadirsoussmassa.com\/wp-content\/uploads\/2020\/04\/tombeaux-4-272x182.jpg 272w\" sizes=\"auto, (max-width: 953px) 100vw, 953px\" \/>\n\t\t\t\t\t\t\t<\/a>\n\t\t\t\n\t\t\t\t\t<\/figure>\n\t\t<\/div>\n\n<\/div>\n\n<div id=\"pl-gb34927-6a572cb8a5a91\"  class=\"panel-layout panel-is-rtl\" ><div id=\"pg-gb34927-6a572cb8a5a91-0\"  class=\"panel-grid panel-no-style\" ><div id=\"pgc-gb34927-6a572cb8a5a91-0-0\"  class=\"panel-grid-cell\" ><div id=\"panel-gb34927-6a572cb8a5a91-0-0-0\" class=\"so-panel widget widget_text panel-first-child panel-last-child\" data-index=\"0\" >\t\t\t<div class=\"textwidget\"><div class=\"thirdtitle bigsize\" style=\"text-transform: uppercase; ;text-align: right; direction: rtl;\">\u0645\u0645\u0631 \u0627\u0633\u062a\u0631\u0627\u062a\u064a\u062c\u064a<\/div>\n<div>\n<p><em>\u062a\u0634\u0645\u0644 \u0647\u0630\u0647 \u0627\u0644\u0645\u0639\u0627\u0644\u0645 \u0627\u0644\u062d\u0636\u0631\u064a\u0629 \u0645\u062f\u0631\u0633\u0629 \u0642\u0631\u0622\u0646\u064a\u0629 \u0648\u0645\u0633\u062c\u062f\u064b\u0627 \u064a\u0639\u0648\u062f \u062a\u0627\u0631\u064a\u062e\u0647 \u0625\u0644\u0649 \u062d\u0642\u0628\u0629 \u0627\u0644\u0645\u0631\u0627\u0628\u0637\u064a\u0646 (1060-1147). <\/em>\u00a0\u0648\u0642\u062f <em>\u062a\u0645 \u0628\u0646\u0627\u0621 \u0645\u0633\u062c\u062f<\/em> <em>\u062a\u0645\u0632\u0643\u064a\u062f\u0627 \u0623\u0648\u0643\u0631\u0636 \u0644\u0645\u0627 \u0643\u0627\u0646 \u0627\u0644\u0645\u0631\u0627\u0628\u0637\u0648\u0646 \u064a\u062d\u0627\u0648\u0644\u0648\u0646 \u0636\u0645\u0627\u0646 \u0633\u0644\u0627\u0645\u0629 \u0627\u0644\u0642\u0648\u0627\u0641\u0644 \u0627\u0644\u0635\u062d\u0631\u0627\u0648\u064a\u0629 \u0627\u0644\u062a\u064a \u062a\u0645\u0631 \u0639\u0628\u0631 \u0627\u0644\u0645\u0645\u0631 \u0627\u0644\u0627\u0633\u062a\u0631\u0627\u062a\u064a\u062c\u064a \u0644\u0645\u0636\u064a\u0642 \u0645\u0633\u0643\u064a\u0646\u0629. \u0648\u062d\u0627\u0641\u0638 \u0627\u0644\u0633\u0639\u062f\u064a\u0648\u0646 \u0628\u0639\u062f \u0630\u0644\u0643 \u0639\u0644\u0649 \u0627\u0644\u0645\u0633\u062c\u062f \u0648\u0627\u0644\u0645\u062f\u0631\u0633\u0629 \u0627\u0644\u0642\u0631\u0622\u0646\u064a\u0629\u060c \u0643\u0645\u0627 \u0642\u0627\u0645\u0648\u0627 \u0628\u0625\u062f\u062e\u0627\u0644 \u0644\u0645\u0633\u062a\u0647\u0645 \u0627\u0644\u0645\u0639\u0645\u0627\u0631\u064a\u0629 \u0627\u0644\u062e\u0627\u0635\u0629 \u0639\u0644\u064a\u0647\u0627.<\/em> <em>\u0623\u0635\u0628\u062d\u062a \u0627\u0644\u0645\u062f\u0631\u0633\u0629 \u0645\u0631\u0643\u0632\u064b\u0627 \u0644\u0644\u062a\u0639\u0644\u0645 \u0648\u0644\u0644\u0639\u0644\u0648\u0645 \u0627\u0644\u062f\u064a\u0646\u064a\u0629\u060c \u0648\u062a\u0636\u0645 \u062f\u0627\u062e\u0644\u064a\u0629 \u062a\u0633\u0645\u062d \u062d\u062a\u0649 \u0627\u0644\u064a\u0648\u0645 \u0644\u0644\u0623\u0626\u0645\u0629 \u0627\u0644\u0645\u0633\u062a\u0642\u0628\u0644\u064a\u064a\u0646 \u0628\u0627\u0644\u0627\u0633\u062a\u0642\u0631\u0627\u0631 \u0647\u0646\u0627\u0643 \u0648\u0627\u0644\u062a\u062f\u0631\u064a\u0628. \u064a\u062a\u0645 \u062a\u0647\u0648\u064a\u0629 \u0627\u0644\u063a\u0631\u0641\u0629 \u0627\u0644\u0643\u0628\u064a\u0631\u0629 \u0627\u0644\u062a\u064a \u062a\u0633\u062a\u062e\u062f\u0645 \u0643\u063a\u0631\u0641\u0629 \u0644\u0644\u0635\u0644\u0627\u0629 \u0648\u0627\u0644\u062f\u0631\u0627\u0633\u0629 \u0645\u0646 \u062e\u0644\u0627\u0644 \u0641\u062a\u062d\u0629 \u0643\u0628\u064a\u0631\u0629 \u0641\u064a \u0627\u0644\u0633\u0645\u0627\u0621<\/em><em>.<\/em><\/p>\n<\/div>\n<\/div>\n\t\t<\/div><\/div><\/div><\/div>\n\n<div class=\"cnvs-block-justified-gallery cnvs-block-justified-gallery-1595534780221\" >\n<div\n\tclass='gallery cnvs-gallery-type-justified'\n\tdata-jg-margins=\"10\"\n\tdata-jg-border=\"-10\"\n\tdata-jg-row-height=\"275\"\n\tdata-jg-max-row-height=\"200%\"\n\tdata-jg-last-row=\"justify\"\n\tdata-jg-captions=\"true\"\n\tdata-jg-randomize=\"false\"\n>\n\t\t\t<figure class=\"gallery-item\">\n\t\t\t\t\t\t\t<a href=\"https:\/\/explore-agadirsoussmassa.com\/wp-content\/uploads\/2020\/04\/tombeaux-1.jpg\">\n\t\t\t\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"960\" height=\"640\" src=\"https:\/\/explore-agadirsoussmassa.com\/wp-content\/uploads\/2020\/04\/tombeaux-1.jpg\" class=\"attachment-csco-1160 size-csco-1160\" alt=\"\" srcset=\"https:\/\/explore-agadirsoussmassa.com\/wp-content\/uploads\/2020\/04\/tombeaux-1.jpg 960w, https:\/\/explore-agadirsoussmassa.com\/wp-content\/uploads\/2020\/04\/tombeaux-1-800x533.jpg 800w, https:\/\/explore-agadirsoussmassa.com\/wp-content\/uploads\/2020\/04\/tombeaux-1-320x213.jpg 320w, https:\/\/explore-agadirsoussmassa.com\/wp-content\/uploads\/2020\/04\/tombeaux-1-560x373.jpg 560w, https:\/\/explore-agadirsoussmassa.com\/wp-content\/uploads\/2020\/04\/tombeaux-1-272x182.jpg 272w\" sizes=\"auto, (max-width: 960px) 100vw, 960px\" \/>\n\t\t\t\t\t\t\t<\/a>\n\t\t\t\n\t\t\t\t\t<\/figure>\n\t\t<\/div>\n\n<\/div>\n\n<div id=\"pl-gb34927-6a572cb8a6b53\"  class=\"panel-layout panel-is-rtl\" ><div id=\"pg-gb34927-6a572cb8a6b53-0\"  class=\"panel-grid panel-no-style\" ><div id=\"pgc-gb34927-6a572cb8a6b53-0-0\"  class=\"panel-grid-cell\" ><div id=\"panel-gb34927-6a572cb8a6b53-0-0-0\" class=\"so-panel widget widget_text panel-first-child panel-last-child\" data-index=\"0\" >\t\t\t<div class=\"textwidget\"><p>\u0643\u064a\u0641\u064a\u0629 \u0627\u0644\u0648\u0635\u0648\u0644: <em>\u064a\u0646\u0628\u063a\u064a \u0627\u0644\u0627\u0646\u0637\u0644\u0627\u0642 \u0645\u0646 \u062a\u064a\u063a\u0627\u0646\u0645\u064a\u0646 \u0627\u0644\u0628\u0627\u0632 (30.435884\u060c 9.490828-) \u0627\u0644\u062a\u064a \u062a\u0642\u0639 \u0639\u0644\u0649 \u0628\u0639\u062f 15 \u0643\u0644\u0645 \u0645\u0646 \u0648\u0633\u0637 \u0645\u062f\u064a\u0646\u0629 \u0623\u0643\u0627\u062f\u064a\u0631\u060c \u062b\u0645 \u0627\u0644\u062a\u0648\u062c\u0647 \u0635\u0648\u0628 <\/em><em>\u0623\u0632\u0631\u0627\u0631\u0627\u0643 <\/em><em>(30.473974\u060c 9.466420-) \u0639\u0628\u0631 \u0633\u0641\u0648\u062d \u0627\u0644\u0623\u0637\u0644\u0633 \u0627\u0644\u0643\u0628\u064a\u0631 \u0627\u0644\u063a\u0631\u0628\u064a.<\/em><\/p>\n<p><em>\u062e\u0637\u0629 \u062c\u064a\u062f\u0629<\/em><em>: <a href=\"\/escapade-pays-de-messguina\/\">\u0645\u0645\u0631 \u062c\u0628\u0644\u064a<\/a><\/em><\/p>\n<\/div>\n\t\t<\/div><\/div><\/div><\/div>\n\n<div class=\"cnvs-block-justified-gallery cnvs-block-justified-gallery-1595534809416\" >\n<div\n\tclass='gallery cnvs-gallery-type-justified'\n\tdata-jg-margins=\"10\"\n\tdata-jg-border=\"-10\"\n\tdata-jg-row-height=\"275\"\n\tdata-jg-max-row-height=\"200%\"\n\tdata-jg-last-row=\"justify\"\n\tdata-jg-captions=\"true\"\n\tdata-jg-randomize=\"false\"\n>\n\t\t\t<figure class=\"gallery-item\">\n\t\t\t\t\t\t\t<a href=\"https:\/\/explore-agadirsoussmassa.com\/wp-content\/uploads\/2020\/04\/circuit-mesguina.png\">\n\t\t\t\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1160\" height=\"592\" src=\"https:\/\/explore-agadirsoussmassa.com\/wp-content\/uploads\/2020\/04\/circuit-mesguina-1160x592.png\" class=\"attachment-csco-1160 size-csco-1160\" alt=\"\" srcset=\"https:\/\/explore-agadirsoussmassa.com\/wp-content\/uploads\/2020\/04\/circuit-mesguina-1160x592.png 1160w, https:\/\/explore-agadirsoussmassa.com\/wp-content\/uploads\/2020\/04\/circuit-mesguina-800x408.png 800w, https:\/\/explore-agadirsoussmassa.com\/wp-content\/uploads\/2020\/04\/circuit-mesguina-1536x784.png 1536w, https:\/\/explore-agadirsoussmassa.com\/wp-content\/uploads\/2020\/04\/circuit-mesguina-2048x1045.png 2048w, https:\/\/explore-agadirsoussmassa.com\/wp-content\/uploads\/2020\/04\/circuit-mesguina-320x163.png 320w, https:\/\/explore-agadirsoussmassa.com\/wp-content\/uploads\/2020\/04\/circuit-mesguina-560x286.png 560w, https:\/\/explore-agadirsoussmassa.com\/wp-content\/uploads\/2020\/04\/circuit-mesguina-1920x979.png 1920w, https:\/\/explore-agadirsoussmassa.com\/wp-content\/uploads\/2020\/04\/circuit-mesguina.png 2568w\" sizes=\"auto, (max-width: 1160px) 100vw, 1160px\" \/>\n\t\t\t\t\t\t\t<\/a>\n\t\t\t\n\t\t\t\t\t<\/figure>\n\t\t<\/div>\n\n<\/div>\n\n<div id=\"pl-gb34927-6a572cb8a7a44\"  class=\"panel-layout panel-is-rtl\" ><div id=\"pg-gb34927-6a572cb8a7a44-0\"  class=\"panel-grid panel-no-style\" ><div id=\"pgc-gb34927-6a572cb8a7a44-0-0\"  class=\"panel-grid-cell\" ><div id=\"panel-gb34927-6a572cb8a7a44-0-0-0\" class=\"so-panel widget widget_text panel-first-child panel-last-child\" data-index=\"0\" >\t\t\t<div class=\"textwidget\"><p>\u00a0<\/p>\n<p>\u00a0<\/p>\n<\/div>\n\t\t<\/div><\/div><\/div><\/div>","protected":false},"excerpt":{"rendered":"<div class=\"post-excerpt\">\u064a\u0624\u0643\u062f \u0627\u0644\u0645\u0624\u0631\u062e\u0648\u0646 \u0623\u0646\u0647 \u0627\u0644\u062d\u0635\u0646 \u0627\u0644\u0645\u0639\u0631\u0648\u0641 \u0628\u0627\u0633\u0645 \u0623\u0643\u0644\u0627\u0644 \u0641\u064a \u0623\u0643\u0631\u0636 \u0623\u0642\u0627\u0645\u0647 \u0627\u0644\u0634\u064a\u062e \u0645\u062d\u0645\u062f \u0627\u0644\u0633\u0639\u062f\u064a\u060c \u0645\u0624\u0633\u0633 \u0627\u0644\u062f\u0648\u0644\u0629 \u0627\u0644\u0633\u0639\u062f\u064a\u0629 \u0648\u0642\u0627\u0626\u062f\u0647\u0627 \u0645\u0646 1540 \u0625\u0644\u0649 1554. \u0648\u0642\u062f \u0643\u0627\u0646 \u0647\u0630\u0627 \u0627\u0644\u062d\u0635\u0646 \u0628\u0645\u062b\u0627\u0628\u0629 \u0646\u0642\u0637\u0629 \u0627\u0646\u0637\u0644\u0627\u0642 \u0644\u0644\u0647\u062c\u0645\u0627\u062a \u0636\u062f \u0627\u0644\u0642\u0644\u0639\u0629 \u0627\u0644\u0628\u0631\u062a\u063a\u0627\u0644\u064a\u0629 \u0627\u0644\u0645\u0639\u0631\u0648\u0641\u0629 \u0628\u0627\u0633\u0645 \u0633\u0627\u0646\u062a\u0627 \u0643\u0631\u0648\u0632 \u062f\u0648 \u0643\u0627\u0628\u0648 \u062f\u064a \u0623\u063a\u064a\u0631 (\u0631\u0623\u0633 \u063a\u064a\u0631).<\/div>\n<div class=\"post-more\"><a href=\"https:\/\/explore-agadirsoussmassa.com\/ar\/%d9%85%d9%82%d8%a7%d8%a8%d8%b1-%d8%a7%d9%84%d8%b3%d8%b9%d8%af%d9%8a%d9%8a%d9%86-%d8%a3%d8%b1%d8%b6-%d9%85%d8%b3%d9%83%d9%8a%d9%86%d8%a9\/\" class=\"button button-primary button-effect\"><span>\u0627\u0646\u0638\u0631 \u0627\u0644\u062a\u0641\u0627\u0635\u064a\u0644<\/span><span><i class=\"cs-icon cs-icon-arrow-right\"><\/i><\/span><\/a><\/div>\n","protected":false},"author":1,"featured_media":13619,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[464,690,544],"tags":[574],"powerkit_post_featured":[],"class_list":{"0":"post-34927","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-464","8":"category-690","9":"category-544","10":"tag-azrarag-ar"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.0 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>\u0645\u0642\u0627\u0628\u0631 \u0627\u0644\u0633\u0639\u062f\u064a\u064a\u0646 - \u0623\u0631\u0636 \u0645\u0633\u0643\u064a\u0646\u0629 - Explore Agadir Souss Massa<\/title>\n<meta name=\"description\" content=\"\u062a\u0642\u0639 \u0642\u0631\u064a\u0629 \u0623\u0643\u0631\u0636 \u0639\u0644\u0649 \u0628\u0639\u062f 12 \u0643\u0644\u0645 \u0634\u0645\u0627\u0644 \u0634\u0631\u0642 \u0623\u0643\u0627\u062f\u064a\u0631\u060c \u0648\u062a\u062d\u0636\u0646 \u0642\u0628\u0648\u0631 \u0627\u0644\u0639\u062f\u064a\u062f \u0645\u0646 \u0627\u0644\u0623\u0645\u0631\u0627\u0621 \u0648\u0645\u0624\u0633\u0633\u064a \u0627\u0644\u062f\u0648\u0644\u0629 \u0627\u0644\u0633\u0639\u062f\u064a\u0629 \u0648\u0639\u0627\u0626\u0644\u0627\u062a\u0647\u0645.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/explore-agadirsoussmassa.com\/ar\/%d9%85%d9%82%d8%a7%d8%a8%d8%b1-%d8%a7%d9%84%d8%b3%d8%b9%d8%af%d9%8a%d9%8a%d9%86-%d8%a3%d8%b1%d8%b6-%d9%85%d8%b3%d9%83%d9%8a%d9%86%d8%a9\/\" \/>\n<meta property=\"og:locale\" content=\"ar_AR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u0645\u0642\u0627\u0628\u0631 \u0627\u0644\u0633\u0639\u062f\u064a\u064a\u0646 - \u0623\u0631\u0636 \u0645\u0633\u0643\u064a\u0646\u0629 - Explore Agadir Souss Massa\" \/>\n<meta property=\"og:description\" content=\"\u062a\u0642\u0639 \u0642\u0631\u064a\u0629 \u0623\u0643\u0631\u0636 \u0639\u0644\u0649 \u0628\u0639\u062f 12 \u0643\u0644\u0645 \u0634\u0645\u0627\u0644 \u0634\u0631\u0642 \u0623\u0643\u0627\u062f\u064a\u0631\u060c \u0648\u062a\u062d\u0636\u0646 \u0642\u0628\u0648\u0631 \u0627\u0644\u0639\u062f\u064a\u062f \u0645\u0646 \u0627\u0644\u0623\u0645\u0631\u0627\u0621 \u0648\u0645\u0624\u0633\u0633\u064a \u0627\u0644\u062f\u0648\u0644\u0629 \u0627\u0644\u0633\u0639\u062f\u064a\u0629 \u0648\u0639\u0627\u0626\u0644\u0627\u062a\u0647\u0645.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/explore-agadirsoussmassa.com\/ar\/%d9%85%d9%82%d8%a7%d8%a8%d8%b1-%d8%a7%d9%84%d8%b3%d8%b9%d8%af%d9%8a%d9%8a%d9%86-%d8%a3%d8%b1%d8%b6-%d9%85%d8%b3%d9%83%d9%8a%d9%86%d8%a9\/\" \/>\n<meta property=\"og:site_name\" content=\"Explore Agadir Souss Massa\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Explore-Souss-Massa-111659480353930\" \/>\n<meta property=\"article:published_time\" content=\"2020-04-10T16:13:16+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-02-18T09:43:05+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/explore-agadirsoussmassa.com\/wp-content\/uploads\/2020\/04\/tombeaux-3.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"878\" \/>\n\t<meta property=\"og:image:height\" content=\"586\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"soussmassa\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u0643\u064f\u062a\u0628 \u0628\u0648\u0627\u0633\u0637\u0629\" \/>\n\t<meta name=\"twitter:data1\" content=\"soussmassa\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/explore-agadirsoussmassa.com\/ar\/%d9%85%d9%82%d8%a7%d8%a8%d8%b1-%d8%a7%d9%84%d8%b3%d8%b9%d8%af%d9%8a%d9%8a%d9%86-%d8%a3%d8%b1%d8%b6-%d9%85%d8%b3%d9%83%d9%8a%d9%86%d8%a9\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/explore-agadirsoussmassa.com\/ar\/%d9%85%d9%82%d8%a7%d8%a8%d8%b1-%d8%a7%d9%84%d8%b3%d8%b9%d8%af%d9%8a%d9%8a%d9%86-%d8%a3%d8%b1%d8%b6-%d9%85%d8%b3%d9%83%d9%8a%d9%86%d8%a9\/\"},\"author\":{\"name\":\"soussmassa\",\"@id\":\"https:\/\/explore-agadirsoussmassa.com\/ar\/#\/schema\/person\/c019e4bcfef76d1c57d426107449d03e\"},\"headline\":\"\u0645\u0642\u0627\u0628\u0631 \u0627\u0644\u0633\u0639\u062f\u064a\u064a\u0646 &#8211; \u0623\u0631\u0636 \u0645\u0633\u0643\u064a\u0646\u0629\",\"datePublished\":\"2020-04-10T16:13:16+00:00\",\"dateModified\":\"2021-02-18T09:43:05+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/explore-agadirsoussmassa.com\/ar\/%d9%85%d9%82%d8%a7%d8%a8%d8%b1-%d8%a7%d9%84%d8%b3%d8%b9%d8%af%d9%8a%d9%8a%d9%86-%d8%a3%d8%b1%d8%b6-%d9%85%d8%b3%d9%83%d9%8a%d9%86%d8%a9\/\"},\"wordCount\":1,\"publisher\":{\"@id\":\"https:\/\/explore-agadirsoussmassa.com\/ar\/#organization\"},\"image\":{\"@id\":\"https:\/\/explore-agadirsoussmassa.com\/ar\/%d9%85%d9%82%d8%a7%d8%a8%d8%b1-%d8%a7%d9%84%d8%b3%d8%b9%d8%af%d9%8a%d9%8a%d9%86-%d8%a3%d8%b1%d8%b6-%d9%85%d8%b3%d9%83%d9%8a%d9%86%d8%a9\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/explore-agadirsoussmassa.com\/wp-content\/uploads\/2020\/04\/tombeaux-3.jpg\",\"keywords\":[\"azrarag\"],\"articleSection\":[\"\u0623\u0646\u0634\u0637\u0629\",\"\u0627\u0644\u0632\u0648\u0627\u064a\u0627 \u0648\u0627\u0644\u0645\u0633\u0627\u062c\u062f\",\"\u0641\u0646 \u0627\u0644\u0639\u0645\u0627\u0631\u0629 \/ \u0627\u0644\u062a\u0631\u0627\u062b\"],\"inLanguage\":\"ar\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/explore-agadirsoussmassa.com\/ar\/%d9%85%d9%82%d8%a7%d8%a8%d8%b1-%d8%a7%d9%84%d8%b3%d8%b9%d8%af%d9%8a%d9%8a%d9%86-%d8%a3%d8%b1%d8%b6-%d9%85%d8%b3%d9%83%d9%8a%d9%86%d8%a9\/\",\"url\":\"https:\/\/explore-agadirsoussmassa.com\/ar\/%d9%85%d9%82%d8%a7%d8%a8%d8%b1-%d8%a7%d9%84%d8%b3%d8%b9%d8%af%d9%8a%d9%8a%d9%86-%d8%a3%d8%b1%d8%b6-%d9%85%d8%b3%d9%83%d9%8a%d9%86%d8%a9\/\",\"name\":\"\u0645\u0642\u0627\u0628\u0631 \u0627\u0644\u0633\u0639\u062f\u064a\u064a\u0646 - \u0623\u0631\u0636 \u0645\u0633\u0643\u064a\u0646\u0629 - Explore Agadir Souss Massa\",\"isPartOf\":{\"@id\":\"https:\/\/explore-agadirsoussmassa.com\/ar\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/explore-agadirsoussmassa.com\/ar\/%d9%85%d9%82%d8%a7%d8%a8%d8%b1-%d8%a7%d9%84%d8%b3%d8%b9%d8%af%d9%8a%d9%8a%d9%86-%d8%a3%d8%b1%d8%b6-%d9%85%d8%b3%d9%83%d9%8a%d9%86%d8%a9\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/explore-agadirsoussmassa.com\/ar\/%d9%85%d9%82%d8%a7%d8%a8%d8%b1-%d8%a7%d9%84%d8%b3%d8%b9%d8%af%d9%8a%d9%8a%d9%86-%d8%a3%d8%b1%d8%b6-%d9%85%d8%b3%d9%83%d9%8a%d9%86%d8%a9\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/explore-agadirsoussmassa.com\/wp-content\/uploads\/2020\/04\/tombeaux-3.jpg\",\"datePublished\":\"2020-04-10T16:13:16+00:00\",\"dateModified\":\"2021-02-18T09:43:05+00:00\",\"description\":\"\u062a\u0642\u0639 \u0642\u0631\u064a\u0629 \u0623\u0643\u0631\u0636 \u0639\u0644\u0649 \u0628\u0639\u062f 12 \u0643\u0644\u0645 \u0634\u0645\u0627\u0644 \u0634\u0631\u0642 \u0623\u0643\u0627\u062f\u064a\u0631\u060c \u0648\u062a\u062d\u0636\u0646 \u0642\u0628\u0648\u0631 \u0627\u0644\u0639\u062f\u064a\u062f \u0645\u0646 \u0627\u0644\u0623\u0645\u0631\u0627\u0621 \u0648\u0645\u0624\u0633\u0633\u064a \u0627\u0644\u062f\u0648\u0644\u0629 \u0627\u0644\u0633\u0639\u062f\u064a\u0629 \u0648\u0639\u0627\u0626\u0644\u0627\u062a\u0647\u0645.\",\"breadcrumb\":{\"@id\":\"https:\/\/explore-agadirsoussmassa.com\/ar\/%d9%85%d9%82%d8%a7%d8%a8%d8%b1-%d8%a7%d9%84%d8%b3%d8%b9%d8%af%d9%8a%d9%8a%d9%86-%d8%a3%d8%b1%d8%b6-%d9%85%d8%b3%d9%83%d9%8a%d9%86%d8%a9\/#breadcrumb\"},\"inLanguage\":\"ar\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/explore-agadirsoussmassa.com\/ar\/%d9%85%d9%82%d8%a7%d8%a8%d8%b1-%d8%a7%d9%84%d8%b3%d8%b9%d8%af%d9%8a%d9%8a%d9%86-%d8%a3%d8%b1%d8%b6-%d9%85%d8%b3%d9%83%d9%8a%d9%86%d8%a9\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"ar\",\"@id\":\"https:\/\/explore-agadirsoussmassa.com\/ar\/%d9%85%d9%82%d8%a7%d8%a8%d8%b1-%d8%a7%d9%84%d8%b3%d8%b9%d8%af%d9%8a%d9%8a%d9%86-%d8%a3%d8%b1%d8%b6-%d9%85%d8%b3%d9%83%d9%8a%d9%86%d8%a9\/#primaryimage\",\"url\":\"https:\/\/explore-agadirsoussmassa.com\/wp-content\/uploads\/2020\/04\/tombeaux-3.jpg\",\"contentUrl\":\"https:\/\/explore-agadirsoussmassa.com\/wp-content\/uploads\/2020\/04\/tombeaux-3.jpg\",\"width\":878,\"height\":586},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/explore-agadirsoussmassa.com\/ar\/%d9%85%d9%82%d8%a7%d8%a8%d8%b1-%d8%a7%d9%84%d8%b3%d8%b9%d8%af%d9%8a%d9%8a%d9%86-%d8%a3%d8%b1%d8%b6-%d9%85%d8%b3%d9%83%d9%8a%d9%86%d8%a9\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/explore-agadirsoussmassa.com\/ar\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u0645\u0642\u0627\u0628\u0631 \u0627\u0644\u0633\u0639\u062f\u064a\u064a\u0646 &#8211; \u0623\u0631\u0636 \u0645\u0633\u0643\u064a\u0646\u0629\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/explore-agadirsoussmassa.com\/ar\/#website\",\"url\":\"https:\/\/explore-agadirsoussmassa.com\/ar\/\",\"name\":\"Explore Agadir Souss Massa\",\"description\":\"R\u00e9gion Souss Massa\",\"publisher\":{\"@id\":\"https:\/\/explore-agadirsoussmassa.com\/ar\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/explore-agadirsoussmassa.com\/ar\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ar\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/explore-agadirsoussmassa.com\/ar\/#organization\",\"name\":\"SDR Tourisme Souss Massa\",\"url\":\"https:\/\/explore-agadirsoussmassa.com\/ar\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ar\",\"@id\":\"https:\/\/explore-agadirsoussmassa.com\/ar\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/zt88dgbrixj.preview.infomaniak.website\/wp-content\/uploads\/2020\/08\/logo-sdr.png\",\"contentUrl\":\"https:\/\/zt88dgbrixj.preview.infomaniak.website\/wp-content\/uploads\/2020\/08\/logo-sdr.png\",\"width\":404,\"height\":286,\"caption\":\"SDR Tourisme Souss Massa\"},\"image\":{\"@id\":\"https:\/\/explore-agadirsoussmassa.com\/ar\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/Explore-Souss-Massa-111659480353930\",\"https:\/\/www.instagram.com\/exploresoussmassamorocco\/\",\"https:\/\/www.youtube.com\/channel\/UCpSGZAsRRpG40CeT3UcIcOA\/videos\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/explore-agadirsoussmassa.com\/ar\/#\/schema\/person\/c019e4bcfef76d1c57d426107449d03e\",\"name\":\"soussmassa\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ar\",\"@id\":\"https:\/\/explore-agadirsoussmassa.com\/ar\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/71a3f2c422286f264199c19844c327bfdf2a272a6aab356511f8970061b8dc04?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/71a3f2c422286f264199c19844c327bfdf2a272a6aab356511f8970061b8dc04?s=96&d=mm&r=g\",\"caption\":\"soussmassa\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u0645\u0642\u0627\u0628\u0631 \u0627\u0644\u0633\u0639\u062f\u064a\u064a\u0646 - \u0623\u0631\u0636 \u0645\u0633\u0643\u064a\u0646\u0629 - Explore Agadir Souss Massa","description":"\u062a\u0642\u0639 \u0642\u0631\u064a\u0629 \u0623\u0643\u0631\u0636 \u0639\u0644\u0649 \u0628\u0639\u062f 12 \u0643\u0644\u0645 \u0634\u0645\u0627\u0644 \u0634\u0631\u0642 \u0623\u0643\u0627\u062f\u064a\u0631\u060c \u0648\u062a\u062d\u0636\u0646 \u0642\u0628\u0648\u0631 \u0627\u0644\u0639\u062f\u064a\u062f \u0645\u0646 \u0627\u0644\u0623\u0645\u0631\u0627\u0621 \u0648\u0645\u0624\u0633\u0633\u064a \u0627\u0644\u062f\u0648\u0644\u0629 \u0627\u0644\u0633\u0639\u062f\u064a\u0629 \u0648\u0639\u0627\u0626\u0644\u0627\u062a\u0647\u0645.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/explore-agadirsoussmassa.com\/ar\/%d9%85%d9%82%d8%a7%d8%a8%d8%b1-%d8%a7%d9%84%d8%b3%d8%b9%d8%af%d9%8a%d9%8a%d9%86-%d8%a3%d8%b1%d8%b6-%d9%85%d8%b3%d9%83%d9%8a%d9%86%d8%a9\/","og_locale":"ar_AR","og_type":"article","og_title":"\u0645\u0642\u0627\u0628\u0631 \u0627\u0644\u0633\u0639\u062f\u064a\u064a\u0646 - \u0623\u0631\u0636 \u0645\u0633\u0643\u064a\u0646\u0629 - Explore Agadir Souss Massa","og_description":"\u062a\u0642\u0639 \u0642\u0631\u064a\u0629 \u0623\u0643\u0631\u0636 \u0639\u0644\u0649 \u0628\u0639\u062f 12 \u0643\u0644\u0645 \u0634\u0645\u0627\u0644 \u0634\u0631\u0642 \u0623\u0643\u0627\u062f\u064a\u0631\u060c \u0648\u062a\u062d\u0636\u0646 \u0642\u0628\u0648\u0631 \u0627\u0644\u0639\u062f\u064a\u062f \u0645\u0646 \u0627\u0644\u0623\u0645\u0631\u0627\u0621 \u0648\u0645\u0624\u0633\u0633\u064a \u0627\u0644\u062f\u0648\u0644\u0629 \u0627\u0644\u0633\u0639\u062f\u064a\u0629 \u0648\u0639\u0627\u0626\u0644\u0627\u062a\u0647\u0645.","og_url":"https:\/\/explore-agadirsoussmassa.com\/ar\/%d9%85%d9%82%d8%a7%d8%a8%d8%b1-%d8%a7%d9%84%d8%b3%d8%b9%d8%af%d9%8a%d9%8a%d9%86-%d8%a3%d8%b1%d8%b6-%d9%85%d8%b3%d9%83%d9%8a%d9%86%d8%a9\/","og_site_name":"Explore Agadir Souss Massa","article_publisher":"https:\/\/www.facebook.com\/Explore-Souss-Massa-111659480353930","article_published_time":"2020-04-10T16:13:16+00:00","article_modified_time":"2021-02-18T09:43:05+00:00","og_image":[{"width":878,"height":586,"url":"https:\/\/explore-agadirsoussmassa.com\/wp-content\/uploads\/2020\/04\/tombeaux-3.jpg","type":"image\/jpeg"}],"author":"soussmassa","twitter_card":"summary_large_image","twitter_misc":{"\u0643\u064f\u062a\u0628 \u0628\u0648\u0627\u0633\u0637\u0629":"soussmassa"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/explore-agadirsoussmassa.com\/ar\/%d9%85%d9%82%d8%a7%d8%a8%d8%b1-%d8%a7%d9%84%d8%b3%d8%b9%d8%af%d9%8a%d9%8a%d9%86-%d8%a3%d8%b1%d8%b6-%d9%85%d8%b3%d9%83%d9%8a%d9%86%d8%a9\/#article","isPartOf":{"@id":"https:\/\/explore-agadirsoussmassa.com\/ar\/%d9%85%d9%82%d8%a7%d8%a8%d8%b1-%d8%a7%d9%84%d8%b3%d8%b9%d8%af%d9%8a%d9%8a%d9%86-%d8%a3%d8%b1%d8%b6-%d9%85%d8%b3%d9%83%d9%8a%d9%86%d8%a9\/"},"author":{"name":"soussmassa","@id":"https:\/\/explore-agadirsoussmassa.com\/ar\/#\/schema\/person\/c019e4bcfef76d1c57d426107449d03e"},"headline":"\u0645\u0642\u0627\u0628\u0631 \u0627\u0644\u0633\u0639\u062f\u064a\u064a\u0646 &#8211; \u0623\u0631\u0636 \u0645\u0633\u0643\u064a\u0646\u0629","datePublished":"2020-04-10T16:13:16+00:00","dateModified":"2021-02-18T09:43:05+00:00","mainEntityOfPage":{"@id":"https:\/\/explore-agadirsoussmassa.com\/ar\/%d9%85%d9%82%d8%a7%d8%a8%d8%b1-%d8%a7%d9%84%d8%b3%d8%b9%d8%af%d9%8a%d9%8a%d9%86-%d8%a3%d8%b1%d8%b6-%d9%85%d8%b3%d9%83%d9%8a%d9%86%d8%a9\/"},"wordCount":1,"publisher":{"@id":"https:\/\/explore-agadirsoussmassa.com\/ar\/#organization"},"image":{"@id":"https:\/\/explore-agadirsoussmassa.com\/ar\/%d9%85%d9%82%d8%a7%d8%a8%d8%b1-%d8%a7%d9%84%d8%b3%d8%b9%d8%af%d9%8a%d9%8a%d9%86-%d8%a3%d8%b1%d8%b6-%d9%85%d8%b3%d9%83%d9%8a%d9%86%d8%a9\/#primaryimage"},"thumbnailUrl":"https:\/\/explore-agadirsoussmassa.com\/wp-content\/uploads\/2020\/04\/tombeaux-3.jpg","keywords":["azrarag"],"articleSection":["\u0623\u0646\u0634\u0637\u0629","\u0627\u0644\u0632\u0648\u0627\u064a\u0627 \u0648\u0627\u0644\u0645\u0633\u0627\u062c\u062f","\u0641\u0646 \u0627\u0644\u0639\u0645\u0627\u0631\u0629 \/ \u0627\u0644\u062a\u0631\u0627\u062b"],"inLanguage":"ar"},{"@type":"WebPage","@id":"https:\/\/explore-agadirsoussmassa.com\/ar\/%d9%85%d9%82%d8%a7%d8%a8%d8%b1-%d8%a7%d9%84%d8%b3%d8%b9%d8%af%d9%8a%d9%8a%d9%86-%d8%a3%d8%b1%d8%b6-%d9%85%d8%b3%d9%83%d9%8a%d9%86%d8%a9\/","url":"https:\/\/explore-agadirsoussmassa.com\/ar\/%d9%85%d9%82%d8%a7%d8%a8%d8%b1-%d8%a7%d9%84%d8%b3%d8%b9%d8%af%d9%8a%d9%8a%d9%86-%d8%a3%d8%b1%d8%b6-%d9%85%d8%b3%d9%83%d9%8a%d9%86%d8%a9\/","name":"\u0645\u0642\u0627\u0628\u0631 \u0627\u0644\u0633\u0639\u062f\u064a\u064a\u0646 - \u0623\u0631\u0636 \u0645\u0633\u0643\u064a\u0646\u0629 - Explore Agadir Souss Massa","isPartOf":{"@id":"https:\/\/explore-agadirsoussmassa.com\/ar\/#website"},"primaryImageOfPage":{"@id":"https:\/\/explore-agadirsoussmassa.com\/ar\/%d9%85%d9%82%d8%a7%d8%a8%d8%b1-%d8%a7%d9%84%d8%b3%d8%b9%d8%af%d9%8a%d9%8a%d9%86-%d8%a3%d8%b1%d8%b6-%d9%85%d8%b3%d9%83%d9%8a%d9%86%d8%a9\/#primaryimage"},"image":{"@id":"https:\/\/explore-agadirsoussmassa.com\/ar\/%d9%85%d9%82%d8%a7%d8%a8%d8%b1-%d8%a7%d9%84%d8%b3%d8%b9%d8%af%d9%8a%d9%8a%d9%86-%d8%a3%d8%b1%d8%b6-%d9%85%d8%b3%d9%83%d9%8a%d9%86%d8%a9\/#primaryimage"},"thumbnailUrl":"https:\/\/explore-agadirsoussmassa.com\/wp-content\/uploads\/2020\/04\/tombeaux-3.jpg","datePublished":"2020-04-10T16:13:16+00:00","dateModified":"2021-02-18T09:43:05+00:00","description":"\u062a\u0642\u0639 \u0642\u0631\u064a\u0629 \u0623\u0643\u0631\u0636 \u0639\u0644\u0649 \u0628\u0639\u062f 12 \u0643\u0644\u0645 \u0634\u0645\u0627\u0644 \u0634\u0631\u0642 \u0623\u0643\u0627\u062f\u064a\u0631\u060c \u0648\u062a\u062d\u0636\u0646 \u0642\u0628\u0648\u0631 \u0627\u0644\u0639\u062f\u064a\u062f \u0645\u0646 \u0627\u0644\u0623\u0645\u0631\u0627\u0621 \u0648\u0645\u0624\u0633\u0633\u064a \u0627\u0644\u062f\u0648\u0644\u0629 \u0627\u0644\u0633\u0639\u062f\u064a\u0629 \u0648\u0639\u0627\u0626\u0644\u0627\u062a\u0647\u0645.","breadcrumb":{"@id":"https:\/\/explore-agadirsoussmassa.com\/ar\/%d9%85%d9%82%d8%a7%d8%a8%d8%b1-%d8%a7%d9%84%d8%b3%d8%b9%d8%af%d9%8a%d9%8a%d9%86-%d8%a3%d8%b1%d8%b6-%d9%85%d8%b3%d9%83%d9%8a%d9%86%d8%a9\/#breadcrumb"},"inLanguage":"ar","potentialAction":[{"@type":"ReadAction","target":["https:\/\/explore-agadirsoussmassa.com\/ar\/%d9%85%d9%82%d8%a7%d8%a8%d8%b1-%d8%a7%d9%84%d8%b3%d8%b9%d8%af%d9%8a%d9%8a%d9%86-%d8%a3%d8%b1%d8%b6-%d9%85%d8%b3%d9%83%d9%8a%d9%86%d8%a9\/"]}]},{"@type":"ImageObject","inLanguage":"ar","@id":"https:\/\/explore-agadirsoussmassa.com\/ar\/%d9%85%d9%82%d8%a7%d8%a8%d8%b1-%d8%a7%d9%84%d8%b3%d8%b9%d8%af%d9%8a%d9%8a%d9%86-%d8%a3%d8%b1%d8%b6-%d9%85%d8%b3%d9%83%d9%8a%d9%86%d8%a9\/#primaryimage","url":"https:\/\/explore-agadirsoussmassa.com\/wp-content\/uploads\/2020\/04\/tombeaux-3.jpg","contentUrl":"https:\/\/explore-agadirsoussmassa.com\/wp-content\/uploads\/2020\/04\/tombeaux-3.jpg","width":878,"height":586},{"@type":"BreadcrumbList","@id":"https:\/\/explore-agadirsoussmassa.com\/ar\/%d9%85%d9%82%d8%a7%d8%a8%d8%b1-%d8%a7%d9%84%d8%b3%d8%b9%d8%af%d9%8a%d9%8a%d9%86-%d8%a3%d8%b1%d8%b6-%d9%85%d8%b3%d9%83%d9%8a%d9%86%d8%a9\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/explore-agadirsoussmassa.com\/ar\/"},{"@type":"ListItem","position":2,"name":"\u0645\u0642\u0627\u0628\u0631 \u0627\u0644\u0633\u0639\u062f\u064a\u064a\u0646 &#8211; \u0623\u0631\u0636 \u0645\u0633\u0643\u064a\u0646\u0629"}]},{"@type":"WebSite","@id":"https:\/\/explore-agadirsoussmassa.com\/ar\/#website","url":"https:\/\/explore-agadirsoussmassa.com\/ar\/","name":"Explore Agadir Souss Massa","description":"R\u00e9gion Souss Massa","publisher":{"@id":"https:\/\/explore-agadirsoussmassa.com\/ar\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/explore-agadirsoussmassa.com\/ar\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ar"},{"@type":"Organization","@id":"https:\/\/explore-agadirsoussmassa.com\/ar\/#organization","name":"SDR Tourisme Souss Massa","url":"https:\/\/explore-agadirsoussmassa.com\/ar\/","logo":{"@type":"ImageObject","inLanguage":"ar","@id":"https:\/\/explore-agadirsoussmassa.com\/ar\/#\/schema\/logo\/image\/","url":"https:\/\/zt88dgbrixj.preview.infomaniak.website\/wp-content\/uploads\/2020\/08\/logo-sdr.png","contentUrl":"https:\/\/zt88dgbrixj.preview.infomaniak.website\/wp-content\/uploads\/2020\/08\/logo-sdr.png","width":404,"height":286,"caption":"SDR Tourisme Souss Massa"},"image":{"@id":"https:\/\/explore-agadirsoussmassa.com\/ar\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Explore-Souss-Massa-111659480353930","https:\/\/www.instagram.com\/exploresoussmassamorocco\/","https:\/\/www.youtube.com\/channel\/UCpSGZAsRRpG40CeT3UcIcOA\/videos"]},{"@type":"Person","@id":"https:\/\/explore-agadirsoussmassa.com\/ar\/#\/schema\/person\/c019e4bcfef76d1c57d426107449d03e","name":"soussmassa","image":{"@type":"ImageObject","inLanguage":"ar","@id":"https:\/\/explore-agadirsoussmassa.com\/ar\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/71a3f2c422286f264199c19844c327bfdf2a272a6aab356511f8970061b8dc04?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/71a3f2c422286f264199c19844c327bfdf2a272a6aab356511f8970061b8dc04?s=96&d=mm&r=g","caption":"soussmassa"}}]}},"_links":{"self":[{"href":"https:\/\/explore-agadirsoussmassa.com\/ar\/wp-json\/wp\/v2\/posts\/34927","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/explore-agadirsoussmassa.com\/ar\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/explore-agadirsoussmassa.com\/ar\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/explore-agadirsoussmassa.com\/ar\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/explore-agadirsoussmassa.com\/ar\/wp-json\/wp\/v2\/comments?post=34927"}],"version-history":[{"count":6,"href":"https:\/\/explore-agadirsoussmassa.com\/ar\/wp-json\/wp\/v2\/posts\/34927\/revisions"}],"predecessor-version":[{"id":43696,"href":"https:\/\/explore-agadirsoussmassa.com\/ar\/wp-json\/wp\/v2\/posts\/34927\/revisions\/43696"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/explore-agadirsoussmassa.com\/ar\/wp-json\/wp\/v2\/media\/13619"}],"wp:attachment":[{"href":"https:\/\/explore-agadirsoussmassa.com\/ar\/wp-json\/wp\/v2\/media?parent=34927"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/explore-agadirsoussmassa.com\/ar\/wp-json\/wp\/v2\/categories?post=34927"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/explore-agadirsoussmassa.com\/ar\/wp-json\/wp\/v2\/tags?post=34927"},{"taxonomy":"powerkit_post_featured","embeddable":true,"href":"https:\/\/explore-agadirsoussmassa.com\/ar\/wp-json\/wp\/v2\/powerkit_post_featured?post=34927"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}