{"id":34560,"date":"2020-07-26T20:20:29","date_gmt":"2020-07-26T18:20:29","guid":{"rendered":"https:\/\/explore-agadirsoussmassa.com\/vallee-des-cedrats-randonnee\/"},"modified":"2021-03-04T15:58:43","modified_gmt":"2021-03-04T14:58:43","slug":"valle-de-cedrats-senderismo","status":"publish","type":"post","link":"https:\/\/explore-agadirsoussmassa.com\/es\/valle-de-cedrats-senderismo\/","title":{"rendered":"Valle de C\u00e9drats &#8211; Senderismo"},"content":{"rendered":"<div id=\"pl-gb34560-6a580d953c2a5\"  class=\"panel-layout\" ><div id=\"pg-gb34560-6a580d953c2a5-0\"  class=\"panel-grid panel-no-style\" ><div id=\"pgc-gb34560-6a580d953c2a5-0-0\"  class=\"panel-grid-cell\" ><div id=\"panel-gb34560-6a580d953c2a5-0-0-0\" class=\"so-panel widget widget_text panel-first-child panel-last-child\" data-index=\"0\" ><div id=\"sdrstyle\" class=\"panel-widget-style panel-widget-style-for-gb34560-6a580d953c2a5-0-0-0\" >\t\t\t<div class=\"textwidget\"><h3 id=\"el-valle-de-los-frutos-sagrados\">El valle de los frutos sagrados<\/h3>\n<p><em>Duraci\u00f3n del trayecto desde Agadir: 1h40mn<\/em><\/p>\n<\/div>\n\t\t<\/div><\/div><\/div><\/div><div id=\"pg-gb34560-6a580d953c2a5-1\"  class=\"panel-grid panel-no-style\" ><div id=\"pgc-gb34560-6a580d953c2a5-1-0\"  class=\"panel-grid-cell\" ><div id=\"panel-gb34560-6a580d953c2a5-1-0-0\" class=\"so-panel widget widget_text panel-first-child panel-last-child\" data-index=\"1\" ><div id=\"sdrstyle\" class=\"panel-widget-style panel-widget-style-for-gb34560-6a580d953c2a5-1-0-0\" >\t\t\t<div class=\"textwidget\"><div class=\"thirdtitle bigsize\" style=\"text-transform: uppercase;\">frutos sagrados = frutos escondidos<\/div>\n<p>El Valle de C\u00e9drats debe su nombre a una variedad de grandes limones cultivados en las orillas de este Oued (r\u00edo). Se trata de una magn\u00edfica caminata en un ca\u00f1\u00f3n de 3 kms donde la vegetaci\u00f3n y el cidro van apareciendo poco a poco\u2026.<\/p>\n<p>Los c\u00edticos eran muy populares entre los jud\u00edos. Los bereberes han perpetuado la cultura y la exportan hoy.<\/p>\n<\/div>\n\t\t<\/div><\/div><\/div><\/div><\/div>\n\n<div class=\"cnvs-block-justified-gallery cnvs-block-justified-gallery-1595791082621\" >\n<div\n\tclass='gallery cnvs-gallery-type-justified'\n\tdata-jg-margins=\"10\"\n\tdata-jg-border=\"-10\"\n\tdata-jg-row-height=\"258\"\n\tdata-jg-max-row-height=\"220%\"\n\tdata-jg-last-row=\"justify\"\n\tdata-jg-captions=\"true\"\n\tdata-jg-randomize=\"false\"\n>\n\t\t\t<figure class=\"gallery-item\">\n\t\t\t\t\t\t\t<a href=\"https:\/\/explore-agadirsoussmassa.com\/wp-content\/uploads\/2020\/02\/cedrats-23.png\">\n\t\t\t\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1160\" height=\"870\" src=\"https:\/\/explore-agadirsoussmassa.com\/wp-content\/uploads\/2020\/02\/cedrats-23-1160x870.png\" class=\"attachment-csco-1160 size-csco-1160\" alt=\"C\u00e9drats - Vall\u00e9e des C\u00e9drats\" srcset=\"https:\/\/explore-agadirsoussmassa.com\/wp-content\/uploads\/2020\/02\/cedrats-23-1160x870.png 1160w, https:\/\/explore-agadirsoussmassa.com\/wp-content\/uploads\/2020\/02\/cedrats-23-800x600.png 800w, https:\/\/explore-agadirsoussmassa.com\/wp-content\/uploads\/2020\/02\/cedrats-23-320x240.png 320w, https:\/\/explore-agadirsoussmassa.com\/wp-content\/uploads\/2020\/02\/cedrats-23-1536x1152.png 1536w, https:\/\/explore-agadirsoussmassa.com\/wp-content\/uploads\/2020\/02\/cedrats-23-300x225.png 300w, https:\/\/explore-agadirsoussmassa.com\/wp-content\/uploads\/2020\/02\/cedrats-23-560x420.png 560w, https:\/\/explore-agadirsoussmassa.com\/wp-content\/uploads\/2020\/02\/cedrats-23.png 1600w\" sizes=\"auto, (max-width: 1160px) 100vw, 1160px\" \/>\n\t\t\t\t\t\t\t<\/a>\n\t\t\t\n\t\t\t<div class=\"caption wp-caption-text gallery-caption\">Cidro &#8211; Valle de C\u00e9drats<\/div>\t\t<\/figure>\n\t\t\t\t<figure class=\"gallery-item\">\n\t\t\t\t\t\t\t<a href=\"https:\/\/explore-agadirsoussmassa.com\/wp-content\/uploads\/2020\/02\/cedrats-24.png\">\n\t\t\t\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1160\" height=\"870\" src=\"https:\/\/explore-agadirsoussmassa.com\/wp-content\/uploads\/2020\/02\/cedrats-24-1160x870.png\" class=\"attachment-csco-1160 size-csco-1160\" alt=\"Vall\u00e9e des C\u00e9drats\" srcset=\"https:\/\/explore-agadirsoussmassa.com\/wp-content\/uploads\/2020\/02\/cedrats-24-1160x870.png 1160w, https:\/\/explore-agadirsoussmassa.com\/wp-content\/uploads\/2020\/02\/cedrats-24-800x600.png 800w, https:\/\/explore-agadirsoussmassa.com\/wp-content\/uploads\/2020\/02\/cedrats-24-320x240.png 320w, https:\/\/explore-agadirsoussmassa.com\/wp-content\/uploads\/2020\/02\/cedrats-24-1536x1152.png 1536w, https:\/\/explore-agadirsoussmassa.com\/wp-content\/uploads\/2020\/02\/cedrats-24-300x225.png 300w, https:\/\/explore-agadirsoussmassa.com\/wp-content\/uploads\/2020\/02\/cedrats-24-560x420.png 560w, https:\/\/explore-agadirsoussmassa.com\/wp-content\/uploads\/2020\/02\/cedrats-24.png 1600w\" sizes=\"auto, (max-width: 1160px) 100vw, 1160px\" \/>\n\t\t\t\t\t\t\t<\/a>\n\t\t\t\n\t\t\t<div class=\"caption wp-caption-text gallery-caption\">Valle de C\u00e9drats<\/div>\t\t<\/figure>\n\t\t\t\t<figure class=\"gallery-item\">\n\t\t\t\t\t\t\t<a href=\"https:\/\/explore-agadirsoussmassa.com\/wp-content\/uploads\/2020\/02\/cedrats-26.png\">\n\t\t\t\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1160\" height=\"870\" src=\"https:\/\/explore-agadirsoussmassa.com\/wp-content\/uploads\/2020\/02\/cedrats-26-1160x870.png\" class=\"attachment-csco-1160 size-csco-1160\" alt=\"Canyon - Vall\u00e9e des C\u00e9drats\" srcset=\"https:\/\/explore-agadirsoussmassa.com\/wp-content\/uploads\/2020\/02\/cedrats-26-1160x870.png 1160w, https:\/\/explore-agadirsoussmassa.com\/wp-content\/uploads\/2020\/02\/cedrats-26-800x600.png 800w, https:\/\/explore-agadirsoussmassa.com\/wp-content\/uploads\/2020\/02\/cedrats-26-320x240.png 320w, https:\/\/explore-agadirsoussmassa.com\/wp-content\/uploads\/2020\/02\/cedrats-26-1536x1152.png 1536w, https:\/\/explore-agadirsoussmassa.com\/wp-content\/uploads\/2020\/02\/cedrats-26-300x225.png 300w, https:\/\/explore-agadirsoussmassa.com\/wp-content\/uploads\/2020\/02\/cedrats-26-560x420.png 560w, https:\/\/explore-agadirsoussmassa.com\/wp-content\/uploads\/2020\/02\/cedrats-26.png 1600w\" sizes=\"auto, (max-width: 1160px) 100vw, 1160px\" \/>\n\t\t\t\t\t\t\t<\/a>\n\t\t\t\n\t\t\t<div class=\"caption wp-caption-text gallery-caption\">Ca\u00f1\u00f3n &#8211; Valle de C\u00e9drats<\/div>\t\t<\/figure>\n\t\t<\/div>\n\n<\/div>\n\n<div id=\"pl-gb34560-6a580d953e5e1\"  class=\"panel-layout\" ><div id=\"pg-gb34560-6a580d953e5e1-0\"  class=\"panel-grid panel-no-style\" ><div id=\"pgc-gb34560-6a580d953e5e1-0-0\"  class=\"panel-grid-cell\" ><div id=\"panel-gb34560-6a580d953e5e1-0-0-0\" class=\"so-panel widget widget_text panel-first-child panel-last-child\" data-index=\"0\" >\t\t\t<div class=\"textwidget\"><p><em><span style=\"font-weight: 400;\">C\u00f3mo llegar:<\/span><\/em><\/p>\n<p><span style=\"font-weight: 400;\">Desde Agadir, tome la carretera del aeropuerto en direcci\u00f3n a Taroudant.<\/span> <span style=\"font-weight: 400;\">Despu\u00e9s de Sebt Guerdane, gire a la derecha hacia el pueblo de Assads (30.376455, -8.921305) y luego gire a la izquierda en el punto (30.352840, -8.930425). Contin\u00fae hacia Tourght y luego cruce el pueblo de Assads (30.201727, -8.859966), contin\u00fae la pista hacia el \u00faltimo pueblo: Douar Tamguinsift donde dejar\u00e1 su autom\u00f3vil (imposible continuar).<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Contin\u00fae a pie por un peque\u00f1o sendero a lo largo del canal de riego (seguia). Solo hay que remontar el r\u00edo (oued) en direcci\u00f3n sureste, hasta encontrar una presa que retiene agua al pie de los acantilados.<\/span> <span style=\"font-weight: 400;\">La caminata por el oued es de un poco m\u00e1s de 3 kil\u00f3metros y le llevar\u00e1 2 horas.<\/span><\/p>\n<p><em>Actividades <span style=\"font-weight: 400;\">:<\/span><\/em><\/p>\n<ul>\n<li><span style=\"font-weight: 400;\">Excursionismo<\/span><\/li>\n<li>Descubrimiento del C\u00e9drat (cidro)<\/li>\n<\/ul>\n<p><em>Recomendaciones:<\/em><\/p>\n<ul>\n<li><span style=\"font-weight: 400;\">Excursi\u00f3n a combinar con la visita de la Ciudad de <a href=\"\/murallas-medina-y-zocos-de-taroudant\/\">Taroudant<\/a> o el <a href=\"\/palmeraie-de-tioute-la-excursion-familiar\/\">Oasis de Tioute<\/a>.<\/span><\/li>\n<\/ul>\n<\/div>\n\t\t<\/div><\/div><\/div><\/div>","protected":false},"excerpt":{"rendered":"<div class=\"post-excerpt\">La Vall\u00e9e des C\u00e9drats &#8211; Magn\u00edfica caminata desde Taroudant en un ca\u00f1\u00f3n de 3 km donde la cidra, una especie de limones grandes, aparece poco a poco.<\/div>\n<div class=\"post-more\"><a href=\"https:\/\/explore-agadirsoussmassa.com\/es\/valle-de-cedrats-senderismo\/\" class=\"button button-primary button-effect\"><span>Ver detalle<\/span><span><i class=\"cs-icon cs-icon-arrow-right\"><\/i><\/span><\/a><\/div>\n","protected":false},"author":1,"featured_media":6243,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[416,127],"tags":[],"powerkit_post_featured":[],"class_list":{"0":"post-34560","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-anti-atlas-4","8":"category-montanas"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.0 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Vall\u00e9e des c\u00e9drats - senderismo - Explore Agadir Souss Massa<\/title>\n<meta name=\"description\" content=\"La Vall\u00e9e des c\u00e9drats - Magn\u00edfica caminata desde Taroudant en un ca\u00f1\u00f3n de 3 km donde crece el cidro, una especie de limones grandes\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/explore-agadirsoussmassa.com\/es\/valle-de-cedrats-senderismo\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Vall\u00e9e des c\u00e9drats - senderismo - Explore Agadir Souss Massa\" \/>\n<meta property=\"og:description\" content=\"La Vall\u00e9e des c\u00e9drats - Magn\u00edfica caminata desde Taroudant en un ca\u00f1\u00f3n de 3 km donde crece el cidro, una especie de limones grandes\" \/>\n<meta property=\"og:url\" content=\"https:\/\/explore-agadirsoussmassa.com\/es\/valle-de-cedrats-senderismo\/\" \/>\n<meta property=\"og:site_name\" content=\"Explore Agadir Souss Massa\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Explore-Souss-Massa-111659480353930\" \/>\n<meta property=\"article:published_time\" content=\"2020-07-26T18:20:29+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-03-04T14:58:43+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/explore-agadirsoussmassa.com\/wp-content\/uploads\/2020\/02\/cedrats-2-large-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1903\" \/>\n\t<meta property=\"og:image:height\" content=\"600\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"soussmassa\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"soussmassa\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/explore-agadirsoussmassa.com\/es\/valle-de-cedrats-senderismo\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/explore-agadirsoussmassa.com\/es\/valle-de-cedrats-senderismo\/\"},\"author\":{\"name\":\"soussmassa\",\"@id\":\"https:\/\/explore-agadirsoussmassa.com\/es\/#\/schema\/person\/c019e4bcfef76d1c57d426107449d03e\"},\"headline\":\"Valle de C\u00e9drats &#8211; Senderismo\",\"datePublished\":\"2020-07-26T18:20:29+00:00\",\"dateModified\":\"2021-03-04T14:58:43+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/explore-agadirsoussmassa.com\/es\/valle-de-cedrats-senderismo\/\"},\"wordCount\":6,\"publisher\":{\"@id\":\"https:\/\/explore-agadirsoussmassa.com\/es\/#organization\"},\"image\":{\"@id\":\"https:\/\/explore-agadirsoussmassa.com\/es\/valle-de-cedrats-senderismo\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/explore-agadirsoussmassa.com\/wp-content\/uploads\/2020\/02\/cedrats-2-large-1.jpg\",\"articleSection\":[\"Anti Atlas\",\"Monta\u00f1as\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/explore-agadirsoussmassa.com\/es\/valle-de-cedrats-senderismo\/\",\"url\":\"https:\/\/explore-agadirsoussmassa.com\/es\/valle-de-cedrats-senderismo\/\",\"name\":\"Vall\u00e9e des c\u00e9drats - senderismo - Explore Agadir Souss Massa\",\"isPartOf\":{\"@id\":\"https:\/\/explore-agadirsoussmassa.com\/es\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/explore-agadirsoussmassa.com\/es\/valle-de-cedrats-senderismo\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/explore-agadirsoussmassa.com\/es\/valle-de-cedrats-senderismo\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/explore-agadirsoussmassa.com\/wp-content\/uploads\/2020\/02\/cedrats-2-large-1.jpg\",\"datePublished\":\"2020-07-26T18:20:29+00:00\",\"dateModified\":\"2021-03-04T14:58:43+00:00\",\"description\":\"La Vall\u00e9e des c\u00e9drats - Magn\u00edfica caminata desde Taroudant en un ca\u00f1\u00f3n de 3 km donde crece el cidro, una especie de limones grandes\",\"breadcrumb\":{\"@id\":\"https:\/\/explore-agadirsoussmassa.com\/es\/valle-de-cedrats-senderismo\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/explore-agadirsoussmassa.com\/es\/valle-de-cedrats-senderismo\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/explore-agadirsoussmassa.com\/es\/valle-de-cedrats-senderismo\/#primaryimage\",\"url\":\"https:\/\/explore-agadirsoussmassa.com\/wp-content\/uploads\/2020\/02\/cedrats-2-large-1.jpg\",\"contentUrl\":\"https:\/\/explore-agadirsoussmassa.com\/wp-content\/uploads\/2020\/02\/cedrats-2-large-1.jpg\",\"width\":1903,\"height\":600},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/explore-agadirsoussmassa.com\/es\/valle-de-cedrats-senderismo\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/explore-agadirsoussmassa.com\/es\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Valle de C\u00e9drats &#8211; Senderismo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/explore-agadirsoussmassa.com\/es\/#website\",\"url\":\"https:\/\/explore-agadirsoussmassa.com\/es\/\",\"name\":\"Explore Agadir Souss Massa\",\"description\":\"R\u00e9gion Souss Massa\",\"publisher\":{\"@id\":\"https:\/\/explore-agadirsoussmassa.com\/es\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/explore-agadirsoussmassa.com\/es\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/explore-agadirsoussmassa.com\/es\/#organization\",\"name\":\"SDR Tourisme Souss Massa\",\"url\":\"https:\/\/explore-agadirsoussmassa.com\/es\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/explore-agadirsoussmassa.com\/es\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/zt88dgbrixj.preview.infomaniak.website\/wp-content\/uploads\/2020\/08\/logo-sdr.png\",\"contentUrl\":\"https:\/\/zt88dgbrixj.preview.infomaniak.website\/wp-content\/uploads\/2020\/08\/logo-sdr.png\",\"width\":404,\"height\":286,\"caption\":\"SDR Tourisme Souss Massa\"},\"image\":{\"@id\":\"https:\/\/explore-agadirsoussmassa.com\/es\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/Explore-Souss-Massa-111659480353930\",\"https:\/\/www.instagram.com\/exploresoussmassamorocco\/\",\"https:\/\/www.youtube.com\/channel\/UCpSGZAsRRpG40CeT3UcIcOA\/videos\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/explore-agadirsoussmassa.com\/es\/#\/schema\/person\/c019e4bcfef76d1c57d426107449d03e\",\"name\":\"soussmassa\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/explore-agadirsoussmassa.com\/es\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/71a3f2c422286f264199c19844c327bfdf2a272a6aab356511f8970061b8dc04?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/71a3f2c422286f264199c19844c327bfdf2a272a6aab356511f8970061b8dc04?s=96&d=mm&r=g\",\"caption\":\"soussmassa\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Vall\u00e9e des c\u00e9drats - senderismo - Explore Agadir Souss Massa","description":"La Vall\u00e9e des c\u00e9drats - Magn\u00edfica caminata desde Taroudant en un ca\u00f1\u00f3n de 3 km donde crece el cidro, una especie de limones grandes","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/explore-agadirsoussmassa.com\/es\/valle-de-cedrats-senderismo\/","og_locale":"es_ES","og_type":"article","og_title":"Vall\u00e9e des c\u00e9drats - senderismo - Explore Agadir Souss Massa","og_description":"La Vall\u00e9e des c\u00e9drats - Magn\u00edfica caminata desde Taroudant en un ca\u00f1\u00f3n de 3 km donde crece el cidro, una especie de limones grandes","og_url":"https:\/\/explore-agadirsoussmassa.com\/es\/valle-de-cedrats-senderismo\/","og_site_name":"Explore Agadir Souss Massa","article_publisher":"https:\/\/www.facebook.com\/Explore-Souss-Massa-111659480353930","article_published_time":"2020-07-26T18:20:29+00:00","article_modified_time":"2021-03-04T14:58:43+00:00","og_image":[{"width":1903,"height":600,"url":"https:\/\/explore-agadirsoussmassa.com\/wp-content\/uploads\/2020\/02\/cedrats-2-large-1.jpg","type":"image\/jpeg"}],"author":"soussmassa","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"soussmassa"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/explore-agadirsoussmassa.com\/es\/valle-de-cedrats-senderismo\/#article","isPartOf":{"@id":"https:\/\/explore-agadirsoussmassa.com\/es\/valle-de-cedrats-senderismo\/"},"author":{"name":"soussmassa","@id":"https:\/\/explore-agadirsoussmassa.com\/es\/#\/schema\/person\/c019e4bcfef76d1c57d426107449d03e"},"headline":"Valle de C\u00e9drats &#8211; Senderismo","datePublished":"2020-07-26T18:20:29+00:00","dateModified":"2021-03-04T14:58:43+00:00","mainEntityOfPage":{"@id":"https:\/\/explore-agadirsoussmassa.com\/es\/valle-de-cedrats-senderismo\/"},"wordCount":6,"publisher":{"@id":"https:\/\/explore-agadirsoussmassa.com\/es\/#organization"},"image":{"@id":"https:\/\/explore-agadirsoussmassa.com\/es\/valle-de-cedrats-senderismo\/#primaryimage"},"thumbnailUrl":"https:\/\/explore-agadirsoussmassa.com\/wp-content\/uploads\/2020\/02\/cedrats-2-large-1.jpg","articleSection":["Anti Atlas","Monta\u00f1as"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/explore-agadirsoussmassa.com\/es\/valle-de-cedrats-senderismo\/","url":"https:\/\/explore-agadirsoussmassa.com\/es\/valle-de-cedrats-senderismo\/","name":"Vall\u00e9e des c\u00e9drats - senderismo - Explore Agadir Souss Massa","isPartOf":{"@id":"https:\/\/explore-agadirsoussmassa.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/explore-agadirsoussmassa.com\/es\/valle-de-cedrats-senderismo\/#primaryimage"},"image":{"@id":"https:\/\/explore-agadirsoussmassa.com\/es\/valle-de-cedrats-senderismo\/#primaryimage"},"thumbnailUrl":"https:\/\/explore-agadirsoussmassa.com\/wp-content\/uploads\/2020\/02\/cedrats-2-large-1.jpg","datePublished":"2020-07-26T18:20:29+00:00","dateModified":"2021-03-04T14:58:43+00:00","description":"La Vall\u00e9e des c\u00e9drats - Magn\u00edfica caminata desde Taroudant en un ca\u00f1\u00f3n de 3 km donde crece el cidro, una especie de limones grandes","breadcrumb":{"@id":"https:\/\/explore-agadirsoussmassa.com\/es\/valle-de-cedrats-senderismo\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/explore-agadirsoussmassa.com\/es\/valle-de-cedrats-senderismo\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/explore-agadirsoussmassa.com\/es\/valle-de-cedrats-senderismo\/#primaryimage","url":"https:\/\/explore-agadirsoussmassa.com\/wp-content\/uploads\/2020\/02\/cedrats-2-large-1.jpg","contentUrl":"https:\/\/explore-agadirsoussmassa.com\/wp-content\/uploads\/2020\/02\/cedrats-2-large-1.jpg","width":1903,"height":600},{"@type":"BreadcrumbList","@id":"https:\/\/explore-agadirsoussmassa.com\/es\/valle-de-cedrats-senderismo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/explore-agadirsoussmassa.com\/es\/"},{"@type":"ListItem","position":2,"name":"Valle de C\u00e9drats &#8211; Senderismo"}]},{"@type":"WebSite","@id":"https:\/\/explore-agadirsoussmassa.com\/es\/#website","url":"https:\/\/explore-agadirsoussmassa.com\/es\/","name":"Explore Agadir Souss Massa","description":"R\u00e9gion Souss Massa","publisher":{"@id":"https:\/\/explore-agadirsoussmassa.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/explore-agadirsoussmassa.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/explore-agadirsoussmassa.com\/es\/#organization","name":"SDR Tourisme Souss Massa","url":"https:\/\/explore-agadirsoussmassa.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/explore-agadirsoussmassa.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/zt88dgbrixj.preview.infomaniak.website\/wp-content\/uploads\/2020\/08\/logo-sdr.png","contentUrl":"https:\/\/zt88dgbrixj.preview.infomaniak.website\/wp-content\/uploads\/2020\/08\/logo-sdr.png","width":404,"height":286,"caption":"SDR Tourisme Souss Massa"},"image":{"@id":"https:\/\/explore-agadirsoussmassa.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Explore-Souss-Massa-111659480353930","https:\/\/www.instagram.com\/exploresoussmassamorocco\/","https:\/\/www.youtube.com\/channel\/UCpSGZAsRRpG40CeT3UcIcOA\/videos"]},{"@type":"Person","@id":"https:\/\/explore-agadirsoussmassa.com\/es\/#\/schema\/person\/c019e4bcfef76d1c57d426107449d03e","name":"soussmassa","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/explore-agadirsoussmassa.com\/es\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/71a3f2c422286f264199c19844c327bfdf2a272a6aab356511f8970061b8dc04?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/71a3f2c422286f264199c19844c327bfdf2a272a6aab356511f8970061b8dc04?s=96&d=mm&r=g","caption":"soussmassa"}}]}},"_links":{"self":[{"href":"https:\/\/explore-agadirsoussmassa.com\/es\/wp-json\/wp\/v2\/posts\/34560","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/explore-agadirsoussmassa.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/explore-agadirsoussmassa.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/explore-agadirsoussmassa.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/explore-agadirsoussmassa.com\/es\/wp-json\/wp\/v2\/comments?post=34560"}],"version-history":[{"count":6,"href":"https:\/\/explore-agadirsoussmassa.com\/es\/wp-json\/wp\/v2\/posts\/34560\/revisions"}],"predecessor-version":[{"id":40935,"href":"https:\/\/explore-agadirsoussmassa.com\/es\/wp-json\/wp\/v2\/posts\/34560\/revisions\/40935"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/explore-agadirsoussmassa.com\/es\/wp-json\/wp\/v2\/media\/6243"}],"wp:attachment":[{"href":"https:\/\/explore-agadirsoussmassa.com\/es\/wp-json\/wp\/v2\/media?parent=34560"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/explore-agadirsoussmassa.com\/es\/wp-json\/wp\/v2\/categories?post=34560"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/explore-agadirsoussmassa.com\/es\/wp-json\/wp\/v2\/tags?post=34560"},{"taxonomy":"powerkit_post_featured","embeddable":true,"href":"https:\/\/explore-agadirsoussmassa.com\/es\/wp-json\/wp\/v2\/powerkit_post_featured?post=34560"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}