{"id":34572,"date":"2020-07-26T00:11:41","date_gmt":"2020-07-25T22:11:41","guid":{"rendered":"https:\/\/explore-agadirsoussmassa.com\/parc-national-d-iriki-traversee-foum-zguid-mhamid\/"},"modified":"2021-03-04T16:00:58","modified_gmt":"2021-03-04T15:00:58","slug":"parque-nacional-iriki-cruzando-foum-zguid-mhamid","status":"publish","type":"post","link":"https:\/\/explore-agadirsoussmassa.com\/es\/parque-nacional-iriki-cruzando-foum-zguid-mhamid\/","title":{"rendered":"Parque Nacional Iriki: Cruzando Foum Zguid &#8211; M&#8217;hamid"},"content":{"rendered":"<div id=\"pl-gb34572-6a57f17acb5cd\"  class=\"panel-layout\" ><div id=\"pg-gb34572-6a57f17acb5cd-0\"  class=\"panel-grid panel-no-style\" ><div id=\"pgc-gb34572-6a57f17acb5cd-0-0\"  class=\"panel-grid-cell\" ><div id=\"panel-gb34572-6a57f17acb5cd-0-0-0\" class=\"so-panel widget widget_text panel-first-child panel-last-child\" data-index=\"0\" ><div id=\"sdrstyle\" class=\"panel-widget-style panel-widget-style-for-gb34572-6a57f17acb5cd-0-0-0\" >\t\t\t<div class=\"textwidget\"><h3 id=\"parque-nacional-iriqui\">Parque Nacional Iriqui<\/h3>\n<p><em>Trayecto desde Agadir: 7 horas<\/em><\/p>\n<\/div>\n\t\t<\/div><\/div><\/div><\/div><div id=\"pg-gb34572-6a57f17acb5cd-1\"  class=\"panel-grid panel-no-style\" ><div id=\"pgc-gb34572-6a57f17acb5cd-1-0\"  class=\"panel-grid-cell\" ><div id=\"panel-gb34572-6a57f17acb5cd-1-0-0\" class=\"so-panel widget widget_text panel-first-child panel-last-child\" data-index=\"1\" ><div id=\"sdrstyle\" class=\"panel-widget-style panel-widget-style-for-gb34572-6a57f17acb5cd-1-0-0\" >\t\t\t<div class=\"textwidget\"><div class=\"thirdtitle bigsize\" style=\"text-transform: uppercase;\">Veh\u00edculo 4&#215;4 obligatorio<\/div>\n<p>El lago Iriki constituye una superficie plana muy extensa y seca en ciertas zonas.<\/p>\n<p>Algunos campamentos se encuentran repartidos por el Parque y existe la posibilidad de hacer algunas compras. La comodidad es rudimentaria para hacer vivac, pero la experiencia no tiene parang\u00f3n. Los paisajes des\u00e9rticos del <a href=\"\/parque-nacional-iriqui-presentacion\/\">Parque Nacional<\/a> son representativos del sur de Marruecos: estepas, acacias, tamariscos &#8230;<\/p>\n<p>Hoy en d\u00eda el lago Iriki suele estar seco, pero en per\u00edodos h\u00famedos se llena temporalmente con unos cent\u00edmetros de agua. Durante la temporada de lluvias, quiz\u00e1s pueda observar las aves migratorias, flamencos rosados y gansos salvajes.<\/p>\n<p>Si piensa visitar el lago despu\u00e9s de un mes h\u00famedo (octubre, noviembre, diciembre), inf\u00f3rmese previamente del estado del terreno pues el lago puede convertirse en una trampa para los veh\u00edculos debido al barro.<\/p>\n<\/div>\n\t\t<\/div><\/div><\/div><\/div><\/div>\n\n<div class=\"cnvs-block-justified-gallery cnvs-block-justified-gallery-1595718850215\" >\n<div\n\tclass='gallery cnvs-gallery-type-justified'\n\tdata-jg-margins=\"10\"\n\tdata-jg-border=\"-10\"\n\tdata-jg-row-height=\"258\"\n\tdata-jg-max-row-height=\"220%\"\n\tdata-jg-last-row=\"justify\"\n\tdata-jg-captions=\"true\"\n\tdata-jg-randomize=\"false\"\n>\n\t\t\t<figure class=\"gallery-item\">\n\t\t\t\t\t\t\t<a href=\"https:\/\/explore-agadirsoussmassa.com\/wp-content\/uploads\/2020\/02\/iriqui-64.png\">\n\t\t\t\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1160\" height=\"870\" src=\"https:\/\/explore-agadirsoussmassa.com\/wp-content\/uploads\/2020\/02\/iriqui-64-1160x870.png\" class=\"attachment-csco-1160 size-csco-1160\" alt=\"Zone de Bivouac - Dunes de Chegaga\" srcset=\"https:\/\/explore-agadirsoussmassa.com\/wp-content\/uploads\/2020\/02\/iriqui-64-1160x870.png 1160w, https:\/\/explore-agadirsoussmassa.com\/wp-content\/uploads\/2020\/02\/iriqui-64-800x600.png 800w, https:\/\/explore-agadirsoussmassa.com\/wp-content\/uploads\/2020\/02\/iriqui-64-320x240.png 320w, https:\/\/explore-agadirsoussmassa.com\/wp-content\/uploads\/2020\/02\/iriqui-64-300x225.png 300w, https:\/\/explore-agadirsoussmassa.com\/wp-content\/uploads\/2020\/02\/iriqui-64-560x420.png 560w, https:\/\/explore-agadirsoussmassa.com\/wp-content\/uploads\/2020\/02\/iriqui-64.png 1200w\" sizes=\"auto, (max-width: 1160px) 100vw, 1160px\" \/>\n\t\t\t\t\t\t\t<\/a>\n\t\t\t\n\t\t\t<div class=\"caption wp-caption-text gallery-caption\">\u00c1rea de vivac &#8211; dunas de Chegaga<\/div>\t\t<\/figure>\n\t\t\t\t<figure class=\"gallery-item\">\n\t\t\t\t\t\t\t<a href=\"https:\/\/explore-agadirsoussmassa.com\/wp-content\/uploads\/2020\/02\/iriki-etoile.png\">\n\t\t\t\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1040\" height=\"780\" src=\"https:\/\/explore-agadirsoussmassa.com\/wp-content\/uploads\/2020\/02\/iriki-etoile.png\" class=\"attachment-csco-1160 size-csco-1160\" alt=\"Pause photo - Lac d&#039;Iriqui\" srcset=\"https:\/\/explore-agadirsoussmassa.com\/wp-content\/uploads\/2020\/02\/iriki-etoile.png 1040w, https:\/\/explore-agadirsoussmassa.com\/wp-content\/uploads\/2020\/02\/iriki-etoile-800x600.png 800w, https:\/\/explore-agadirsoussmassa.com\/wp-content\/uploads\/2020\/02\/iriki-etoile-320x240.png 320w, https:\/\/explore-agadirsoussmassa.com\/wp-content\/uploads\/2020\/02\/iriki-etoile-300x225.png 300w, https:\/\/explore-agadirsoussmassa.com\/wp-content\/uploads\/2020\/02\/iriki-etoile-560x420.png 560w\" sizes=\"auto, (max-width: 1040px) 100vw, 1040px\" \/>\n\t\t\t\t\t\t\t<\/a>\n\t\t\t\n\t\t\t<div class=\"caption wp-caption-text gallery-caption\">Pausa fotogr\u00e1fica &#8211; Lago Iriqui<\/div>\t\t<\/figure>\n\t\t\t\t<figure class=\"gallery-item\">\n\t\t\t\t\t\t\t<a href=\"https:\/\/explore-agadirsoussmassa.com\/wp-content\/uploads\/2020\/05\/iriki-34.png\">\n\t\t\t\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1160\" height=\"868\" src=\"https:\/\/explore-agadirsoussmassa.com\/wp-content\/uploads\/2020\/05\/iriki-34-1160x868.png\" class=\"attachment-csco-1160 size-csco-1160\" alt=\"Zone de Bivouac - Dunes de Chegaga\" srcset=\"https:\/\/explore-agadirsoussmassa.com\/wp-content\/uploads\/2020\/05\/iriki-34-1160x868.png 1160w, https:\/\/explore-agadirsoussmassa.com\/wp-content\/uploads\/2020\/05\/iriki-34-800x599.png 800w, https:\/\/explore-agadirsoussmassa.com\/wp-content\/uploads\/2020\/05\/iriki-34-320x240.png 320w, https:\/\/explore-agadirsoussmassa.com\/wp-content\/uploads\/2020\/05\/iriki-34-300x225.png 300w, https:\/\/explore-agadirsoussmassa.com\/wp-content\/uploads\/2020\/05\/iriki-34-560x420.png 560w, https:\/\/explore-agadirsoussmassa.com\/wp-content\/uploads\/2020\/05\/iriki-34.png 1496w\" sizes=\"auto, (max-width: 1160px) 100vw, 1160px\" \/>\n\t\t\t\t\t\t\t<\/a>\n\t\t\t\n\t\t\t<div class=\"caption wp-caption-text gallery-caption\">\u00c1rea de vivac &#8211; dunas de Chegaga<\/div>\t\t<\/figure>\n\t\t<\/div>\n\n<\/div>\n\n<div id=\"pl-gb34572-6a57f17ace00a\"  class=\"panel-layout\" ><div id=\"pg-gb34572-6a57f17ace00a-0\"  class=\"panel-grid panel-no-style\" ><div id=\"pgc-gb34572-6a57f17ace00a-0-0\"  class=\"panel-grid-cell\" ><div id=\"panel-gb34572-6a57f17ace00a-0-0-0\" class=\"so-panel widget widget_text panel-first-child panel-last-child\" data-index=\"0\" >\t\t\t<div class=\"textwidget\"><p><em><span style=\"font-weight: 400;\">C\u00f3mo llegar:<\/span><\/em><\/p>\n<p>Desde Agadir, tome la direcci\u00f3n de Akka Ighane (29.838782, -7.499735) y luego en la intersecci\u00f3n con la N12 gire a la izquierda hacia <a href=\"\/oasis-de-tissint-akka-nait-sidi\/\">Tissint<\/a> &#8211; <a href=\"\/es\/oasis-foum-zguid-allogoum\/\">Foum Zguid<\/a> para unirse al Parque Nacional Iriki al que se puede acceder por la pista que comienza en el punto (30.060216, -6.869288).<\/p>\n<p>Se deja el alquitr\u00e1n por una pista pedregosa a lo largo del Jbel Madouer Kbir y Sghir para llegar al lago Iriqui, que se encuentra entre las localidades de Foum Zguid y M&#8217;hamid El Ghizlane.<\/p>\n<p>Reserva tu <a href=\"\/actividad-familiar-vivac-en-el-desierto\/\" target=\"_blank\" rel=\"noopener\">vivac<\/a> en el Parque Nacional para pasar la noche all\u00ed. Al d\u00eda siguiente, tome la direcci\u00f3n de Erg Chegaga donde algunas dunas est\u00e1n a unos 50\/60 metros.<\/p>\n<p>Luego direcci\u00f3n M&#8217;Hamid por una pista entre las dunas y los tamariscos donde ser\u00e1 imprescindible disponer de un buen veh\u00edculo 4&#215;4 pero puede ir acompa\u00f1ado de un gu\u00eda. En M&#8217;Hamid, encontrar\u00e1 la carretera asfaltada.<\/p>\n<p>La traves\u00eda tarda de 5 a 6 horas.<\/p>\n<p>&nbsp;<\/p>\n<p><em>Actividad<span style=\"font-weight: 400;\">es:<\/span><\/em><\/p>\n<ul>\n<li><span style=\"font-weight: 400;\">4 * 4 pistas<\/span><\/li>\n<li><span style=\"font-weight: 400;\">Vivac<\/span><\/li>\n<li><span style=\"font-weight: 400;\">Caminar en las dunas<\/span><\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<\/div>\n\t\t<\/div><\/div><\/div><\/div>","protected":false},"excerpt":{"rendered":"<div class=\"post-excerpt\">El Parque Nacional Iriqui se encuentra entre las provincias de Tata y Zagora y se puede cruzar en veh\u00edculo 4&#215;4 desde el Oasis de Foum Zguid.<\/div>\n<div class=\"post-more\"><a href=\"https:\/\/explore-agadirsoussmassa.com\/es\/parque-nacional-iriki-cruzando-foum-zguid-mhamid\/\" class=\"button button-primary button-effect\"><span>Ver detalle<\/span><span><i class=\"cs-icon cs-icon-arrow-right\"><\/i><\/span><\/a><\/div>\n","protected":false},"author":1,"featured_media":12409,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[125,425],"tags":[426,420],"powerkit_post_featured":[],"class_list":{"0":"post-34572","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-oasis-y-desierto","8":"category-parque-nacional-iriki","9":"tag-foum-zguid-es","10":"tag-tissint-es"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.0 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Parque Nacional Iriki - Marruecos - Explore Agadir Souss Massa<\/title>\n<meta name=\"description\" content=\"El Parque Nacional Iriki se encuentra entre las provincias de Tata y Zagora y se puede cruzar en veh\u00edculo 4x4 desde el Oasis de Foum Zguid.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/explore-agadirsoussmassa.com\/es\/parque-nacional-iriki-cruzando-foum-zguid-mhamid\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Parque Nacional Iriki - Marruecos - Explore Agadir Souss Massa\" \/>\n<meta property=\"og:description\" content=\"El Parque Nacional Iriki se encuentra entre las provincias de Tata y Zagora y se puede cruzar en veh\u00edculo 4x4 desde el Oasis de Foum Zguid.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/explore-agadirsoussmassa.com\/es\/parque-nacional-iriki-cruzando-foum-zguid-mhamid\/\" \/>\n<meta property=\"og:site_name\" content=\"Explore Agadir Souss Massa\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Explore-Souss-Massa-111659480353930\" \/>\n<meta property=\"article:published_time\" content=\"2020-07-25T22:11:41+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-03-04T15:00:58+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/explore-agadirsoussmassa.com\/wp-content\/uploads\/2020\/03\/vue-iriki-min.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1754\" \/>\n\t<meta property=\"og:image:height\" content=\"906\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"soussmassa\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"soussmassa\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/explore-agadirsoussmassa.com\/es\/parque-nacional-iriki-cruzando-foum-zguid-mhamid\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/explore-agadirsoussmassa.com\/es\/parque-nacional-iriki-cruzando-foum-zguid-mhamid\/\"},\"author\":{\"name\":\"soussmassa\",\"@id\":\"https:\/\/explore-agadirsoussmassa.com\/es\/#\/schema\/person\/c019e4bcfef76d1c57d426107449d03e\"},\"headline\":\"Parque Nacional Iriki: Cruzando Foum Zguid &#8211; M&#8217;hamid\",\"datePublished\":\"2020-07-25T22:11:41+00:00\",\"dateModified\":\"2021-03-04T15:00:58+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/explore-agadirsoussmassa.com\/es\/parque-nacional-iriki-cruzando-foum-zguid-mhamid\/\"},\"wordCount\":9,\"publisher\":{\"@id\":\"https:\/\/explore-agadirsoussmassa.com\/es\/#organization\"},\"image\":{\"@id\":\"https:\/\/explore-agadirsoussmassa.com\/es\/parque-nacional-iriki-cruzando-foum-zguid-mhamid\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/explore-agadirsoussmassa.com\/wp-content\/uploads\/2020\/03\/vue-iriki-min.png\",\"keywords\":[\"foum zguid\",\"tissint\"],\"articleSection\":[\"Oasis y desierto\",\"Parque Nacional Iriki\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/explore-agadirsoussmassa.com\/es\/parque-nacional-iriki-cruzando-foum-zguid-mhamid\/\",\"url\":\"https:\/\/explore-agadirsoussmassa.com\/es\/parque-nacional-iriki-cruzando-foum-zguid-mhamid\/\",\"name\":\"Parque Nacional Iriki - Marruecos - Explore Agadir Souss Massa\",\"isPartOf\":{\"@id\":\"https:\/\/explore-agadirsoussmassa.com\/es\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/explore-agadirsoussmassa.com\/es\/parque-nacional-iriki-cruzando-foum-zguid-mhamid\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/explore-agadirsoussmassa.com\/es\/parque-nacional-iriki-cruzando-foum-zguid-mhamid\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/explore-agadirsoussmassa.com\/wp-content\/uploads\/2020\/03\/vue-iriki-min.png\",\"datePublished\":\"2020-07-25T22:11:41+00:00\",\"dateModified\":\"2021-03-04T15:00:58+00:00\",\"description\":\"El Parque Nacional Iriki se encuentra entre las provincias de Tata y Zagora y se puede cruzar en veh\u00edculo 4x4 desde el Oasis de Foum Zguid.\",\"breadcrumb\":{\"@id\":\"https:\/\/explore-agadirsoussmassa.com\/es\/parque-nacional-iriki-cruzando-foum-zguid-mhamid\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/explore-agadirsoussmassa.com\/es\/parque-nacional-iriki-cruzando-foum-zguid-mhamid\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/explore-agadirsoussmassa.com\/es\/parque-nacional-iriki-cruzando-foum-zguid-mhamid\/#primaryimage\",\"url\":\"https:\/\/explore-agadirsoussmassa.com\/wp-content\/uploads\/2020\/03\/vue-iriki-min.png\",\"contentUrl\":\"https:\/\/explore-agadirsoussmassa.com\/wp-content\/uploads\/2020\/03\/vue-iriki-min.png\",\"width\":1754,\"height\":906,\"caption\":\"Mdaouer - Parc National Iriki\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/explore-agadirsoussmassa.com\/es\/parque-nacional-iriki-cruzando-foum-zguid-mhamid\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/explore-agadirsoussmassa.com\/es\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Parque Nacional Iriki: Cruzando Foum Zguid &#8211; M&#8217;hamid\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/explore-agadirsoussmassa.com\/es\/#website\",\"url\":\"https:\/\/explore-agadirsoussmassa.com\/es\/\",\"name\":\"Explore Agadir Souss Massa\",\"description\":\"R\u00e9gion Souss Massa\",\"publisher\":{\"@id\":\"https:\/\/explore-agadirsoussmassa.com\/es\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/explore-agadirsoussmassa.com\/es\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/explore-agadirsoussmassa.com\/es\/#organization\",\"name\":\"SDR Tourisme Souss Massa\",\"url\":\"https:\/\/explore-agadirsoussmassa.com\/es\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/explore-agadirsoussmassa.com\/es\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/zt88dgbrixj.preview.infomaniak.website\/wp-content\/uploads\/2020\/08\/logo-sdr.png\",\"contentUrl\":\"https:\/\/zt88dgbrixj.preview.infomaniak.website\/wp-content\/uploads\/2020\/08\/logo-sdr.png\",\"width\":404,\"height\":286,\"caption\":\"SDR Tourisme Souss Massa\"},\"image\":{\"@id\":\"https:\/\/explore-agadirsoussmassa.com\/es\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/Explore-Souss-Massa-111659480353930\",\"https:\/\/www.instagram.com\/exploresoussmassamorocco\/\",\"https:\/\/www.youtube.com\/channel\/UCpSGZAsRRpG40CeT3UcIcOA\/videos\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/explore-agadirsoussmassa.com\/es\/#\/schema\/person\/c019e4bcfef76d1c57d426107449d03e\",\"name\":\"soussmassa\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/explore-agadirsoussmassa.com\/es\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/71a3f2c422286f264199c19844c327bfdf2a272a6aab356511f8970061b8dc04?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/71a3f2c422286f264199c19844c327bfdf2a272a6aab356511f8970061b8dc04?s=96&d=mm&r=g\",\"caption\":\"soussmassa\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Parque Nacional Iriki - Marruecos - Explore Agadir Souss Massa","description":"El Parque Nacional Iriki se encuentra entre las provincias de Tata y Zagora y se puede cruzar en veh\u00edculo 4x4 desde el Oasis de Foum Zguid.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/explore-agadirsoussmassa.com\/es\/parque-nacional-iriki-cruzando-foum-zguid-mhamid\/","og_locale":"es_ES","og_type":"article","og_title":"Parque Nacional Iriki - Marruecos - Explore Agadir Souss Massa","og_description":"El Parque Nacional Iriki se encuentra entre las provincias de Tata y Zagora y se puede cruzar en veh\u00edculo 4x4 desde el Oasis de Foum Zguid.","og_url":"https:\/\/explore-agadirsoussmassa.com\/es\/parque-nacional-iriki-cruzando-foum-zguid-mhamid\/","og_site_name":"Explore Agadir Souss Massa","article_publisher":"https:\/\/www.facebook.com\/Explore-Souss-Massa-111659480353930","article_published_time":"2020-07-25T22:11:41+00:00","article_modified_time":"2021-03-04T15:00:58+00:00","og_image":[{"width":1754,"height":906,"url":"https:\/\/explore-agadirsoussmassa.com\/wp-content\/uploads\/2020\/03\/vue-iriki-min.png","type":"image\/png"}],"author":"soussmassa","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"soussmassa"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/explore-agadirsoussmassa.com\/es\/parque-nacional-iriki-cruzando-foum-zguid-mhamid\/#article","isPartOf":{"@id":"https:\/\/explore-agadirsoussmassa.com\/es\/parque-nacional-iriki-cruzando-foum-zguid-mhamid\/"},"author":{"name":"soussmassa","@id":"https:\/\/explore-agadirsoussmassa.com\/es\/#\/schema\/person\/c019e4bcfef76d1c57d426107449d03e"},"headline":"Parque Nacional Iriki: Cruzando Foum Zguid &#8211; M&#8217;hamid","datePublished":"2020-07-25T22:11:41+00:00","dateModified":"2021-03-04T15:00:58+00:00","mainEntityOfPage":{"@id":"https:\/\/explore-agadirsoussmassa.com\/es\/parque-nacional-iriki-cruzando-foum-zguid-mhamid\/"},"wordCount":9,"publisher":{"@id":"https:\/\/explore-agadirsoussmassa.com\/es\/#organization"},"image":{"@id":"https:\/\/explore-agadirsoussmassa.com\/es\/parque-nacional-iriki-cruzando-foum-zguid-mhamid\/#primaryimage"},"thumbnailUrl":"https:\/\/explore-agadirsoussmassa.com\/wp-content\/uploads\/2020\/03\/vue-iriki-min.png","keywords":["foum zguid","tissint"],"articleSection":["Oasis y desierto","Parque Nacional Iriki"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/explore-agadirsoussmassa.com\/es\/parque-nacional-iriki-cruzando-foum-zguid-mhamid\/","url":"https:\/\/explore-agadirsoussmassa.com\/es\/parque-nacional-iriki-cruzando-foum-zguid-mhamid\/","name":"Parque Nacional Iriki - Marruecos - Explore Agadir Souss Massa","isPartOf":{"@id":"https:\/\/explore-agadirsoussmassa.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/explore-agadirsoussmassa.com\/es\/parque-nacional-iriki-cruzando-foum-zguid-mhamid\/#primaryimage"},"image":{"@id":"https:\/\/explore-agadirsoussmassa.com\/es\/parque-nacional-iriki-cruzando-foum-zguid-mhamid\/#primaryimage"},"thumbnailUrl":"https:\/\/explore-agadirsoussmassa.com\/wp-content\/uploads\/2020\/03\/vue-iriki-min.png","datePublished":"2020-07-25T22:11:41+00:00","dateModified":"2021-03-04T15:00:58+00:00","description":"El Parque Nacional Iriki se encuentra entre las provincias de Tata y Zagora y se puede cruzar en veh\u00edculo 4x4 desde el Oasis de Foum Zguid.","breadcrumb":{"@id":"https:\/\/explore-agadirsoussmassa.com\/es\/parque-nacional-iriki-cruzando-foum-zguid-mhamid\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/explore-agadirsoussmassa.com\/es\/parque-nacional-iriki-cruzando-foum-zguid-mhamid\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/explore-agadirsoussmassa.com\/es\/parque-nacional-iriki-cruzando-foum-zguid-mhamid\/#primaryimage","url":"https:\/\/explore-agadirsoussmassa.com\/wp-content\/uploads\/2020\/03\/vue-iriki-min.png","contentUrl":"https:\/\/explore-agadirsoussmassa.com\/wp-content\/uploads\/2020\/03\/vue-iriki-min.png","width":1754,"height":906,"caption":"Mdaouer - Parc National Iriki"},{"@type":"BreadcrumbList","@id":"https:\/\/explore-agadirsoussmassa.com\/es\/parque-nacional-iriki-cruzando-foum-zguid-mhamid\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/explore-agadirsoussmassa.com\/es\/"},{"@type":"ListItem","position":2,"name":"Parque Nacional Iriki: Cruzando Foum Zguid &#8211; M&#8217;hamid"}]},{"@type":"WebSite","@id":"https:\/\/explore-agadirsoussmassa.com\/es\/#website","url":"https:\/\/explore-agadirsoussmassa.com\/es\/","name":"Explore Agadir Souss Massa","description":"R\u00e9gion Souss Massa","publisher":{"@id":"https:\/\/explore-agadirsoussmassa.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/explore-agadirsoussmassa.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/explore-agadirsoussmassa.com\/es\/#organization","name":"SDR Tourisme Souss Massa","url":"https:\/\/explore-agadirsoussmassa.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/explore-agadirsoussmassa.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/zt88dgbrixj.preview.infomaniak.website\/wp-content\/uploads\/2020\/08\/logo-sdr.png","contentUrl":"https:\/\/zt88dgbrixj.preview.infomaniak.website\/wp-content\/uploads\/2020\/08\/logo-sdr.png","width":404,"height":286,"caption":"SDR Tourisme Souss Massa"},"image":{"@id":"https:\/\/explore-agadirsoussmassa.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Explore-Souss-Massa-111659480353930","https:\/\/www.instagram.com\/exploresoussmassamorocco\/","https:\/\/www.youtube.com\/channel\/UCpSGZAsRRpG40CeT3UcIcOA\/videos"]},{"@type":"Person","@id":"https:\/\/explore-agadirsoussmassa.com\/es\/#\/schema\/person\/c019e4bcfef76d1c57d426107449d03e","name":"soussmassa","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/explore-agadirsoussmassa.com\/es\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/71a3f2c422286f264199c19844c327bfdf2a272a6aab356511f8970061b8dc04?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/71a3f2c422286f264199c19844c327bfdf2a272a6aab356511f8970061b8dc04?s=96&d=mm&r=g","caption":"soussmassa"}}]}},"_links":{"self":[{"href":"https:\/\/explore-agadirsoussmassa.com\/es\/wp-json\/wp\/v2\/posts\/34572","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/explore-agadirsoussmassa.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/explore-agadirsoussmassa.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/explore-agadirsoussmassa.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/explore-agadirsoussmassa.com\/es\/wp-json\/wp\/v2\/comments?post=34572"}],"version-history":[{"count":9,"href":"https:\/\/explore-agadirsoussmassa.com\/es\/wp-json\/wp\/v2\/posts\/34572\/revisions"}],"predecessor-version":[{"id":44270,"href":"https:\/\/explore-agadirsoussmassa.com\/es\/wp-json\/wp\/v2\/posts\/34572\/revisions\/44270"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/explore-agadirsoussmassa.com\/es\/wp-json\/wp\/v2\/media\/12409"}],"wp:attachment":[{"href":"https:\/\/explore-agadirsoussmassa.com\/es\/wp-json\/wp\/v2\/media?parent=34572"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/explore-agadirsoussmassa.com\/es\/wp-json\/wp\/v2\/categories?post=34572"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/explore-agadirsoussmassa.com\/es\/wp-json\/wp\/v2\/tags?post=34572"},{"taxonomy":"powerkit_post_featured","embeddable":true,"href":"https:\/\/explore-agadirsoussmassa.com\/es\/wp-json\/wp\/v2\/powerkit_post_featured?post=34572"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}