{"id":35013,"date":"2020-04-02T17:24:54","date_gmt":"2020-04-02T15:24:54","guid":{"rendered":"https:\/\/explore-agadirsoussmassa.com\/spot-surf-desert-point\/"},"modified":"2021-03-05T10:52:19","modified_gmt":"2021-03-05T09:52:19","slug":"lugar-de-surf-desert-point","status":"publish","type":"post","link":"https:\/\/explore-agadirsoussmassa.com\/es\/lugar-de-surf-desert-point\/","title":{"rendered":"Spot de surf: Desert Point"},"content":{"rendered":"<div id=\"pl-gb35013-6a580081a0bde\"  class=\"panel-layout\" ><div id=\"pg-gb35013-6a580081a0bde-0\"  class=\"panel-grid panel-no-style\" ><div id=\"pgc-gb35013-6a580081a0bde-0-0\"  class=\"panel-grid-cell\" ><div id=\"panel-gb35013-6a580081a0bde-0-0-0\" class=\"so-panel widget widget_text panel-first-child panel-last-child\" data-index=\"0\" ><div id=\"sdrstyle\" class=\"panel-widget-style panel-widget-style-for-gb35013-6a580081a0bde-0-0-0\" >\t\t\t<div class=\"textwidget\"><h3 id=\"desert-point-paisaje-salvaje\">Desert Point &#8211; Paisaje salvaje<\/h3>\n<p><em>Trayecto desde Agadir: 50mn \/ 50kms<\/em><\/p>\n<p>&nbsp;<\/p>\n<div class=\"thirdtitle bigsize\" style=\"text-transform: uppercase;\">Spot accesible a todos los niveles.<\/div>\n<p>El spot de surf de Desert Point es una derecha r\u00e1pida y hueca accesible para todos los niveles. El fondo es de arena y losas de roca muy planas que no presentan ning\u00fan peligro especial.<\/p>\n<p>En fuertes marejadas, la corriente puede ser bastante fuerte.<\/p>\n<\/div>\n\t\t<\/div><\/div><\/div><\/div><\/div>\n\n<div class=\"cnvs-block-justified-gallery cnvs-block-justified-gallery-1595455547790\" >\n<div\n\tclass='gallery cnvs-gallery-type-justified'\n\tdata-jg-margins=\"10\"\n\tdata-jg-border=\"-10\"\n\tdata-jg-row-height=\"275\"\n\tdata-jg-max-row-height=\"250%\"\n\tdata-jg-last-row=\"justify\"\n\tdata-jg-captions=\"true\"\n\tdata-jg-randomize=\"false\"\n>\n\t\t\t<figure class=\"gallery-item\">\n\t\t\t\t\t\t\t<a href=\"https:\/\/explore-agadirsoussmassa.com\/wp-content\/uploads\/2020\/04\/desert33.png\">\n\t\t\t\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1160\" height=\"870\" src=\"https:\/\/explore-agadirsoussmassa.com\/wp-content\/uploads\/2020\/04\/desert33-1160x870.png\" class=\"attachment-csco-1160 size-csco-1160\" alt=\"Desert Point\" srcset=\"https:\/\/explore-agadirsoussmassa.com\/wp-content\/uploads\/2020\/04\/desert33-1160x870.png 1160w, https:\/\/explore-agadirsoussmassa.com\/wp-content\/uploads\/2020\/04\/desert33-800x600.png 800w, https:\/\/explore-agadirsoussmassa.com\/wp-content\/uploads\/2020\/04\/desert33-320x240.png 320w, https:\/\/explore-agadirsoussmassa.com\/wp-content\/uploads\/2020\/04\/desert33-300x225.png 300w, https:\/\/explore-agadirsoussmassa.com\/wp-content\/uploads\/2020\/04\/desert33-560x420.png 560w, https:\/\/explore-agadirsoussmassa.com\/wp-content\/uploads\/2020\/04\/desert33.png 1360w\" sizes=\"auto, (max-width: 1160px) 100vw, 1160px\" \/>\n\t\t\t\t\t\t\t<\/a>\n\t\t\t\n\t\t\t<div class=\"caption wp-caption-text gallery-caption\">Desert Point<\/div>\t\t<\/figure>\n\t\t\t\t<figure class=\"gallery-item\">\n\t\t\t\t\t\t\t<a href=\"https:\/\/explore-agadirsoussmassa.com\/wp-content\/uploads\/2020\/04\/desert34.png\">\n\t\t\t\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1120\" height=\"840\" src=\"https:\/\/explore-agadirsoussmassa.com\/wp-content\/uploads\/2020\/04\/desert34.png\" class=\"attachment-csco-1160 size-csco-1160\" alt=\"Desert Point\" srcset=\"https:\/\/explore-agadirsoussmassa.com\/wp-content\/uploads\/2020\/04\/desert34.png 1120w, https:\/\/explore-agadirsoussmassa.com\/wp-content\/uploads\/2020\/04\/desert34-800x600.png 800w, https:\/\/explore-agadirsoussmassa.com\/wp-content\/uploads\/2020\/04\/desert34-320x240.png 320w, https:\/\/explore-agadirsoussmassa.com\/wp-content\/uploads\/2020\/04\/desert34-300x225.png 300w, https:\/\/explore-agadirsoussmassa.com\/wp-content\/uploads\/2020\/04\/desert34-560x420.png 560w\" sizes=\"auto, (max-width: 1120px) 100vw, 1120px\" \/>\n\t\t\t\t\t\t\t<\/a>\n\t\t\t\n\t\t\t<div class=\"caption wp-caption-text gallery-caption\">Desert Point<\/div>\t\t<\/figure>\n\t\t\t\t<figure class=\"gallery-item\">\n\t\t\t\t\t\t\t<a href=\"https:\/\/explore-agadirsoussmassa.com\/wp-content\/uploads\/2020\/04\/Capture-d\u2019e\u0301cran-2020-06-12-a\u0300-01.41.49-min.png\">\n\t\t\t\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1160\" height=\"870\" src=\"https:\/\/explore-agadirsoussmassa.com\/wp-content\/uploads\/2020\/04\/Capture-d\u2019e\u0301cran-2020-06-12-a\u0300-01.41.49-min-1160x870.png\" class=\"attachment-csco-1160 size-csco-1160\" alt=\"Desert Point\" srcset=\"https:\/\/explore-agadirsoussmassa.com\/wp-content\/uploads\/2020\/04\/Capture-d\u2019e\u0301cran-2020-06-12-a\u0300-01.41.49-min-1160x870.png 1160w, https:\/\/explore-agadirsoussmassa.com\/wp-content\/uploads\/2020\/04\/Capture-d\u2019e\u0301cran-2020-06-12-a\u0300-01.41.49-min-800x600.png 800w, https:\/\/explore-agadirsoussmassa.com\/wp-content\/uploads\/2020\/04\/Capture-d\u2019e\u0301cran-2020-06-12-a\u0300-01.41.49-min-320x240.png 320w, https:\/\/explore-agadirsoussmassa.com\/wp-content\/uploads\/2020\/04\/Capture-d\u2019e\u0301cran-2020-06-12-a\u0300-01.41.49-min-300x225.png 300w, https:\/\/explore-agadirsoussmassa.com\/wp-content\/uploads\/2020\/04\/Capture-d\u2019e\u0301cran-2020-06-12-a\u0300-01.41.49-min-560x420.png 560w, https:\/\/explore-agadirsoussmassa.com\/wp-content\/uploads\/2020\/04\/Capture-d\u2019e\u0301cran-2020-06-12-a\u0300-01.41.49-min.png 1440w\" sizes=\"auto, (max-width: 1160px) 100vw, 1160px\" \/>\n\t\t\t\t\t\t\t<\/a>\n\t\t\t\n\t\t\t<div class=\"caption wp-caption-text gallery-caption\">Desert Point<\/div>\t\t<\/figure>\n\t\t<\/div>\n\n<\/div>\n\n<div id=\"pl-gb35013-6a580081a3280\"  class=\"panel-layout\" ><div id=\"pg-gb35013-6a580081a3280-0\"  class=\"panel-grid panel-no-style\" ><div id=\"pgc-gb35013-6a580081a3280-0-0\"  class=\"panel-grid-cell\" ><div id=\"panel-gb35013-6a580081a3280-0-0-0\" class=\"so-panel widget widget_text panel-first-child panel-last-child\" data-index=\"0\" ><div id=\"sdrstyle\" class=\"panel-widget-style panel-widget-style-for-gb35013-6a580081a3280-0-0-0\" >\t\t\t<div class=\"textwidget\"><p><em>C\u00f3mo llegar: <\/em><\/p>\n<p>Desde Agadir, tome la carretera N1 en <a href=\"\/playas-al-norte-de-agadir\/\">direcci\u00f3n norte<\/a> (carretera de la costa), el spot (30.622788, -9.816133) se encuentra entre los pueblos de Aghroud y Tighrert.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<div class=\"thirdtitle bigsize\" style=\"text-transform: uppercase;\">Informaci\u00f3n &#8211; spot:<\/div>\n<\/div>\n\t\t<\/div><\/div><\/div><\/div><\/div>\n\n<div class=\"cnvs-block-justified-gallery cnvs-block-justified-gallery-1595455620475\" >\n<div\n\tclass='gallery cnvs-gallery-type-justified'\n\tdata-jg-margins=\"10\"\n\tdata-jg-border=\"-10\"\n\tdata-jg-row-height=\"275\"\n\tdata-jg-max-row-height=\"200%\"\n\tdata-jg-last-row=\"justify\"\n\tdata-jg-captions=\"true\"\n\tdata-jg-randomize=\"false\"\n>\n\t\t\t<figure class=\"gallery-item\">\n\t\t\t\t\t\t\t<a href=\"https:\/\/explore-agadirsoussmassa.com\/wp-content\/uploads\/2020\/04\/desert-infos2.png\">\n\t\t\t\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"712\" height=\"504\" src=\"https:\/\/explore-agadirsoussmassa.com\/wp-content\/uploads\/2020\/04\/desert-infos2.png\" class=\"attachment-csco-1160 size-csco-1160\" alt=\"Desert Point - Infos spot\" srcset=\"https:\/\/explore-agadirsoussmassa.com\/wp-content\/uploads\/2020\/04\/desert-infos2.png 712w, https:\/\/explore-agadirsoussmassa.com\/wp-content\/uploads\/2020\/04\/desert-infos2-320x227.png 320w, https:\/\/explore-agadirsoussmassa.com\/wp-content\/uploads\/2020\/04\/desert-infos2-560x396.png 560w\" sizes=\"auto, (max-width: 712px) 100vw, 712px\" \/>\n\t\t\t\t\t\t\t<\/a>\n\t\t\t\n\t\t\t<div class=\"caption wp-caption-text gallery-caption\">Desert Point &#8211; Informaci\u00f3n del lugar<\/div>\t\t<\/figure>\n\t\t\t\t<figure class=\"gallery-item\">\n\t\t\t\t\t\t\t<a href=\"https:\/\/explore-agadirsoussmassa.com\/wp-content\/uploads\/2020\/04\/desert-infos1.png\">\n\t\t\t\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"712\" height=\"508\" src=\"https:\/\/explore-agadirsoussmassa.com\/wp-content\/uploads\/2020\/04\/desert-infos1.png\" class=\"attachment-csco-1160 size-csco-1160\" alt=\"Desert Point - Infos spot\" srcset=\"https:\/\/explore-agadirsoussmassa.com\/wp-content\/uploads\/2020\/04\/desert-infos1.png 712w, https:\/\/explore-agadirsoussmassa.com\/wp-content\/uploads\/2020\/04\/desert-infos1-320x228.png 320w, https:\/\/explore-agadirsoussmassa.com\/wp-content\/uploads\/2020\/04\/desert-infos1-560x400.png 560w\" sizes=\"auto, (max-width: 712px) 100vw, 712px\" \/>\n\t\t\t\t\t\t\t<\/a>\n\t\t\t\n\t\t\t<div class=\"caption wp-caption-text gallery-caption\">Desert Point &#8211; Informaci\u00f3n del lugar<\/div>\t\t<\/figure>\n\t\t<\/div>\n\n<\/div>","protected":false},"excerpt":{"rendered":"<div class=\"post-excerpt\">El lugar de surf de Desert Point es una l\u00ednea recta r\u00e1pida y hueca que permanece accesible para todos los niveles. El fondo es de arena y losas de roca muy planas que no presentan ning\u00fan peligro especial.<\/div>\n<div class=\"post-more\"><a href=\"https:\/\/explore-agadirsoussmassa.com\/es\/lugar-de-surf-desert-point\/\" class=\"button button-primary button-effect\"><span>Ver detalle<\/span><span><i class=\"cs-icon cs-icon-arrow-right\"><\/i><\/span><\/a><\/div>\n","protected":false},"author":1,"featured_media":13205,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[562,482,516,458],"tags":[716,500],"powerkit_post_featured":[],"class_list":{"0":"post-35013","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-actividad-de-surf","8":"category-deporte-y-naturaleza","9":"category-playas-del-norte-de-agadir","10":"category-que-hacer","11":"tag-imi-ouaddar-es","12":"tag-tamri-es"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.0 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Spot de surf: Desert Point - Explore Agadir Souss Massa<\/title>\n<meta name=\"description\" content=\"El lugar de surf de Desert Point es una derecha r\u00e1pida y hueca que permanece accesible para todos los niveles. Ning\u00fan peligro particular.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/explore-agadirsoussmassa.com\/es\/lugar-de-surf-desert-point\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Spot de surf: Desert Point - Explore Agadir Souss Massa\" \/>\n<meta property=\"og:description\" content=\"El lugar de surf de Desert Point es una derecha r\u00e1pida y hueca que permanece accesible para todos los niveles. Ning\u00fan peligro particular.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/explore-agadirsoussmassa.com\/es\/lugar-de-surf-desert-point\/\" \/>\n<meta property=\"og:site_name\" content=\"Explore Agadir Souss Massa\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Explore-Souss-Massa-111659480353930\" \/>\n<meta property=\"article:published_time\" content=\"2020-04-02T15:24:54+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-03-05T09:52:19+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/explore-agadirsoussmassa.com\/wp-content\/uploads\/2020\/04\/Desert-point-2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"720\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"soussmassa\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"soussmassa\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/explore-agadirsoussmassa.com\/es\/lugar-de-surf-desert-point\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/explore-agadirsoussmassa.com\/es\/lugar-de-surf-desert-point\/\"},\"author\":{\"name\":\"soussmassa\",\"@id\":\"https:\/\/explore-agadirsoussmassa.com\/es\/#\/schema\/person\/c019e4bcfef76d1c57d426107449d03e\"},\"headline\":\"Spot de surf: Desert Point\",\"datePublished\":\"2020-04-02T15:24:54+00:00\",\"dateModified\":\"2021-03-05T09:52:19+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/explore-agadirsoussmassa.com\/es\/lugar-de-surf-desert-point\/\"},\"wordCount\":5,\"publisher\":{\"@id\":\"https:\/\/explore-agadirsoussmassa.com\/es\/#organization\"},\"image\":{\"@id\":\"https:\/\/explore-agadirsoussmassa.com\/es\/lugar-de-surf-desert-point\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/explore-agadirsoussmassa.com\/wp-content\/uploads\/2020\/04\/Desert-point-2.jpg\",\"keywords\":[\"imi ouaddar\",\"tamri\"],\"articleSection\":[\"Actividad de surf\",\"Deporte y naturaleza\",\"Playas del norte de Agadir\",\"Qu\u00e9 hacer\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/explore-agadirsoussmassa.com\/es\/lugar-de-surf-desert-point\/\",\"url\":\"https:\/\/explore-agadirsoussmassa.com\/es\/lugar-de-surf-desert-point\/\",\"name\":\"Spot de surf: Desert Point - Explore Agadir Souss Massa\",\"isPartOf\":{\"@id\":\"https:\/\/explore-agadirsoussmassa.com\/es\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/explore-agadirsoussmassa.com\/es\/lugar-de-surf-desert-point\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/explore-agadirsoussmassa.com\/es\/lugar-de-surf-desert-point\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/explore-agadirsoussmassa.com\/wp-content\/uploads\/2020\/04\/Desert-point-2.jpg\",\"datePublished\":\"2020-04-02T15:24:54+00:00\",\"dateModified\":\"2021-03-05T09:52:19+00:00\",\"description\":\"El lugar de surf de Desert Point es una derecha r\u00e1pida y hueca que permanece accesible para todos los niveles. Ning\u00fan peligro particular.\",\"breadcrumb\":{\"@id\":\"https:\/\/explore-agadirsoussmassa.com\/es\/lugar-de-surf-desert-point\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/explore-agadirsoussmassa.com\/es\/lugar-de-surf-desert-point\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/explore-agadirsoussmassa.com\/es\/lugar-de-surf-desert-point\/#primaryimage\",\"url\":\"https:\/\/explore-agadirsoussmassa.com\/wp-content\/uploads\/2020\/04\/Desert-point-2.jpg\",\"contentUrl\":\"https:\/\/explore-agadirsoussmassa.com\/wp-content\/uploads\/2020\/04\/Desert-point-2.jpg\",\"width\":1280,\"height\":720},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/explore-agadirsoussmassa.com\/es\/lugar-de-surf-desert-point\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/explore-agadirsoussmassa.com\/es\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Spot de surf: Desert Point\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/explore-agadirsoussmassa.com\/es\/#website\",\"url\":\"https:\/\/explore-agadirsoussmassa.com\/es\/\",\"name\":\"Explore Agadir Souss Massa\",\"description\":\"R\u00e9gion Souss Massa\",\"publisher\":{\"@id\":\"https:\/\/explore-agadirsoussmassa.com\/es\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/explore-agadirsoussmassa.com\/es\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/explore-agadirsoussmassa.com\/es\/#organization\",\"name\":\"SDR Tourisme Souss Massa\",\"url\":\"https:\/\/explore-agadirsoussmassa.com\/es\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/explore-agadirsoussmassa.com\/es\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/zt88dgbrixj.preview.infomaniak.website\/wp-content\/uploads\/2020\/08\/logo-sdr.png\",\"contentUrl\":\"https:\/\/zt88dgbrixj.preview.infomaniak.website\/wp-content\/uploads\/2020\/08\/logo-sdr.png\",\"width\":404,\"height\":286,\"caption\":\"SDR Tourisme Souss Massa\"},\"image\":{\"@id\":\"https:\/\/explore-agadirsoussmassa.com\/es\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/Explore-Souss-Massa-111659480353930\",\"https:\/\/www.instagram.com\/exploresoussmassamorocco\/\",\"https:\/\/www.youtube.com\/channel\/UCpSGZAsRRpG40CeT3UcIcOA\/videos\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/explore-agadirsoussmassa.com\/es\/#\/schema\/person\/c019e4bcfef76d1c57d426107449d03e\",\"name\":\"soussmassa\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/explore-agadirsoussmassa.com\/es\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/71a3f2c422286f264199c19844c327bfdf2a272a6aab356511f8970061b8dc04?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/71a3f2c422286f264199c19844c327bfdf2a272a6aab356511f8970061b8dc04?s=96&d=mm&r=g\",\"caption\":\"soussmassa\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Spot de surf: Desert Point - Explore Agadir Souss Massa","description":"El lugar de surf de Desert Point es una derecha r\u00e1pida y hueca que permanece accesible para todos los niveles. Ning\u00fan peligro particular.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/explore-agadirsoussmassa.com\/es\/lugar-de-surf-desert-point\/","og_locale":"es_ES","og_type":"article","og_title":"Spot de surf: Desert Point - Explore Agadir Souss Massa","og_description":"El lugar de surf de Desert Point es una derecha r\u00e1pida y hueca que permanece accesible para todos los niveles. Ning\u00fan peligro particular.","og_url":"https:\/\/explore-agadirsoussmassa.com\/es\/lugar-de-surf-desert-point\/","og_site_name":"Explore Agadir Souss Massa","article_publisher":"https:\/\/www.facebook.com\/Explore-Souss-Massa-111659480353930","article_published_time":"2020-04-02T15:24:54+00:00","article_modified_time":"2021-03-05T09:52:19+00:00","og_image":[{"width":1280,"height":720,"url":"https:\/\/explore-agadirsoussmassa.com\/wp-content\/uploads\/2020\/04\/Desert-point-2.jpg","type":"image\/jpeg"}],"author":"soussmassa","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"soussmassa"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/explore-agadirsoussmassa.com\/es\/lugar-de-surf-desert-point\/#article","isPartOf":{"@id":"https:\/\/explore-agadirsoussmassa.com\/es\/lugar-de-surf-desert-point\/"},"author":{"name":"soussmassa","@id":"https:\/\/explore-agadirsoussmassa.com\/es\/#\/schema\/person\/c019e4bcfef76d1c57d426107449d03e"},"headline":"Spot de surf: Desert Point","datePublished":"2020-04-02T15:24:54+00:00","dateModified":"2021-03-05T09:52:19+00:00","mainEntityOfPage":{"@id":"https:\/\/explore-agadirsoussmassa.com\/es\/lugar-de-surf-desert-point\/"},"wordCount":5,"publisher":{"@id":"https:\/\/explore-agadirsoussmassa.com\/es\/#organization"},"image":{"@id":"https:\/\/explore-agadirsoussmassa.com\/es\/lugar-de-surf-desert-point\/#primaryimage"},"thumbnailUrl":"https:\/\/explore-agadirsoussmassa.com\/wp-content\/uploads\/2020\/04\/Desert-point-2.jpg","keywords":["imi ouaddar","tamri"],"articleSection":["Actividad de surf","Deporte y naturaleza","Playas del norte de Agadir","Qu\u00e9 hacer"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/explore-agadirsoussmassa.com\/es\/lugar-de-surf-desert-point\/","url":"https:\/\/explore-agadirsoussmassa.com\/es\/lugar-de-surf-desert-point\/","name":"Spot de surf: Desert Point - Explore Agadir Souss Massa","isPartOf":{"@id":"https:\/\/explore-agadirsoussmassa.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/explore-agadirsoussmassa.com\/es\/lugar-de-surf-desert-point\/#primaryimage"},"image":{"@id":"https:\/\/explore-agadirsoussmassa.com\/es\/lugar-de-surf-desert-point\/#primaryimage"},"thumbnailUrl":"https:\/\/explore-agadirsoussmassa.com\/wp-content\/uploads\/2020\/04\/Desert-point-2.jpg","datePublished":"2020-04-02T15:24:54+00:00","dateModified":"2021-03-05T09:52:19+00:00","description":"El lugar de surf de Desert Point es una derecha r\u00e1pida y hueca que permanece accesible para todos los niveles. Ning\u00fan peligro particular.","breadcrumb":{"@id":"https:\/\/explore-agadirsoussmassa.com\/es\/lugar-de-surf-desert-point\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/explore-agadirsoussmassa.com\/es\/lugar-de-surf-desert-point\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/explore-agadirsoussmassa.com\/es\/lugar-de-surf-desert-point\/#primaryimage","url":"https:\/\/explore-agadirsoussmassa.com\/wp-content\/uploads\/2020\/04\/Desert-point-2.jpg","contentUrl":"https:\/\/explore-agadirsoussmassa.com\/wp-content\/uploads\/2020\/04\/Desert-point-2.jpg","width":1280,"height":720},{"@type":"BreadcrumbList","@id":"https:\/\/explore-agadirsoussmassa.com\/es\/lugar-de-surf-desert-point\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/explore-agadirsoussmassa.com\/es\/"},{"@type":"ListItem","position":2,"name":"Spot de surf: Desert Point"}]},{"@type":"WebSite","@id":"https:\/\/explore-agadirsoussmassa.com\/es\/#website","url":"https:\/\/explore-agadirsoussmassa.com\/es\/","name":"Explore Agadir Souss Massa","description":"R\u00e9gion Souss Massa","publisher":{"@id":"https:\/\/explore-agadirsoussmassa.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/explore-agadirsoussmassa.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/explore-agadirsoussmassa.com\/es\/#organization","name":"SDR Tourisme Souss Massa","url":"https:\/\/explore-agadirsoussmassa.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/explore-agadirsoussmassa.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/zt88dgbrixj.preview.infomaniak.website\/wp-content\/uploads\/2020\/08\/logo-sdr.png","contentUrl":"https:\/\/zt88dgbrixj.preview.infomaniak.website\/wp-content\/uploads\/2020\/08\/logo-sdr.png","width":404,"height":286,"caption":"SDR Tourisme Souss Massa"},"image":{"@id":"https:\/\/explore-agadirsoussmassa.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Explore-Souss-Massa-111659480353930","https:\/\/www.instagram.com\/exploresoussmassamorocco\/","https:\/\/www.youtube.com\/channel\/UCpSGZAsRRpG40CeT3UcIcOA\/videos"]},{"@type":"Person","@id":"https:\/\/explore-agadirsoussmassa.com\/es\/#\/schema\/person\/c019e4bcfef76d1c57d426107449d03e","name":"soussmassa","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/explore-agadirsoussmassa.com\/es\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/71a3f2c422286f264199c19844c327bfdf2a272a6aab356511f8970061b8dc04?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/71a3f2c422286f264199c19844c327bfdf2a272a6aab356511f8970061b8dc04?s=96&d=mm&r=g","caption":"soussmassa"}}]}},"_links":{"self":[{"href":"https:\/\/explore-agadirsoussmassa.com\/es\/wp-json\/wp\/v2\/posts\/35013","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/explore-agadirsoussmassa.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/explore-agadirsoussmassa.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/explore-agadirsoussmassa.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/explore-agadirsoussmassa.com\/es\/wp-json\/wp\/v2\/comments?post=35013"}],"version-history":[{"count":6,"href":"https:\/\/explore-agadirsoussmassa.com\/es\/wp-json\/wp\/v2\/posts\/35013\/revisions"}],"predecessor-version":[{"id":41862,"href":"https:\/\/explore-agadirsoussmassa.com\/es\/wp-json\/wp\/v2\/posts\/35013\/revisions\/41862"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/explore-agadirsoussmassa.com\/es\/wp-json\/wp\/v2\/media\/13205"}],"wp:attachment":[{"href":"https:\/\/explore-agadirsoussmassa.com\/es\/wp-json\/wp\/v2\/media?parent=35013"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/explore-agadirsoussmassa.com\/es\/wp-json\/wp\/v2\/categories?post=35013"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/explore-agadirsoussmassa.com\/es\/wp-json\/wp\/v2\/tags?post=35013"},{"taxonomy":"powerkit_post_featured","embeddable":true,"href":"https:\/\/explore-agadirsoussmassa.com\/es\/wp-json\/wp\/v2\/powerkit_post_featured?post=35013"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}