{"id":33847,"date":"2020-07-26T20:20:29","date_gmt":"2020-07-26T18:20:29","guid":{"rendered":"http:\/\/explore-agadirsoussmassa.com\/?p=33847"},"modified":"2021-02-22T21:56:49","modified_gmt":"2021-02-22T20:56:49","slug":"vallee-des-cedrats-randonnee","status":"publish","type":"post","link":"https:\/\/explore-agadirsoussmassa.com\/fr\/vallee-des-cedrats-randonnee\/","title":{"rendered":"Vall\u00e9e des C\u00e9drats &#8211; Randonn\u00e9e"},"content":{"rendered":"<div id=\"pl-gb33847-6a979f5134c56\"  class=\"panel-layout\" ><div id=\"pg-gb33847-6a979f5134c56-0\"  class=\"panel-grid panel-no-style\" ><div id=\"pgc-gb33847-6a979f5134c56-0-0\"  class=\"panel-grid-cell\" ><div id=\"panel-gb33847-6a979f5134c56-0-0-0\" class=\"so-panel widget widget_text panel-first-child panel-last-child\" data-index=\"0\" ><div id=\"sdrstyle\" class=\"panel-widget-style panel-widget-style-for-gb33847-6a979f5134c56-0-0-0\" >\t\t\t<div class=\"textwidget\"><h3 id=\"la-vallee-des-fruits-sacres\">La vall\u00e9e des fruits sacr\u00e9s<\/h3>\n<p><em>Trajet depuis Agadir : 1h40mn<\/em><\/p>\n<\/div>\n\t\t<\/div><\/div><\/div><\/div><div id=\"pg-gb33847-6a979f5134c56-1\"  class=\"panel-grid panel-no-style\" ><div id=\"pgc-gb33847-6a979f5134c56-1-0\"  class=\"panel-grid-cell\" ><div id=\"panel-gb33847-6a979f5134c56-1-0-0\" class=\"so-panel widget widget_text panel-first-child panel-last-child\" data-index=\"1\" ><div id=\"sdrstyle\" class=\"panel-widget-style panel-widget-style-for-gb33847-6a979f5134c56-1-0-0\" >\t\t\t<div class=\"textwidget\"><div class=\"thirdtitle bigsize\" style=\"text-transform: uppercase;\">fruits sacr\u00e9s = fruits cach\u00e9s <\/div>\n<p>La Vall\u00e9e des C\u00e9drats doit son nom \u00e0 une vari\u00e9t\u00e9 de gros citrons, cultiv\u00e9s au bord de cet Oued (rivi\u00e8re). Magnifique randonn\u00e9e dans un canyon de 3 kms o\u00f9 la v\u00e9g\u00e9tation et les c\u00e9drats apparaissent petit \u00e0 petit\u2026. Les c\u00e9drats sont des fruits tr\u00e8s pris\u00e9s des juifs. Les berb\u00e8res en ont perp\u00e9tu\u00e9 la culture et les exportent aujourd&rsquo;hui.<\/p>\n<\/div>\n\t\t<\/div><\/div><\/div><\/div><\/div>\n\n<div class=\"cnvs-block-justified-gallery cnvs-block-justified-gallery-1595791082621\" >\n<div\n\tclass='gallery cnvs-gallery-type-justified'\n\tdata-jg-margins=\"10\"\n\tdata-jg-border=\"-10\"\n\tdata-jg-row-height=\"258\"\n\tdata-jg-max-row-height=\"220%\"\n\tdata-jg-last-row=\"justify\"\n\tdata-jg-captions=\"true\"\n\tdata-jg-randomize=\"false\"\n>\n\t\t\t<figure class=\"gallery-item\">\n\t\t\t\t\t\t\t<a href=\"https:\/\/explore-agadirsoussmassa.com\/wp-content\/uploads\/2020\/02\/cedrats-23.png\">\n\t\t\t\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1160\" height=\"870\" src=\"https:\/\/explore-agadirsoussmassa.com\/wp-content\/uploads\/2020\/02\/cedrats-23-1160x870.png\" class=\"attachment-csco-1160 size-csco-1160\" alt=\"C\u00e9drats - Vall\u00e9e des C\u00e9drats\" srcset=\"https:\/\/explore-agadirsoussmassa.com\/wp-content\/uploads\/2020\/02\/cedrats-23-1160x870.png 1160w, https:\/\/explore-agadirsoussmassa.com\/wp-content\/uploads\/2020\/02\/cedrats-23-800x600.png 800w, https:\/\/explore-agadirsoussmassa.com\/wp-content\/uploads\/2020\/02\/cedrats-23-320x240.png 320w, https:\/\/explore-agadirsoussmassa.com\/wp-content\/uploads\/2020\/02\/cedrats-23-1536x1152.png 1536w, https:\/\/explore-agadirsoussmassa.com\/wp-content\/uploads\/2020\/02\/cedrats-23-300x225.png 300w, https:\/\/explore-agadirsoussmassa.com\/wp-content\/uploads\/2020\/02\/cedrats-23-560x420.png 560w, https:\/\/explore-agadirsoussmassa.com\/wp-content\/uploads\/2020\/02\/cedrats-23.png 1600w\" sizes=\"auto, (max-width: 1160px) 100vw, 1160px\" \/>\n\t\t\t\t\t\t\t<\/a>\n\t\t\t\n\t\t\t<div class=\"caption wp-caption-text gallery-caption\">C\u00e9drats &#8211; Vall\u00e9e des C\u00e9drats<\/div>\t\t<\/figure>\n\t\t\t\t<figure class=\"gallery-item\">\n\t\t\t\t\t\t\t<a href=\"https:\/\/explore-agadirsoussmassa.com\/wp-content\/uploads\/2020\/02\/cedrats-24.png\">\n\t\t\t\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1160\" height=\"870\" src=\"https:\/\/explore-agadirsoussmassa.com\/wp-content\/uploads\/2020\/02\/cedrats-24-1160x870.png\" class=\"attachment-csco-1160 size-csco-1160\" alt=\"Vall\u00e9e des C\u00e9drats\" srcset=\"https:\/\/explore-agadirsoussmassa.com\/wp-content\/uploads\/2020\/02\/cedrats-24-1160x870.png 1160w, https:\/\/explore-agadirsoussmassa.com\/wp-content\/uploads\/2020\/02\/cedrats-24-800x600.png 800w, https:\/\/explore-agadirsoussmassa.com\/wp-content\/uploads\/2020\/02\/cedrats-24-320x240.png 320w, https:\/\/explore-agadirsoussmassa.com\/wp-content\/uploads\/2020\/02\/cedrats-24-1536x1152.png 1536w, https:\/\/explore-agadirsoussmassa.com\/wp-content\/uploads\/2020\/02\/cedrats-24-300x225.png 300w, https:\/\/explore-agadirsoussmassa.com\/wp-content\/uploads\/2020\/02\/cedrats-24-560x420.png 560w, https:\/\/explore-agadirsoussmassa.com\/wp-content\/uploads\/2020\/02\/cedrats-24.png 1600w\" sizes=\"auto, (max-width: 1160px) 100vw, 1160px\" \/>\n\t\t\t\t\t\t\t<\/a>\n\t\t\t\n\t\t\t<div class=\"caption wp-caption-text gallery-caption\"> Vall\u00e9e des C\u00e9drats<\/div>\t\t<\/figure>\n\t\t\t\t<figure class=\"gallery-item\">\n\t\t\t\t\t\t\t<a href=\"https:\/\/explore-agadirsoussmassa.com\/wp-content\/uploads\/2020\/02\/cedrats-26.png\">\n\t\t\t\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1160\" height=\"870\" src=\"https:\/\/explore-agadirsoussmassa.com\/wp-content\/uploads\/2020\/02\/cedrats-26-1160x870.png\" class=\"attachment-csco-1160 size-csco-1160\" alt=\"Canyon - Vall\u00e9e des C\u00e9drats\" srcset=\"https:\/\/explore-agadirsoussmassa.com\/wp-content\/uploads\/2020\/02\/cedrats-26-1160x870.png 1160w, https:\/\/explore-agadirsoussmassa.com\/wp-content\/uploads\/2020\/02\/cedrats-26-800x600.png 800w, https:\/\/explore-agadirsoussmassa.com\/wp-content\/uploads\/2020\/02\/cedrats-26-320x240.png 320w, https:\/\/explore-agadirsoussmassa.com\/wp-content\/uploads\/2020\/02\/cedrats-26-1536x1152.png 1536w, https:\/\/explore-agadirsoussmassa.com\/wp-content\/uploads\/2020\/02\/cedrats-26-300x225.png 300w, https:\/\/explore-agadirsoussmassa.com\/wp-content\/uploads\/2020\/02\/cedrats-26-560x420.png 560w, https:\/\/explore-agadirsoussmassa.com\/wp-content\/uploads\/2020\/02\/cedrats-26.png 1600w\" sizes=\"auto, (max-width: 1160px) 100vw, 1160px\" \/>\n\t\t\t\t\t\t\t<\/a>\n\t\t\t\n\t\t\t<div class=\"caption wp-caption-text gallery-caption\">Canyon &#8211; Vall\u00e9e des C\u00e9drats<\/div>\t\t<\/figure>\n\t\t<\/div>\n\n<\/div>\n\n<div id=\"pl-gb33847-6a979f513678b\"  class=\"panel-layout\" ><div id=\"pg-gb33847-6a979f513678b-0\"  class=\"panel-grid panel-no-style\" ><div id=\"pgc-gb33847-6a979f513678b-0-0\"  class=\"panel-grid-cell\" ><div id=\"panel-gb33847-6a979f513678b-0-0-0\" class=\"so-panel widget widget_text panel-first-child panel-last-child\" data-index=\"0\" >\t\t\t<div class=\"textwidget\"><p><em><span style=\"font-weight: 400;\">Comment s&rsquo;y rendre :<\/span><\/em><\/p>\n<p><span style=\"font-weight: 400;\">Depuis Agadir, prenez la route de l&rsquo;a\u00e9roport direction &#8211; Taroudant . <\/span><span style=\"font-weight: 400;\">Apr\u00e8s Sebt Guerdane, prenez \u00e0 droite la direction du village d&rsquo;Assads (30.376455, -8.921305) puis tournez \u00e0 gauche au point (30.352840, -8.930425). Passez \u00e0 Tourght puis traversez le village d&rsquo;Assads (30.201727, -8.859966), continuez la piste vers le dernier village: Douar Tamguinsift\u00a0 o\u00f9 vous laisserez votre voiture (impossible d\u2019aller plus loin) . <\/span><\/p>\n<p><span style=\"font-weight: 400;\">Continuez \u00e0 pied en prenant un petit sentier le long du canal d&rsquo;irrigation (seguia) . Il suffit de remonter la rivi\u00e8re (oued) direction Sud- Est, jusqu&rsquo; \u00e0 d\u00e9couvrir un barrage retenant l&rsquo;eau, au pied de falaises. <\/span><span style=\"font-weight: 400;\">Le trajet \u00e0 pied dans l&rsquo;oued fait un peu plus de 3 kilom\u00e8tres et\u00a0 vous prendra 2 heures de marche.<\/span><\/p>\n<p>&nbsp;<\/p>\n<p><em><span style=\"font-weight: 400;\">Activit\u00e9s :\u00a0<\/span><\/em><\/p>\n<ul>\n<li><span style=\"font-weight: 400;\">Randonn\u00e9e<\/span><\/li>\n<li>D\u00e9couverte du C\u00e9drat<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<p><em>Conseils :\u00a0<\/em><\/p>\n<ul>\n<li><span style=\"font-weight: 400;\">Activit\u00e9 \u00e0 lier \u00e0 la visite de la Ville de Taroudant ou l&rsquo;Oasis de Tioute.<\/span><\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<\/div>\n\t\t<\/div><\/div><\/div><\/div>","protected":false},"excerpt":{"rendered":"<div class=\"post-excerpt\">La Vall\u00e9e des C\u00e9drats &#8211; Magnifique randonn\u00e9e depuis Taroudant dans un canyon de 3 kms\u00a0 o\u00f9 les c\u00e9drats, sorte de gros citrons, apparaissent petit \u00e0 petit.<\/div>\n<div class=\"post-more\"><a href=\"https:\/\/explore-agadirsoussmassa.com\/fr\/vallee-des-cedrats-randonnee\/\" class=\"button button-primary button-effect\"><span>Voir le d\u00e9tail<\/span><span><i class=\"cs-icon cs-icon-arrow-right\"><\/i><\/span><\/a><\/div>\n","protected":false},"author":1,"featured_media":6239,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[225,16],"tags":[],"powerkit_post_featured":[],"class_list":{"0":"post-33847","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-anti-atlas","8":"category-montagnes"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.0 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Vall\u00e9e des C\u00e9drats - Randonn\u00e9e - Explore Agadir Souss Massa<\/title>\n<meta name=\"description\" content=\"La Vall\u00e9e des C\u00e9drats - Magnifique randonn\u00e9e depuis Taroudant dans un canyon de 3 kms o\u00f9 les c\u00e9drats, sorte de gros citrons, apparaissent petit \u00e0 petit.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/explore-agadirsoussmassa.com\/fr\/vallee-des-cedrats-randonnee\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Vall\u00e9e des C\u00e9drats - Randonn\u00e9e - Explore Agadir Souss Massa\" \/>\n<meta property=\"og:description\" content=\"La Vall\u00e9e des C\u00e9drats - Magnifique randonn\u00e9e depuis Taroudant dans un canyon de 3 kms o\u00f9 les c\u00e9drats, sorte de gros citrons, apparaissent petit \u00e0 petit.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/explore-agadirsoussmassa.com\/fr\/vallee-des-cedrats-randonnee\/\" \/>\n<meta property=\"og:site_name\" content=\"Explore Agadir Souss Massa\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Explore-Souss-Massa-111659480353930\" \/>\n<meta property=\"article:published_time\" content=\"2020-07-26T18:20:29+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-02-22T20:56:49+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/explore-agadirsoussmassa.com\/wp-content\/uploads\/2020\/02\/cedrats-2-large-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1903\" \/>\n\t<meta property=\"og:image:height\" content=\"600\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"soussmassa\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"soussmassa\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/explore-agadirsoussmassa.com\/fr\/vallee-des-cedrats-randonnee\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/explore-agadirsoussmassa.com\/fr\/vallee-des-cedrats-randonnee\/\"},\"author\":{\"name\":\"soussmassa\",\"@id\":\"https:\/\/explore-agadirsoussmassa.com\/fr\/#\/schema\/person\/c019e4bcfef76d1c57d426107449d03e\"},\"headline\":\"Vall\u00e9e des C\u00e9drats &#8211; Randonn\u00e9e\",\"datePublished\":\"2020-07-26T18:20:29+00:00\",\"dateModified\":\"2021-02-22T20:56:49+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/explore-agadirsoussmassa.com\/fr\/vallee-des-cedrats-randonnee\/\"},\"wordCount\":8,\"publisher\":{\"@id\":\"https:\/\/explore-agadirsoussmassa.com\/fr\/#organization\"},\"image\":{\"@id\":\"https:\/\/explore-agadirsoussmassa.com\/fr\/vallee-des-cedrats-randonnee\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/explore-agadirsoussmassa.com\/wp-content\/uploads\/2020\/02\/cedrats-2-large-1.jpg\",\"articleSection\":[\"Anti Atlas\",\"Montagnes\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/explore-agadirsoussmassa.com\/fr\/vallee-des-cedrats-randonnee\/\",\"url\":\"https:\/\/explore-agadirsoussmassa.com\/fr\/vallee-des-cedrats-randonnee\/\",\"name\":\"Vall\u00e9e des C\u00e9drats - Randonn\u00e9e - Explore Agadir Souss Massa\",\"isPartOf\":{\"@id\":\"https:\/\/explore-agadirsoussmassa.com\/fr\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/explore-agadirsoussmassa.com\/fr\/vallee-des-cedrats-randonnee\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/explore-agadirsoussmassa.com\/fr\/vallee-des-cedrats-randonnee\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/explore-agadirsoussmassa.com\/wp-content\/uploads\/2020\/02\/cedrats-2-large-1.jpg\",\"datePublished\":\"2020-07-26T18:20:29+00:00\",\"dateModified\":\"2021-02-22T20:56:49+00:00\",\"description\":\"La Vall\u00e9e des C\u00e9drats - Magnifique randonn\u00e9e depuis Taroudant dans un canyon de 3 kms o\u00f9 les c\u00e9drats, sorte de gros citrons, apparaissent petit \u00e0 petit.\",\"breadcrumb\":{\"@id\":\"https:\/\/explore-agadirsoussmassa.com\/fr\/vallee-des-cedrats-randonnee\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/explore-agadirsoussmassa.com\/fr\/vallee-des-cedrats-randonnee\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/explore-agadirsoussmassa.com\/fr\/vallee-des-cedrats-randonnee\/#primaryimage\",\"url\":\"https:\/\/explore-agadirsoussmassa.com\/wp-content\/uploads\/2020\/02\/cedrats-2-large-1.jpg\",\"contentUrl\":\"https:\/\/explore-agadirsoussmassa.com\/wp-content\/uploads\/2020\/02\/cedrats-2-large-1.jpg\",\"width\":1903,\"height\":600},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/explore-agadirsoussmassa.com\/fr\/vallee-des-cedrats-randonnee\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/explore-agadirsoussmassa.com\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Vall\u00e9e des C\u00e9drats &#8211; Randonn\u00e9e\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/explore-agadirsoussmassa.com\/fr\/#website\",\"url\":\"https:\/\/explore-agadirsoussmassa.com\/fr\/\",\"name\":\"Explore Agadir Souss Massa\",\"description\":\"R\u00e9gion Souss Massa\",\"publisher\":{\"@id\":\"https:\/\/explore-agadirsoussmassa.com\/fr\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/explore-agadirsoussmassa.com\/fr\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/explore-agadirsoussmassa.com\/fr\/#organization\",\"name\":\"SDR Tourisme Souss Massa\",\"url\":\"https:\/\/explore-agadirsoussmassa.com\/fr\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/explore-agadirsoussmassa.com\/fr\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/zt88dgbrixj.preview.infomaniak.website\/wp-content\/uploads\/2020\/08\/logo-sdr.png\",\"contentUrl\":\"https:\/\/zt88dgbrixj.preview.infomaniak.website\/wp-content\/uploads\/2020\/08\/logo-sdr.png\",\"width\":404,\"height\":286,\"caption\":\"SDR Tourisme Souss Massa\"},\"image\":{\"@id\":\"https:\/\/explore-agadirsoussmassa.com\/fr\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/Explore-Souss-Massa-111659480353930\",\"https:\/\/www.instagram.com\/exploresoussmassamorocco\/\",\"https:\/\/www.youtube.com\/channel\/UCpSGZAsRRpG40CeT3UcIcOA\/videos\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/explore-agadirsoussmassa.com\/fr\/#\/schema\/person\/c019e4bcfef76d1c57d426107449d03e\",\"name\":\"soussmassa\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/explore-agadirsoussmassa.com\/fr\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/71a3f2c422286f264199c19844c327bfdf2a272a6aab356511f8970061b8dc04?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/71a3f2c422286f264199c19844c327bfdf2a272a6aab356511f8970061b8dc04?s=96&d=mm&r=g\",\"caption\":\"soussmassa\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Vall\u00e9e des C\u00e9drats - Randonn\u00e9e - Explore Agadir Souss Massa","description":"La Vall\u00e9e des C\u00e9drats - Magnifique randonn\u00e9e depuis Taroudant dans un canyon de 3 kms o\u00f9 les c\u00e9drats, sorte de gros citrons, apparaissent petit \u00e0 petit.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/explore-agadirsoussmassa.com\/fr\/vallee-des-cedrats-randonnee\/","og_locale":"fr_FR","og_type":"article","og_title":"Vall\u00e9e des C\u00e9drats - Randonn\u00e9e - Explore Agadir Souss Massa","og_description":"La Vall\u00e9e des C\u00e9drats - Magnifique randonn\u00e9e depuis Taroudant dans un canyon de 3 kms o\u00f9 les c\u00e9drats, sorte de gros citrons, apparaissent petit \u00e0 petit.","og_url":"https:\/\/explore-agadirsoussmassa.com\/fr\/vallee-des-cedrats-randonnee\/","og_site_name":"Explore Agadir Souss Massa","article_publisher":"https:\/\/www.facebook.com\/Explore-Souss-Massa-111659480353930","article_published_time":"2020-07-26T18:20:29+00:00","article_modified_time":"2021-02-22T20:56:49+00:00","og_image":[{"width":1903,"height":600,"url":"https:\/\/explore-agadirsoussmassa.com\/wp-content\/uploads\/2020\/02\/cedrats-2-large-1.jpg","type":"image\/jpeg"}],"author":"soussmassa","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"soussmassa"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/explore-agadirsoussmassa.com\/fr\/vallee-des-cedrats-randonnee\/#article","isPartOf":{"@id":"https:\/\/explore-agadirsoussmassa.com\/fr\/vallee-des-cedrats-randonnee\/"},"author":{"name":"soussmassa","@id":"https:\/\/explore-agadirsoussmassa.com\/fr\/#\/schema\/person\/c019e4bcfef76d1c57d426107449d03e"},"headline":"Vall\u00e9e des C\u00e9drats &#8211; Randonn\u00e9e","datePublished":"2020-07-26T18:20:29+00:00","dateModified":"2021-02-22T20:56:49+00:00","mainEntityOfPage":{"@id":"https:\/\/explore-agadirsoussmassa.com\/fr\/vallee-des-cedrats-randonnee\/"},"wordCount":8,"publisher":{"@id":"https:\/\/explore-agadirsoussmassa.com\/fr\/#organization"},"image":{"@id":"https:\/\/explore-agadirsoussmassa.com\/fr\/vallee-des-cedrats-randonnee\/#primaryimage"},"thumbnailUrl":"https:\/\/explore-agadirsoussmassa.com\/wp-content\/uploads\/2020\/02\/cedrats-2-large-1.jpg","articleSection":["Anti Atlas","Montagnes"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/explore-agadirsoussmassa.com\/fr\/vallee-des-cedrats-randonnee\/","url":"https:\/\/explore-agadirsoussmassa.com\/fr\/vallee-des-cedrats-randonnee\/","name":"Vall\u00e9e des C\u00e9drats - Randonn\u00e9e - Explore Agadir Souss Massa","isPartOf":{"@id":"https:\/\/explore-agadirsoussmassa.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/explore-agadirsoussmassa.com\/fr\/vallee-des-cedrats-randonnee\/#primaryimage"},"image":{"@id":"https:\/\/explore-agadirsoussmassa.com\/fr\/vallee-des-cedrats-randonnee\/#primaryimage"},"thumbnailUrl":"https:\/\/explore-agadirsoussmassa.com\/wp-content\/uploads\/2020\/02\/cedrats-2-large-1.jpg","datePublished":"2020-07-26T18:20:29+00:00","dateModified":"2021-02-22T20:56:49+00:00","description":"La Vall\u00e9e des C\u00e9drats - Magnifique randonn\u00e9e depuis Taroudant dans un canyon de 3 kms o\u00f9 les c\u00e9drats, sorte de gros citrons, apparaissent petit \u00e0 petit.","breadcrumb":{"@id":"https:\/\/explore-agadirsoussmassa.com\/fr\/vallee-des-cedrats-randonnee\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/explore-agadirsoussmassa.com\/fr\/vallee-des-cedrats-randonnee\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/explore-agadirsoussmassa.com\/fr\/vallee-des-cedrats-randonnee\/#primaryimage","url":"https:\/\/explore-agadirsoussmassa.com\/wp-content\/uploads\/2020\/02\/cedrats-2-large-1.jpg","contentUrl":"https:\/\/explore-agadirsoussmassa.com\/wp-content\/uploads\/2020\/02\/cedrats-2-large-1.jpg","width":1903,"height":600},{"@type":"BreadcrumbList","@id":"https:\/\/explore-agadirsoussmassa.com\/fr\/vallee-des-cedrats-randonnee\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/explore-agadirsoussmassa.com\/fr\/"},{"@type":"ListItem","position":2,"name":"Vall\u00e9e des C\u00e9drats &#8211; Randonn\u00e9e"}]},{"@type":"WebSite","@id":"https:\/\/explore-agadirsoussmassa.com\/fr\/#website","url":"https:\/\/explore-agadirsoussmassa.com\/fr\/","name":"Explore Agadir Souss Massa","description":"R\u00e9gion Souss Massa","publisher":{"@id":"https:\/\/explore-agadirsoussmassa.com\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/explore-agadirsoussmassa.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/explore-agadirsoussmassa.com\/fr\/#organization","name":"SDR Tourisme Souss Massa","url":"https:\/\/explore-agadirsoussmassa.com\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/explore-agadirsoussmassa.com\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/zt88dgbrixj.preview.infomaniak.website\/wp-content\/uploads\/2020\/08\/logo-sdr.png","contentUrl":"https:\/\/zt88dgbrixj.preview.infomaniak.website\/wp-content\/uploads\/2020\/08\/logo-sdr.png","width":404,"height":286,"caption":"SDR Tourisme Souss Massa"},"image":{"@id":"https:\/\/explore-agadirsoussmassa.com\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Explore-Souss-Massa-111659480353930","https:\/\/www.instagram.com\/exploresoussmassamorocco\/","https:\/\/www.youtube.com\/channel\/UCpSGZAsRRpG40CeT3UcIcOA\/videos"]},{"@type":"Person","@id":"https:\/\/explore-agadirsoussmassa.com\/fr\/#\/schema\/person\/c019e4bcfef76d1c57d426107449d03e","name":"soussmassa","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/explore-agadirsoussmassa.com\/fr\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/71a3f2c422286f264199c19844c327bfdf2a272a6aab356511f8970061b8dc04?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/71a3f2c422286f264199c19844c327bfdf2a272a6aab356511f8970061b8dc04?s=96&d=mm&r=g","caption":"soussmassa"}}]}},"_links":{"self":[{"href":"https:\/\/explore-agadirsoussmassa.com\/fr\/wp-json\/wp\/v2\/posts\/33847","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/explore-agadirsoussmassa.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/explore-agadirsoussmassa.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/explore-agadirsoussmassa.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/explore-agadirsoussmassa.com\/fr\/wp-json\/wp\/v2\/comments?post=33847"}],"version-history":[{"count":1,"href":"https:\/\/explore-agadirsoussmassa.com\/fr\/wp-json\/wp\/v2\/posts\/33847\/revisions"}],"predecessor-version":[{"id":33848,"href":"https:\/\/explore-agadirsoussmassa.com\/fr\/wp-json\/wp\/v2\/posts\/33847\/revisions\/33848"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/explore-agadirsoussmassa.com\/fr\/wp-json\/wp\/v2\/media\/6239"}],"wp:attachment":[{"href":"https:\/\/explore-agadirsoussmassa.com\/fr\/wp-json\/wp\/v2\/media?parent=33847"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/explore-agadirsoussmassa.com\/fr\/wp-json\/wp\/v2\/categories?post=33847"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/explore-agadirsoussmassa.com\/fr\/wp-json\/wp\/v2\/tags?post=33847"},{"taxonomy":"powerkit_post_featured","embeddable":true,"href":"https:\/\/explore-agadirsoussmassa.com\/fr\/wp-json\/wp\/v2\/powerkit_post_featured?post=33847"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}